{"id":1104,"date":"2016-01-16T00:48:58","date_gmt":"2016-01-15T23:48:58","guid":{"rendered":"http:\/\/aktuell.dpg.hamburg\/?p=1104"},"modified":"2019-02-22T12:34:11","modified_gmt":"2019-02-22T11:34:11","slug":"klausurtagung-16-17-januar-2016","status":"publish","type":"post","link":"https:\/\/dpg.hamburg\/da\/Beitr\u00e4ge\/dpg-hamburg\/klausurtagung-16-17-januar-2016\/","title":{"rendered":"Klausurtagung 16.-17. Januar 2016"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"bigPictureImg alignleft\" src=\"http:\/\/www.akademie-am-see.net\/gfx\/fotos-akademie-am-see-koppelsberg-2774.jpg\" alt=\"Eingangsbereich akademie am see. Koppelsberg, Pl\u00f6n, Foto: Georg B\u00fchler\" width=\"360\" height=\"240\" \/>Der Vorstand unserer Gesellschaft organisiert vom 16.-17. Januar 2016 eine Klausurtagung, w\u00e4hrend der wir \u00fcber die Aktivit\u00e4ten des Jahres 2016 beraten und einen Jahresplan 2016 erstellen werden. Falls Sie Anregungen, Ideen, Vorschl\u00e4ge haben, teilen Sie uns diese bitte telefonisch (<strong>Viola Krizak 040 830 12 21<\/strong>, <strong>Aleksandra Jeszke-Zillmer 59 49 07<\/strong>) oder per E-Mail (<span style=\"text-decoration: underline; color: #0000ff;\"><strong><a style=\"color: #0000ff; text-decoration: underline;\" href=\"mailto:Info@dpg-hamburg.de\">Info@dpg-hamburg.de<\/a><\/strong><\/span>) mit.<\/p>\n<p>Die Klausurtagung findet in der <span style=\"color: #0000ff;\"><strong>\u201e<a style=\"color: #0000ff;\" href=\"http:\/\/www.akademie-am-see.net\" target=\"_blank\" rel=\"noopener\">Akademie am See<\/a>\u201c<\/strong><\/span> , Kloppenberg 7 in Pl\u00f6n statt. Mitglieder sind herzlich zur Teilnahme eingeladen. Falls Sie Interesse haben, teilen Sie dies uns bitte bis zum 30. November 2015 telefonisch oder per E-Mail mit, damit wir ggf. Zimmer f\u00fcr Sie reservieren lassen k\u00f6nnen. Tagesg\u00e4ste sind ebenfalls willkommen. Der Eigenbeitrag f\u00fcr eine \u00dcbernachtung mit Vollverpflegung wird ca. 50 Euro betragen.<\/p>\n<p>Foto von der Webseite<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der Vorstand unserer Gesellschaft organisiert vom 16.-17. Januar 2016 eine Klausurtagung, w\u00e4hrend der wir \u00fcber die Aktivit\u00e4ten des Jahres 2016 beraten und einen Jahresplan 2016 erstellen werden. Falls Sie Anregungen, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15,347],"tags":[121],"class_list":["post-1104","post","type-post","status-publish","format-standard","category-dpg-hamburg","category-klausurtagung","tag-klausurtagung","czr-hentry"],"_links":{"self":[{"href":"https:\/\/dpg.hamburg\/da\/wp-json\/wp\/v2\/posts\/1104","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dpg.hamburg\/da\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dpg.hamburg\/da\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dpg.hamburg\/da\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dpg.hamburg\/da\/wp-json\/wp\/v2\/comments?post=1104"}],"version-history":[{"count":0,"href":"https:\/\/dpg.hamburg\/da\/wp-json\/wp\/v2\/posts\/1104\/revisions"}],"wp:attachment":[{"href":"https:\/\/dpg.hamburg\/da\/wp-json\/wp\/v2\/media?parent=1104"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dpg.hamburg\/da\/wp-json\/wp\/v2\/categories?post=1104"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dpg.hamburg\/da\/wp-json\/wp\/v2\/tags?post=1104"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}