{"id":4233,"date":"2021-02-08T20:16:17","date_gmt":"2021-02-08T19:16:17","guid":{"rendered":"https:\/\/dpg.hamburg\/?p=4233"},"modified":"2021-03-02T18:03:13","modified_gmt":"2021-03-02T17:03:13","slug":"diskussionsveranstaltung-online-unter-dem-titel-wir-sagen-nein-am-24-februar-um-1900","status":"publish","type":"post","link":"https:\/\/dpg.hamburg\/da\/Beitr\u00e4ge\/fremdveranstaltung\/diskussionsveranstaltung-online-unter-dem-titel-wir-sagen-nein-am-24-februar-um-1900\/","title":{"rendered":"Diskussionsveranstaltung (ONLINE) unter dem Titel \u201eWir sagen nein\u201c am 24. Februar um 19:00"},"content":{"rendered":"<p class=\"xmsonormal\"><span style=\"font-size: 11.0pt; font-family: 'Calibri','sans-serif';\">Liebe Mitglieder, Freundinnen und Freunde der DPG Brandenburg,<\/span><\/p>\n<p class=\"xmsonormal\"><span style=\"font-size: 11.0pt; font-family: 'Calibri','sans-serif';\">\u00a0<\/span><\/p>\n<p class=\"xmsonormal\"><span style=\"font-size: 11.0pt; font-family: 'Calibri','sans-serif';\">wir laden Sie herzlich zu einer Diskussionsveranstaltung (online) unter dem Titel \u201eWir sagen nein\u201c am 24. Februar um 19:00 ein. Maciej Biskup, Pater am Dominikanerkloster in L\u00f3d\u017a und Publizist, wird zu dem offenen Brief von rund 150 polnischen katholischen Geistlichen als Reaktion auf das Urteil des Verfassungsgerichtes zum Schwangerschaftsabbruch sprechen (mehr Informationen unten). <\/span><\/p>\n<p class=\"xmsonormal\"><span style=\"font-size: 11.0pt; font-family: 'Calibri','sans-serif';\">\u00a0<\/span><\/p>\n<p class=\"xmsonormal\"><span style=\"font-size: 11.0pt; font-family: 'Calibri','sans-serif';\">Die Veranstaltung wird ins Polnische bzw. Deutsche gedolmetscht. <\/span><\/p>\n<p class=\"xmsonormal\"><span style=\"font-size: 11.0pt; font-family: 'Calibri','sans-serif';\">\u00a0<\/span><\/p>\n<p class=\"xmsonormal\"><span style=\"font-size: 11.0pt; font-family: 'Calibri','sans-serif';\">Bitte melden Sie sich bis zum 22. Februar f\u00fcr die Online Veranstaltung an. Die Zugangsdaten erhalten Sie nach der Anmeldung: <a href=\"mailto:martin.kujawa@dpg-brandenburg.de\">martin.kujawa@dpg-brandenburg.de<\/a> <\/span><!--more--><\/p>\n<p class=\"xmsonormal\"><span style=\"font-size: 11.0pt; font-family: 'Calibri','sans-serif';\">Wir freuen uns auf Ihre Teilnahme! <\/span><\/p>\n<p class=\"xmsonormal\"><span style=\"font-size: 11.0pt; font-family: 'Calibri','sans-serif';\">\u00a0<\/span><\/p>\n<p class=\"xmsonormal\"><span style=\"font-size: 11.0pt; font-family: 'Calibri','sans-serif';\">Mit freundlichen Gr\u00fc\u00dfen <\/span><\/p>\n<p class=\"xmsonormal\"><span style=\"font-size: 11.0pt; font-family: 'Calibri','sans-serif';\">\u00a0<\/span><\/p>\n<p class=\"xmsonormal\"><span style=\"font-size: 11.0pt; font-family: 'Calibri','sans-serif';\">Im Namen des Vorstands <\/span><\/p>\n<p class=\"xmsonormal\"><span style=\"font-size: 11.0pt; font-family: 'Calibri','sans-serif';\">\u00a0<\/span><\/p>\n<p class=\"xmsonormal\"><span style=\"font-size: 11.0pt; font-family: 'Calibri','sans-serif';\">Martin Kujawa <\/span><\/p>\n<p class=\"xmsonormal\"><span style=\"font-size: 11.0pt; font-family: 'Calibri','sans-serif';\">\u00a0<\/span><\/p>\n<p class=\"xmsonormal\"><span style=\"font-size: 11.0pt; font-family: 'Calibri','sans-serif';\">Am 22. Oktober 2020 verk\u00fcndete die Vorsitzende des Verfassungsgerichts, einen Spruch der obersten Gerichtskammer, nachdem das Abtreibungsrecht, das in den 1990er Jahren zwischen Regierungslager und Kirchenkreisen als Kompromiss ausgehandelt worden war, gegen die Verfassung versto\u00dfe und damit rechtsunwirksam sei. In dieser Woche trat das entsprechende neue Gesetzt hierzu in Kraft. Damit werden Abtreibungen in Polen \u2013 auch bei Missbildungen oder unheilbarer Krankheit des F\u00f6tus \u2013 fast vollst\u00e4ndig verboten. Sowohl die Verk\u00fcndung Verfassungsgerichtes wie auch das Inkrafttreten des Gesetzes trieb viele Menschen in- und au\u00dferhalb Polens auf die Stra\u00dfe. In weiten Teilen der Bev\u00f6lkerung wurden und werden die Proteste zum Anlass genommen, f\u00fcr die Unabh\u00e4ngigkeit der Gerichte und Rechtsstaatlichkeit und gegen den Einfluss der katholischen Kirche auf Staat und Gesellschaft zu protestieren. <\/span><\/p>\n<p class=\"xmsonormal\"><span style=\"font-size: 11.0pt; font-family: 'Calibri','sans-serif';\">\u00a0<\/span><\/p>\n<p class=\"xmsonormal\"><span style=\"font-size: 11.0pt; font-family: 'Calibri','sans-serif';\">Die Reaktionen der Katholischen Kirche in Polen fielen unterschiedlich aus. W\u00e4hrend die einen das Urteil begr\u00fc\u00dften und als Sieg der Kirche feierten, sehen andere die Gefahr einer weiteren gesellschaftlichen Spaltung, ja sogar einer Niederlage der Kirche in dem Urteilsspruch. Rund 150 katholische Geistliche und Ordensschwestern unterzeichneten einen offenen Brief, in dem sie sich unter anderem entschieden gegen die Instrumentalisierung von Religion f\u00fcr politische Zwecke, die Ungleichbehandlung von M\u00e4nnern und Frauen sowie Diskriminierung und Fremdenfeindlichkeit wenden. <\/span><\/p>\n<p class=\"xmsonormal\"><span style=\"font-size: 11.0pt; font-family: 'Calibri','sans-serif';\">\u00a0<\/span><\/p>\n<p class=\"xmsonormal\"><span style=\"font-size: 11.0pt; font-family: 'Calibri','sans-serif';\">Dominikanerpater Maciej Biskup, der bereits vor einigen Jahren eine Debatte zum Thema \u201eVerh\u00e4ltnis von Kirche und Staat\u201c er\u00f6ffnet hat, geh\u00f6rt zu den Unterzeichnern des Briefes. In seinem Artikel \u201eTraum von der Macht\u201c spricht er sich gegen zu viel N\u00e4he zur Politik aus: \u201eDie Kirche ist ver\u00e4ngstigt. Unsere Hoffnung sollten wir auf den Glauben setzen und nicht auf Rechte und Gesetze oder ein B\u00fcndnis von Thron und Altar.\u201c <\/span><\/p>\n<p class=\"xmsonormal\"><span style=\"font-size: 11.0pt; font-family: 'Calibri','sans-serif';\">\u00a0<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Liebe Mitglieder, Freundinnen und Freunde der DPG Brandenburg, \u00a0 wir laden Sie herzlich zu einer Diskussionsveranstaltung (online) unter dem Titel \u201eWir sagen nein\u201c am 24. Februar um 19:00 ein. Maciej [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[159,142,103,439],"tags":[],"class_list":["post-4233","post","type-post","status-publish","format-standard","category-dpg-brandenburg","category-fremdbeitrag","category-fremdveranstaltung","category-onlineveranstaltung","czr-hentry"],"_links":{"self":[{"href":"https:\/\/dpg.hamburg\/da\/wp-json\/wp\/v2\/posts\/4233","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dpg.hamburg\/da\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dpg.hamburg\/da\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dpg.hamburg\/da\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dpg.hamburg\/da\/wp-json\/wp\/v2\/comments?post=4233"}],"version-history":[{"count":0,"href":"https:\/\/dpg.hamburg\/da\/wp-json\/wp\/v2\/posts\/4233\/revisions"}],"wp:attachment":[{"href":"https:\/\/dpg.hamburg\/da\/wp-json\/wp\/v2\/media?parent=4233"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dpg.hamburg\/da\/wp-json\/wp\/v2\/categories?post=4233"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dpg.hamburg\/da\/wp-json\/wp\/v2\/tags?post=4233"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}