{"id":1135,"date":"2015-10-31T19:36:13","date_gmt":"2015-10-31T17:36:13","guid":{"rendered":"http:\/\/aktuell.dpg.hamburg\/?p=1135"},"modified":"2015-10-31T19:36:52","modified_gmt":"2015-10-31T17:36:52","slug":"star-friends-25-jahre-jazzbaltica-donnerstag-19-november-2015-20-00-uhrtheodor-schaefer-berufsbildungswerk-husum","status":"publish","type":"post","link":"https:\/\/dpg.hamburg\/en\/Beitr\u00e4ge\/fremdveranstaltung\/star-friends-25-jahre-jazzbaltica-donnerstag-19-november-2015-20-00-uhrtheodor-schaefer-berufsbildungswerk-husum\/","title":{"rendered":"\u201estar &#038; friends\u201c: 25 Jahre JazzBaltica, Donnerstag, 19. November 2015, 20.00 Uhr|Theodor-Sch\u00e4fer-Berufsbildungswerk Husum"},"content":{"rendered":"<p>Sehr geehrte Damen und Herren,<\/p>\n<p>ich m\u00f6chte Ihnen das <strong>Konzert <em>\u201estar &amp; friends\u201c: 25 Jahre JazzBaltica <\/em>am 19.11.2015 in Elmshorn<\/strong> empfehlen. Es warten uns unvergessliche k\u00fcnstlerische Erlebnisse mit international anerkannten Jazz-Starmusikern: <strong>Vladyslav Sendecki und Adam Ba\u0142dych. <\/strong>Details finden Sie unten und im Anhang.<\/p>\n<p><strong>\u201estar &amp; friends\u201c: 25 Jahre JazzBaltica<\/strong><strong>, <\/strong><strong>Donnerstag, 19. November 2015, 20.00 Uhr<\/strong><\/p>\n<p><strong>star Tankstellen pr\u00e4sentieren Starmusiker Vladyslav Sendecki, Adam Ba\u0142dych und das \u201eEuropean Blue Note Quartet\u201c <\/strong><\/p>\n<p>Elmshorn, 28. Oktober 2015<strong> \u2013 Anl\u00e4sslich des 25-j\u00e4hrigen Jubil\u00e4ums des Jazz-Festivals JazzBaltica sponsern die star Tankstellen als Partner neben dem allj\u00e4hrlichen Sommer-Event auch ein Sonderkonzert unter dem Motto star &amp; friends. Bei dem JazzBaltica Special in Husum erwartet Kulturliebhaber ein erstklassiges Line-up mit K\u00fcnstlern des European Blue Note Quartet und dem Special Guest und Jazzgeigenwunder Adam Ba\u0142dych. <\/strong><\/p>\n<p>Nach den vielgelobten Veranstaltungen in den letzten Jahren initiieren JazzBaltica-Mitbegr\u00fcnder Christian St\u00f6hrmann und die Tankstellenmarke star nun ein besonderes kulturelles Highlight: Am 19. November findet um 20 Uhr das JazzBaltica Special star &amp; friends statt. \u201eWir freuen uns sehr, JazzBaltica mittlerweile zum vierten Mal unterst\u00fctzen zu k\u00f6nnen. Es ist uns ein gro\u00dfes Anliegen, uns langfristig f\u00fcr hervorragende musikalische Leistungen und insbesondere f\u00fcr internationale K\u00fcnstler sowie unser Heimatbundesland Schleswig-Holstein zu engagieren\u201c, erkl\u00e4rt Wieslaw Milkiewicz, Gesch\u00e4ftsf\u00fchrer und Pressesprecher der star Tankstellen. Das Unternehmen ist f\u00fcr sein starkes kulturelles Engagement bekannt, was Vladyslav Sendecki zu sch\u00e4tzen wei\u00df: \u201eGerade wenn der Staat die Unterst\u00fctzung f\u00fcr kulturelle Events zur\u00fcckschraubt, ist das Engagement von Firmen sehr wichtig. Die star Tankstellen tun dies mit der richtigen \u00dcberzeugung, n\u00e4mlich um die Kultur zu bewahren und lebendig zu halten.\u201c<\/p>\n<p>Jazzfreunde k\u00f6nnen sich bei star &amp; friends von hervorragenden Musikern begeistern lassen: Starpianist Vladyslav Sendecki, Saxophonist Andrzej Olejniczak, Bassist Michal Baranski und Schlagzeuger Mark Mondesir bilden das European Blue Note Quartet, das sich durch die gelungene Mischung zwischen lyrischen und romantischen Kl\u00e4ngen bis zu rockigen Ausdrucksformen auszeichnet. Als Special Guest erwartet die G\u00e4ste eine der bekanntesten Gr\u00f6\u00dfen der internationalen Jazzszene \u2013 der polnische Geiger und ECHO-Preistr\u00e4ger Adam Ba\u0142dych wurde von der FAZ als der \u201egr\u00f6\u00dfte lebende Geigentechniker des Jazz\u201c betitelt.<\/p>\n<p><strong>Veranstaltungsinfos<\/strong> <strong>JazzBaltica Special star &amp; friends:<\/strong><\/p>\n<p><strong>Donnerstag, 19. November 2015, 20.00 Uhr<br \/>\nTheodor-Sch\u00e4fer-Berufsbildungswerk Husum<br \/>\nVladyslav Sendecki mit dem &#8220;European Blue Note Quartet&#8221;<br \/>\nSpecial Guest:\u00a0 Adam Baldych, ECHO-Preistr\u00e4ger 2013<br \/>\nKarten: Vorverkauf 18\u20ac (ab dem 01.10.2015 im Husumer TSBW und in der Husumer Fielmann Filiale), Abendkasse 20\u20ac<\/strong><\/p>\n<p><strong>star \u2013 eine starke Marke der ORLEN Deutschland GmbH<\/strong><\/p>\n<p>star ist die Tankstellen-Marke der ORLEN Deutschland GmbH, die seit dem Jahr 2003 in der Nordh\u00e4lfte Deutschlands mehr als 550 Tankstellen betreibt. Das Unternehmen mit Sitz in Elmshorn bei Hamburg geh\u00f6rt zum polnischen Mineral\u00f6l- und Petrochemiekonzern PKN ORLEN SA, der mit einem Jahresumsatz von 26 Milliarden Euro in 2014 das gr\u00f6\u00dfte osteurop\u00e4ische Unternehmen ist und zu den gr\u00f6\u00dften mitteleurop\u00e4ischen Konzernen geh\u00f6rt.<\/p>\n<p>PKN ORLEN SA ist in Warschau und London b\u00f6rsennotiert und auf dem Tankstellenmarkt in Ost- und Zentraleuropa mit insgesamt 2.700 Tankstellen in Polen, Tschechien, Deutschland und Litauen vertreten. In den letzten Jahren wurden gro\u00dfe Investitionen in Litauen und Tschechien get\u00e4tigt, um dem Ziel \u2013 das f\u00fchrende Mineral\u00f6lunternehmen in Zentraleuropa zu werden \u2013 einen weiteren Schritt n\u00e4her zu kommen.<\/p>\n<p><strong>Kontakt:<\/strong><\/p>\n<p>ORLEN Deutschland GmbH<\/p>\n<p>Wieslaw Milkiewicz \/ Gesch\u00e4ftsf\u00fchrer und Pressesprecher<\/p>\n<p>Telefon: 04121 \/ 4750 \u2013 1609, <a href=\"mailto:wieslaw.milkiewicz@orlen-deutschland.de\">wieslaw.milkiewicz@orlen-deutschland.de<\/a><\/p>\n<p>Andreas Khan \/ Leiter Marketing &amp; PR<\/p>\n<p>Telefon: 04121 \/ 4750 \u2013 1618, <a href=\"mailto:andreas.khan@orlen-deutschland.de\">andreas.khan@orlen-deutschland.de<\/a><\/p>\n<p>Marek Sorgowicki<\/p>\n<p>Wicekonsul\/Vizekonsul<\/p>\n<p>Samodzielne Stanowisko ds. Dyplomacji Publicznej i Kulturalnej<\/p>\n<p>Kultur und \u00d6ffentlichkeitsarbeit<\/p>\n<p><strong>Konsulat Generalny Rzeczypospolitej Polskiej w Hamburgu<\/strong><\/p>\n<p><strong>Generalkonsulat der Republik Polen in Hamburg<\/strong><\/p>\n<p>Gr\u00fcndgensstr. 20, 22309 Hamburg<\/p>\n<p>Tel.:\u00a0 +49 40 611 87 133, Fax: +49 40 632 50 30<br \/>\n<a href=\"http:\/\/www.hamburg.msz.gov.pl\/\">www.hamburg.msz.gov.pl<\/a><\/p>\n<p><strong>\u00a0 <\/strong><\/p>\n<p><em>Niniejsza wiadomo\u015b\u0107 (wraz z za\u0142\u0105cznikami) jest w\u0142asno\u015bci\u0105 Ministerstwa Spraw Zagranicznych i mo\u017ce zawiera\u0107 informacje s\u0142u\u017cbowe prawnie chronione. Je\u015bli nie s\u0105 Pa\u0144stwo w\u0142a\u015bciwym adresatem lub otrzymali Pa\u0144stwo t\u0119 wiadomo\u015b\u0107 na skutek pomy\u0142ki, prosimy o tym fakcie niezw\u0142ocznie poinformowa\u0107 nadawc\u0119 i usun\u0105\u0107 otrzyman\u0105 wiadomo\u015b\u0107. Ka\u017cde nieautoryzowane kopiowanie, ujawnianie lub rozpowszechnianie za\u0142\u0105czonej informacji jest zabronione.<\/em><\/p>\n<p><em>This message (including attachments) is the property of the Ministry of Foreign Affairs and may contain important and\/or privileged information. If you are not the intended recipient or have received this message by mistake, please notify the sender immediately and delete this message. Any unauthorized copying, disclosure or distribution of the material in this message is prohibited. <\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sehr geehrte Damen und Herren, ich m\u00f6chte Ihnen das Konzert \u201estar &amp; friends\u201c: 25 Jahre JazzBaltica am 19.11.2015 in Elmshorn empfehlen. Es warten uns unvergessliche k\u00fcnstlerische Erlebnisse mit international anerkannten [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[142,103],"tags":[],"class_list":["post-1135","post","type-post","status-publish","format-standard","category-fremdbeitrag","category-fremdveranstaltung","czr-hentry"],"_links":{"self":[{"href":"https:\/\/dpg.hamburg\/en\/wp-json\/wp\/v2\/posts\/1135","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dpg.hamburg\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dpg.hamburg\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dpg.hamburg\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dpg.hamburg\/en\/wp-json\/wp\/v2\/comments?post=1135"}],"version-history":[{"count":0,"href":"https:\/\/dpg.hamburg\/en\/wp-json\/wp\/v2\/posts\/1135\/revisions"}],"wp:attachment":[{"href":"https:\/\/dpg.hamburg\/en\/wp-json\/wp\/v2\/media?parent=1135"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dpg.hamburg\/en\/wp-json\/wp\/v2\/categories?post=1135"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dpg.hamburg\/en\/wp-json\/wp\/v2\/tags?post=1135"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}