{"id":2232,"date":"2017-04-07T10:40:11","date_gmt":"2017-04-07T09:40:11","guid":{"rendered":"http:\/\/aktuell.dpg.hamburg\/?p=2232"},"modified":"2017-03-06T10:51:38","modified_gmt":"2017-03-06T09:51:38","slug":"ausstellung-wem-gehoert-polen-7-april-2017-18-00-uhr-bis-31-mai-2017-taeglich-von-10-00-bis-17-00-uhr-mahnmals-st-nikolai","status":"publish","type":"post","link":"https:\/\/dpg.hamburg\/en\/Beitr\u00e4ge\/dpg-hamburg\/ausstellung-wem-gehoert-polen-7-april-2017-18-00-uhr-bis-31-mai-2017-taeglich-von-10-00-bis-17-00-uhr-mahnmals-st-nikolai\/","title":{"rendered":"Ausstellung \u201eWem geh\u00f6rt Polen?\u201c 7. April 2017, 18.00 Uhr bis 31. Mai 2017 t\u00e4glich von 10.00 bis 17.00 Uhr &#8211; Mahnmals St. Nikolai"},"content":{"rendered":"<p><strong>WEM GEH\u00d6RT POLEN?<\/strong><\/p>\n<p>Am Freitag, <strong>7. April 2017, 18.00 Uhr<\/strong> laden wir Sie zur Ausstellungser\u00f6ffnung \u201eWem geh\u00f6rt Polen?\u201c Propagandapostkarten aus dem Ersten Weltkrieg ein.<\/p>\n<p>Einleitungsvortrag von <strong>Prof. Dr. Wlodzimierz Borodziej<\/strong>, (Warschau\/Jena) zum Thema \u201eDer Gro\u00dfe Krieg als vergessener Erinnerungsort. Polen 1914-1921\u201c sowie Gru\u00dfworte von Prof. Boguslaw Dybas (Wien) und Prof. Dr. Rudolf Jaworski (Konstanz).<\/p>\n<p>Lange Zeit bestimmte der Stellungskrieg an der Westfront den historischen R\u00fcckblick auf den Ersten Weltkrieg, das dramatische Kriegsgeschehen im Osten Europas erfuhr dagegen erst in j\u00fcngerer Zeit gr\u00f6\u00dfere Aufmerksamkeit. Eine herausragende Rolle spielte dabei einer der Hauptkriegsschaupl\u00e4tze: das seit dem Ende des 18. Jahrhunderts zwischen Deutschland, Russland und \u00d6sterreich-Ungarn geteilte Polen. Alle Konfliktparteien betrieben dabei eine energische Bildpropaganda, was einen regelrechten \u201eKrieg der Bilder\u201c entfachte. Das beliebte und vielfach genutzte Massenkommunikationsmittel Postkarte spielte dabei eine kaum zu \u00fcbersch\u00e4tzende Rolle. Anhand von 60 Propagandapostkarten aus Deutschland, \u00d6sterreich-Ungarn, Russland, Polen und Frankreich zeigt die Ausstellung die Situation und Stimmung der Polen in dieser schicksalhaften Zeit auf und veranschaulicht ihre komplizierte Stellung in der internationalen Politik. Die Ausstellung will m\u00f6glichst viele und verschiedenartige Aspekte der \u201epolnischen Frage\u201c im Ersten Weltkrieg aufzeigen.<\/p>\n<p>Eine Ausstellung des Wissenschaftlichen Zentrums der Polnischen Akademie der Wissenschaften in Wien, Konzept: Prof. Dr. Rudolf Jaworski.<\/p>\n<p>Kooperationspartner sind das Mahnmal St. Nikolai die Landeszentrale f\u00fcr politische Bildung Hamburg und die Deutsch-Polnische Gesellschaft Hamburg.<\/p>\n<p>Die Ausstellung ist bis zum 31. Mai 2017 t\u00e4glich von 10.00 bis 17.00 Uhr im Gew\u00f6lbekeller des Mahnmals St. Nikolai zu besichtigen. Eintritt frei.<\/p>\n<p><strong>BELEITPROGRAMM:<\/strong><\/p>\n<p><strong>Am Samstag, 22.04., 18.00 bis 2.00 Uhr<\/strong> findet \u00a0im Rahmen der langen Nacht der Museen ein Begleitprogramm in Kooperation mit der Universit\u00e4t Hamburg , Bereich Public History und der Hauser Kommunikation, Berlin statt. Es werden mehrere F\u00fchrungen durch die Ausstellung \u201eWem geh\u00f6rt Polen\u201c (18.30, 19.15, 20.15, 21,15, 0.30 Uhr) und durch die Dauerausstellung \u201eGomorra 1943 (19.45, 20.45 Uhr) angeboten.<\/p>\n<p>Der History Salm\u00a0 \u201eNoch ist Polen nicht verloren\u201c findet vom 22.00-0.00Uhr statt.<\/p>\n<p>Kooperation mit der Landeszentrale f\u00fcr politische Bildung Hamburg und dem Bereich Public History der Universit\u00e4t Hamburg.<\/p>\n<p>Kulinarisches: Herzhafte Snacks und Getr\u00e4nke<\/p>\n<p>Weitere Termine zum Begleitprogramm erhalten Sie in den n\u00e4chsten Mitteilungen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>WEM GEH\u00d6RT POLEN? Am Freitag, 7. April 2017, 18.00 Uhr laden wir Sie zur Ausstellungser\u00f6ffnung \u201eWem geh\u00f6rt Polen?\u201c Propagandapostkarten aus dem Ersten Weltkrieg ein. Einleitungsvortrag von Prof. Dr. Wlodzimierz Borodziej, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15,156,206],"tags":[],"class_list":["post-2232","post","type-post","status-publish","format-standard","category-dpg-hamburg","category-landeszentrale-fuer-politische-bildung","category-mahnmals-st-nikolai","czr-hentry"],"_links":{"self":[{"href":"https:\/\/dpg.hamburg\/en\/wp-json\/wp\/v2\/posts\/2232","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dpg.hamburg\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dpg.hamburg\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dpg.hamburg\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dpg.hamburg\/en\/wp-json\/wp\/v2\/comments?post=2232"}],"version-history":[{"count":0,"href":"https:\/\/dpg.hamburg\/en\/wp-json\/wp\/v2\/posts\/2232\/revisions"}],"wp:attachment":[{"href":"https:\/\/dpg.hamburg\/en\/wp-json\/wp\/v2\/media?parent=2232"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dpg.hamburg\/en\/wp-json\/wp\/v2\/categories?post=2232"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dpg.hamburg\/en\/wp-json\/wp\/v2\/tags?post=2232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}