{"id":498,"date":"2015-02-10T14:23:32","date_gmt":"2015-02-10T12:23:32","guid":{"rendered":"http:\/\/aktuell.dpg.hamburg\/?p=498"},"modified":"2015-02-21T14:25:39","modified_gmt":"2015-02-21T12:25:39","slug":"besondere-auszeichnung","status":"publish","type":"post","link":"https:\/\/dpg.hamburg\/en\/Beitr\u00e4ge\/dpg-hamburg\/besondere-auszeichnung\/","title":{"rendered":"BESONDERE AUSZEICHNUNG"},"content":{"rendered":"<p><strong>BESONDERE AUSZEICHNUNG<\/strong><\/p>\n<p>Am 11. September 2014 hat Dr. Jerzy Marganski, Polens Botschafter in Deutschland, unserem langj\u00e4hrigen Mitglied <strong>Richard Pyritz<\/strong> das Offizierskreuz des polnischen Verdienstordens \u00fcberreicht, das ihm vom Pr\u00e4sidenten der Republik Polen in Anerkennung seiner herausragenden Verdienste um die deutsch-polnische Vers\u00f6hnung und die Wissensvermittlung \u00fcber das Konzentrationslager Ausschwitz- Birkenau verliehen wurde. Seit 1972 engagiert sich Richard Pyritz f\u00fcr eine gute Nachbarschaft mit Polen, ist Initiator zahlreicher Hilfsaktionen und Mitbegr\u00fcnder des Rotary Clubs Oswiecim. Er hat in den letzten f\u00fcnf Jahren viele Projekte zur F\u00f6rderung der Arbeit der Internationalen Jugendbegegungsst\u00e4tte Ausschwitz initiiert.<\/p>\n<p>Wir gratulieren ihm sehr herzlich!!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>BESONDERE AUSZEICHNUNG Am 11. September 2014 hat Dr. Jerzy Marganski, Polens Botschafter in Deutschland, unserem langj\u00e4hrigen Mitglied Richard Pyritz das Offizierskreuz des polnischen Verdienstordens \u00fcberreicht, das ihm vom Pr\u00e4sidenten der [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[49,15],"tags":[],"class_list":["post-498","post","type-post","status-publish","format-standard","category-auszeichnung","category-dpg-hamburg","czr-hentry"],"_links":{"self":[{"href":"https:\/\/dpg.hamburg\/en\/wp-json\/wp\/v2\/posts\/498","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dpg.hamburg\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dpg.hamburg\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dpg.hamburg\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dpg.hamburg\/en\/wp-json\/wp\/v2\/comments?post=498"}],"version-history":[{"count":0,"href":"https:\/\/dpg.hamburg\/en\/wp-json\/wp\/v2\/posts\/498\/revisions"}],"wp:attachment":[{"href":"https:\/\/dpg.hamburg\/en\/wp-json\/wp\/v2\/media?parent=498"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dpg.hamburg\/en\/wp-json\/wp\/v2\/categories?post=498"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dpg.hamburg\/en\/wp-json\/wp\/v2\/tags?post=498"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}