{"id":1109,"date":"2015-11-03T00:02:54","date_gmt":"2015-11-02T22:02:54","guid":{"rendered":"http:\/\/aktuell.dpg.hamburg\/?p=1109"},"modified":"2015-10-31T17:04:24","modified_gmt":"2015-10-31T15:04:24","slug":"polnisch-deutsche-versoehnung-1965dienstag-3-november2015","status":"publish","type":"post","link":"https:\/\/dpg.hamburg\/es\/Beitr\u00e4ge\/fremdveranstaltung\/polnisch-deutsche-versoehnung-1965dienstag-3-november2015\/","title":{"rendered":"POLNISCH-DEUTSCHE VERS\u00d6HNUNG 1965|Dienstag, 3. November2015"},"content":{"rendered":"<p><strong>POLNISCH-DEUTSCHE VERS\u00d6HNUNG 1965<\/strong><\/p>\n<p>Am <strong>Dienstag, 3. November um 18:00<\/strong> Uhr findet in der Katholischen Pfarrei St. Joseph &#8211; Altona<\/p>\n<p>Gro\u00dfe Freiheit 43 ein Deutsch-polnischer Vers\u00f6hnungsgottesdienst mit Bischof Jan Kopiec, Bistum Gliwice, Polen und Pfarrer Jacek Bystron, Polnische Kath. Mission in Hamburg, statt.<\/p>\n<p>Anschlie\u00dfend, um 19.30 findet im Mahnmal St. Nikolai Willy-Brandt-Stra\u00dfe 60 eine Diskussion zum Thema: \u201e50 Jahre gemeinsam auf dem Weg der Vers\u00f6hnung und der Zusammenarbeit\u201c statt.<\/p>\n<p>Am 18. November 1965, w\u00e4hrend des 2. Vatikanischen Konzils, schrieben die polnischen Bisch\u00f6fe in einem Brief an ihre deutschen Amtsbr\u00fcder:<\/p>\n<p><strong>\u201eWir strecken unsere H\u00e4nde zu Ihnen hin in den B\u00e4nken des zu Ende gehenden Konzils, gew\u00e4hren Vergebung und bitten um Vergebung.\u201c<\/strong><\/p>\n<p>Dies war der Beginn der Auss\u00f6hnung zwischen dem polnischen und dem deutschen Volk. Jahre der Verst\u00e4ndigung, der Unterst\u00fctzung des polnischen Volkes in seinem Freiheitskampf bis hin zur Wiedervereinigung Deutschlands folgten. Daran wird in der Diskussionsveranstaltung erinnert und auch der Frage nachgegangen, welchen Herausforderungen wir gemeinsam in der Zukunft gegen\u00fcberstehen. Es diskutieren: Bischof Prof. Dr. Jan Kopiec, Bistum Gliwice &#8211; Polen, Weihbischof Dr. Hans-Jochen Jaschke, Propst Dr. Johann Hinrich Claussen und Dr. J\u00f6rg L\u00fcer, Deutsche Kommission Justicia et Pax, Berlin; Moderation Dr. Sabine Bamberger-Stemmann, Leiterin der Landeszentrale f\u00fcr politische Bildung, Hamburg.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>POLNISCH-DEUTSCHE VERS\u00d6HNUNG 1965 Am Dienstag, 3. November um 18:00 Uhr findet in der Katholischen Pfarrei St. Joseph &#8211; Altona Gro\u00dfe Freiheit 43 ein Deutsch-polnischer Vers\u00f6hnungsgottesdienst mit Bischof Jan Kopiec, Bistum [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[142,103],"tags":[78,32,12,37],"class_list":["post-1109","post","type-post","status-publish","format-standard","category-fremdbeitrag","category-fremdveranstaltung","tag-fremdbeitrag","tag-fremdveranstaltung","tag-gedenken","tag-politische-verantwortung","czr-hentry"],"_links":{"self":[{"href":"https:\/\/dpg.hamburg\/es\/wp-json\/wp\/v2\/posts\/1109","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dpg.hamburg\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dpg.hamburg\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dpg.hamburg\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dpg.hamburg\/es\/wp-json\/wp\/v2\/comments?post=1109"}],"version-history":[{"count":0,"href":"https:\/\/dpg.hamburg\/es\/wp-json\/wp\/v2\/posts\/1109\/revisions"}],"wp:attachment":[{"href":"https:\/\/dpg.hamburg\/es\/wp-json\/wp\/v2\/media?parent=1109"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dpg.hamburg\/es\/wp-json\/wp\/v2\/categories?post=1109"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dpg.hamburg\/es\/wp-json\/wp\/v2\/tags?post=1109"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}