{"id":500,"date":"2015-02-21T14:31:30","date_gmt":"2015-02-21T12:31:30","guid":{"rendered":"http:\/\/aktuell.dpg.hamburg\/?p=500"},"modified":"2015-02-21T14:31:30","modified_gmt":"2015-02-21T12:31:30","slug":"adventsfeier-2014-2","status":"publish","type":"post","link":"https:\/\/dpg.hamburg\/es\/Beitr\u00e4ge\/dpg-hamburg\/adventsfeier-2014-2\/","title":{"rendered":"ADVENTSFEIER 2014"},"content":{"rendered":"<p><strong>ADVENTSFEIER<\/strong><\/p>\n<p>Wir haben zu unserer Adventsfeier 2014 das Ensemble Widymo aus der polnisch-ukrainischen Grenzstadt Sanok im San-Tal (S\u00fcd-Ost-Karpaten) eingeladen. Der Kontakt mit der Gruppe ist durch unsere DPG-Freunde in Kiel entstanden. Das Konzert fand in der Christ-K\u00f6nig-Kirche in Lokstedt statt. In der gut gef\u00fcllten Kirche haben die G\u00e4ste dem besonderen Klang der Gruppe gelauscht. Es ist selten, dass man bei sieben S\u00e4ngerinnen einen polyphonen Gesang mit sieben Stimmen h\u00f6ren kann. Entsprechend war die Begeisterung gro\u00df und der Applaus wollte nicht enden.<\/p>\n<p><a href=\"https:\/\/dpg.hamburg\/wp-content\/uploads\/2015\/02\/musikgruppe.png\"><img loading=\"lazy\" decoding=\"async\" class=\" size-medium wp-image-501 aligncenter\" src=\"https:\/\/dpg.hamburg\/wp-content\/uploads\/2015\/02\/musikgruppe-300x226.png\" alt=\"musikgruppe\" width=\"300\" height=\"226\" srcset=\"https:\/\/dpg.hamburg\/wp-content\/uploads\/2015\/02\/musikgruppe-300x226.png 300w, https:\/\/dpg.hamburg\/wp-content\/uploads\/2015\/02\/musikgruppe.png 301w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: left;\">Nach dem Konzert wartete auf unsere G\u00e4ste der festlich dekorierte Gemeindesaal. Wir konnten ca. 80 Besucher begr\u00fc\u00dfen und waren \u00fcber die gute Beteiligung sehr erfreut.<\/p>\n<p style=\"text-align: left;\"><a href=\"https:\/\/dpg.hamburg\/wp-content\/uploads\/2015\/02\/konsul2014.png\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-502 alignleft\" src=\"https:\/\/dpg.hamburg\/wp-content\/uploads\/2015\/02\/konsul2014.png\" alt=\"konsul2014\" width=\"297\" height=\"224\" \/><\/a><\/p>\n<p style=\"text-align: left;\">Besonders freuten wir uns \u00fcber den Ehrengast, den Generalkonsul der Republik Polen in Hamburg Marian Cichosz und seine Gattin Ewa Cichosz. Das Vorstandsmitglied Hartwig Zillmer las zwei interessante besinnliche Weihnachtsgeschichten. F\u00fcr die Gaumengen\u00fcsse unserer G\u00e4ste sorgten der von unserem Vorstandsmitglied Beata Ratajczak selbstgemachte polnische \u201eRote Barszcz\u201c und die von der Chorleiterin Marianna Jara zubereitete ukrainische Kutia gesorgt. Sie besteht aus gekochtem Weizen, Mohn, Honig, Mandeln und N\u00fcssen und darf auf keinem ukrainischen Weihnachtstisch fehlen. Beim gemeinsamen Gesang und einigen wunderbar klingenden Volksliedern der S\u00e4ngerinnen ist der Abend schnell vergangen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ADVENTSFEIER Wir haben zu unserer Adventsfeier 2014 das Ensemble Widymo aus der polnisch-ukrainischen Grenzstadt Sanok im San-Tal (S\u00fcd-Ost-Karpaten) eingeladen. Der Kontakt mit der Gruppe ist durch unsere DPG-Freunde in Kiel [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[11,10,117],"class_list":["post-500","post","type-post","status-publish","format-standard","category-dpg-hamburg","tag-advent","tag-musik","tag-polnisches-konsulat","czr-hentry"],"_links":{"self":[{"href":"https:\/\/dpg.hamburg\/es\/wp-json\/wp\/v2\/posts\/500","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dpg.hamburg\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dpg.hamburg\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dpg.hamburg\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dpg.hamburg\/es\/wp-json\/wp\/v2\/comments?post=500"}],"version-history":[{"count":0,"href":"https:\/\/dpg.hamburg\/es\/wp-json\/wp\/v2\/posts\/500\/revisions"}],"wp:attachment":[{"href":"https:\/\/dpg.hamburg\/es\/wp-json\/wp\/v2\/media?parent=500"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dpg.hamburg\/es\/wp-json\/wp\/v2\/categories?post=500"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dpg.hamburg\/es\/wp-json\/wp\/v2\/tags?post=500"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}