{"id":3789,"date":"2019-11-28T00:35:34","date_gmt":"2019-11-27T23:35:34","guid":{"rendered":"https:\/\/dpg.hamburg\/?p=3789"},"modified":"2019-10-04T14:43:45","modified_gmt":"2019-10-04T13:43:45","slug":"das-tal-der-oberen-narew-28-november-2019-um-1930-uhr-stadthaus-bargteheide","status":"publish","type":"post","link":"https:\/\/dpg.hamburg\/fr\/Beitr\u00e4ge\/fremdveranstaltung\/das-tal-der-oberen-narew-28-november-2019-um-1930-uhr-stadthaus-bargteheide\/","title":{"rendered":"DAS TAL DER OBEREN NAREW &#8211; 28. November 2019 um 19:30 Uhr &#8211; Stadthaus Bargteheide"},"content":{"rendered":"<p><strong>DAS TAL DER OBEREN NAREW <\/strong><\/p>\n<p><a href=\"https:\/\/dpg.hamburg\/wp-content\/uploads\/2019\/01\/narew2019.png\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-3263 alignleft\" src=\"https:\/\/dpg.hamburg\/wp-content\/uploads\/2019\/01\/narew2019.png\" alt=\"\" width=\"265\" height=\"197\" \/><\/a>Im Februar dieses Jahres zeigte der Fotograf <strong>Martin Franz<\/strong> Mitgliedern und G\u00e4sten unserer Gesellschaft seine Bilder-Show \u201eOstpolnisches Kleinod \u2013 Das Tal der Oberen Narew und seine D\u00f6rfer\u201c und weckte damit bei den Zuschauern gro\u00dfes Interesse an einer Region Polens, die in Deutschland weitgehend unbekannt ist. Ende April konnte er dann mit Unterst\u00fctzung der DPG-HH in einem der Orte des Oberen Narewtals sogar eine Fotoausstellung er\u00f6ffnen, \u00fcber die wir berichtet haben.<\/p>\n<p>Wer die Foto-Show im Februar nicht sehen konnte oder sie noch einmal erleben m\u00f6chte, hat dazu am Donnerstag, dem <strong>28. November 2019 um 19:30 Uhr<\/strong> Gelegenheit. Dann wird Martin Franz auf Einladung des Europavereins Bargteheide e.V. und der VHS Bargteheide noch einmal seinen Vortrag<strong> im Stadthaus Bargteheide (Am Markt 4<\/strong>) pr\u00e4sentieren. Der Eintritt betr\u00e4gt 7,50 Euro.<\/p>\n<p>Aus der Ank\u00fcndigung: \u201eHolzh\u00e4user mit sch\u00f6n geschnitzten Verzierungen und bunten Fensterl\u00e4den pr\u00e4gen das Bild einiger D\u00f6rfer im d\u00fcnn besiedelten Nordosten Polens. Die Narew, ein benachbarter kleiner Fluss, schl\u00e4ngelt sich durch bunte Uferwiesen und gro\u00dfe Schilfgebiete. Der Fotograf Martin Franz hat die romantischen D\u00f6rfer und den Fluss mit seiner gro\u00dfartigen Natur zu allen Jahreszeiten besucht und daraus eine ganz pers\u00f6nliche Liebeserkl\u00e4rung an diese bezaubernde Landschaft gestaltet. In seiner Fotoserie haben die Spatzen an der Dorfstra\u00dfe ihren Auf-tritt ebenso wie das Pferd mit der Egge auf dem Feld und die Libellen \u00fcber dem Fluss.\u201c<\/p>\n","protected":false},"excerpt":{"rendered":"<p>DAS TAL DER OBEREN NAREW Im Februar dieses Jahres zeigte der Fotograf Martin Franz Mitgliedern und G\u00e4sten unserer Gesellschaft seine Bilder-Show \u201eOstpolnisches Kleinod \u2013 Das Tal der Oberen Narew und [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3263,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[142,103],"tags":[],"class_list":["post-3789","post","type-post","status-publish","format-standard","has-post-thumbnail","category-fremdbeitrag","category-fremdveranstaltung","czr-hentry"],"_links":{"self":[{"href":"https:\/\/dpg.hamburg\/fr\/wp-json\/wp\/v2\/posts\/3789","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dpg.hamburg\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dpg.hamburg\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dpg.hamburg\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dpg.hamburg\/fr\/wp-json\/wp\/v2\/comments?post=3789"}],"version-history":[{"count":0,"href":"https:\/\/dpg.hamburg\/fr\/wp-json\/wp\/v2\/posts\/3789\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dpg.hamburg\/fr\/wp-json\/wp\/v2\/media\/3263"}],"wp:attachment":[{"href":"https:\/\/dpg.hamburg\/fr\/wp-json\/wp\/v2\/media?parent=3789"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dpg.hamburg\/fr\/wp-json\/wp\/v2\/categories?post=3789"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dpg.hamburg\/fr\/wp-json\/wp\/v2\/tags?post=3789"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}