{"id":3848,"date":"2019-11-20T00:40:56","date_gmt":"2019-11-19T23:40:56","guid":{"rendered":"https:\/\/dpg.hamburg\/?p=3848"},"modified":"2019-11-19T16:09:37","modified_gmt":"2019-11-19T15:09:37","slug":"kurzfilmvorstellung-der-marschall-und-der-mann-von-welt-harry-graf-kessler-und-jozef-pilsudski-20-11-2019-19-uhr-residenz-des-generalkonsuls-der-republik-polen","status":"publish","type":"post","link":"https:\/\/dpg.hamburg\/fr\/Beitr\u00e4ge\/fremdveranstaltung\/kurzfilmvorstellung-der-marschall-und-der-mann-von-welt-harry-graf-kessler-und-jozef-pilsudski-20-11-2019-19-uhr-residenz-des-generalkonsuls-der-republik-polen\/","title":{"rendered":"Kurzfilmvorstellung \u00ab\u00a0Der Marschall und der Mann von Welt: Harry Graf Kessler und J\u00f3zef Pi\u0142sudski\u00a0\u00bb &#8211; 20.11.2019 19 Uhr &#8211; Residenz des Generalkonsuls der Republik Polen"},"content":{"rendered":"<p>Liebe DPG-Mitgleder,<\/p>\n<p>szanowni Panstwo,<\/p>\n<h2><strong>Daten\u00e4nderung Kurzfilmvorstellung<\/strong><\/h2>\n<p>das Generalkonsulat der Republik Polen organisiert<\/p>\n<h2><strong>am 20.11.2019 um 19 Uhr <\/strong><\/h2>\n<h2>Residenz des Generalkonsuls der Republik Polen<\/h2>\n<p><strong>(Marie-Louisen Str. 137)<\/strong><\/p>\n<p>in Rahmen der \u00ab\u00a0Polnischen Kulturtage\u00a0\u00bb in Hamburg, ein Treffen zum Thema:<\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u00ab\u00a0Der Marschall und der Mann von Welt: Harry Graf Kessler und J\u00f3zef Pi\u0142sudski\u00a0\u00bb <\/strong><\/p>\n<p>Die 45-min\u00fctige Dokumentation von Sabine Carbon, Felix Oehler und Hans von Brescius (Friedrich Naumann-Stiftung, Harry Graf Kessler Gesellschaft e.V.) erz\u00e4hlt die Wiedererstehung Polens vor 100 Jahren mit einer deutsch-polnischen Geschichte zweier bedeutender Pers\u00f6nlichkeiten. Im Anschluss folgt eine Podiumsdiskussion mit Historikern und den Schaffern des Forschungsprojekts \u00fcber die Befreiung Pilsudskis durch Harry Graf Kessler. Mit Prof. Dr. Werner Benecke, Sabine Carbon und weiteren G\u00e4sten.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Liebe DPG-Mitgleder, szanowni Panstwo, Daten\u00e4nderung Kurzfilmvorstellung das Generalkonsulat der Republik Polen organisiert am 20.11.2019 um 19 Uhr Residenz des Generalkonsuls der Republik Polen (Marie-Louisen Str. 137) in Rahmen der \u00ab\u00a0Polnischen [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[142,103,396,232],"tags":[],"class_list":["post-3848","post","type-post","status-publish","format-standard","category-fremdbeitrag","category-fremdveranstaltung","category-generalkonsulat-der-republik-polen","category-residenz-des-polnischen-generalkonsuls","czr-hentry"],"_links":{"self":[{"href":"https:\/\/dpg.hamburg\/fr\/wp-json\/wp\/v2\/posts\/3848","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dpg.hamburg\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dpg.hamburg\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dpg.hamburg\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dpg.hamburg\/fr\/wp-json\/wp\/v2\/comments?post=3848"}],"version-history":[{"count":0,"href":"https:\/\/dpg.hamburg\/fr\/wp-json\/wp\/v2\/posts\/3848\/revisions"}],"wp:attachment":[{"href":"https:\/\/dpg.hamburg\/fr\/wp-json\/wp\/v2\/media?parent=3848"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dpg.hamburg\/fr\/wp-json\/wp\/v2\/categories?post=3848"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dpg.hamburg\/fr\/wp-json\/wp\/v2\/tags?post=3848"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}