{"id":4028,"date":"2020-02-25T23:08:46","date_gmt":"2020-02-25T22:08:46","guid":{"rendered":"https:\/\/dpg.hamburg\/?p=4028"},"modified":"2020-02-25T23:35:18","modified_gmt":"2020-02-25T22:35:18","slug":"mitteilungen-2-2020-maerz-april","status":"publish","type":"post","link":"https:\/\/dpg.hamburg\/fr\/Beitr\u00e4ge\/mitteilungen\/mitteilungen-2-2020-maerz-april\/","title":{"rendered":"MITTEILUNGEN 2-2020 (M\u00e4rz-April)"},"content":{"rendered":"<p><strong>U N S E R E\u00a0 V E R A N S T A L T U N G E N<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>MITGLIEDERVERSAMMLUNG<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><a href=\"https:\/\/dpg.hamburg\/wp-content\/uploads\/2020\/01\/bfw.png\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3979 alignleft\" src=\"https:\/\/dpg.hamburg\/wp-content\/uploads\/2020\/01\/bfw.png\" alt=\"\" width=\"337\" height=\"90\" srcset=\"https:\/\/dpg.hamburg\/wp-content\/uploads\/2020\/01\/bfw.png 1600w, https:\/\/dpg.hamburg\/wp-content\/uploads\/2020\/01\/bfw-300x80.png 300w, https:\/\/dpg.hamburg\/wp-content\/uploads\/2020\/01\/bfw-1024x273.png 1024w, https:\/\/dpg.hamburg\/wp-content\/uploads\/2020\/01\/bfw-768x205.png 768w, https:\/\/dpg.hamburg\/wp-content\/uploads\/2020\/01\/bfw-1536x410.png 1536w\" sizes=\"auto, (max-width: 337px) 100vw, 337px\" \/><\/a>Am Montag<strong>, 6. April 2020\u00a0 um 18.00 Uhr, <\/strong>findet im Berufsf\u00f6rderungswerk Hamburg (August-Krogmann-Str. 52, Geb\u00e4ude U, Kaminzimmer\u00a0 im Erdgeschoss) die Mitgliederversammlung 2020 statt, die f\u00fcr uns das wichtigste Forum ist, in dem wir mit Ihnen ins Gespr\u00e4ch kommen k\u00f6nnen. Das vergangene Jahr war von vielen besonderen Ereignissen gekennzeichnet, \u00fcber die wir Ihnen berichten werden.\u00a0 Da es um die wesentliche Weichenstellung f\u00fcr die Arbeit im kommenden Jahr geht, w\u00fcrden wir uns \u00fcber Ihre Anwesenheit und zahlreiche Teilnahme freuen. Mit diesen Mitteilungen erhalten Sie die Tagesordnung. F\u00fcr einen kleinen Imbiss und Getr\u00e4nke wird wieder gesorgt.<\/p>\n<p>Diesmal beginnen wir die Mitgliederversammlung mit dem Bericht einer Studentengruppe der Evangelischen Hochschule f\u00fcr Soziale Arbeit am Rauen Haus, die ein Praktikum in Polen von 1.10. bis 10.10.2019,\u00a0 (15 Studierenden) absolviert haben. Im Antrag f\u00fcr diese Reise stand: \u201eDie erste Station unserer Reise wird Krakau sein. Dort werden wir, neben dem Erkunden der Kultur und Geschichte Krakaus, unserem Erasmus Projektpartner, der P\u00e4dagogischen Universit\u00e4t Krakau, begegnen und uns mit ihm austauschen. Die zweite Station unserer Reise wird ein dreit\u00e4giger Aufenthalt in einer Jugendbegegnungsst\u00e4tte in O\u015bwi\u0119cim sein. Dort werden wir, begleitet durch die Jugendbegegnungsst\u00e4tte, die Gedenkst\u00e4tte KZ Auschwitz besuchen und uns, mit von der Jugendbegegnungsst\u00e4tte vorbereiteten Workshops, intensiv mit der Geschichte auseinandersetzen. Die dritte und letzte Station unserer Reise wird Warschau sein, wo wir auf den Spuren von Janusz Korczak die Stadt und ihre Geschichte erkunden wollen.\u201c Sie wurden von Prof. Dr. Timm Kunstreich begleitet. Wir haben auch dieses Projekt finanziell unterst\u00fctzt.<\/p>\n<p><strong>TAGESORDNUNG<\/strong><\/p>\n<p><strong>DER\u00a0 MITGLIEDERVERSAMMLUNG DER DPG HAMBURG 2020<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>am Montag, dem 6. April 2020 um 18.00 Uhr im Berufsf\u00f6rderungswerk Hamburg, Kaminzimmer im Erdgeschoss, August-Krogmann-Str. 52*, <\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<ol>\n<li><strong>Bericht einiger Studenten \u00fcber das Praktikum in Polen vom 1. bis 10.10.2019, die 15 Studierenden an der Evangelischen Hochschule f\u00fcr Soziale Arbeit am Rauen Haus in Begleitung von Prof. Dr. Timm Kunstreich absolviert haben.<\/strong><\/li>\n<li><strong>Pause<\/strong><\/li>\n<\/ol>\n<ul>\n<li><\/li>\n<\/ul>\n<ol>\n<li><strong> Er\u00f6ffnung und Begr\u00fc\u00dfung sowie Feststellen der Beschlussf\u00e4higkeit<\/strong><\/li>\n<li><strong> Genehmigung der Tagesordnung und Wahl eines Protokollf\u00fchrers<\/strong><\/li>\n<li><strong> Entwicklung der Mitgliederzahl und Begr\u00fc\u00dfung neuer Mitglieder<\/strong><\/li>\n<li><strong> Bericht des Vorstands<\/strong><\/li>\n<li><strong> Kassenbericht<\/strong><\/li>\n<li><strong> Aussprache zu den Berichten<\/strong><\/li>\n<li><strong> Bericht der Kassenpr\u00fcfer<\/strong><\/li>\n<li><strong> Entlastung des Vorstandes<\/strong><\/li>\n<\/ol>\n<p><strong>9\u00a0\u00a0\u00a0 Ausblick auf die Jahresplanung 2018<\/strong><\/p>\n<ol start=\"10\">\n<li><strong> Verschiedenes <\/strong><\/li>\n<\/ol>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>*Sie erreichen das BFW mit der U-Bahn U1 (Station Farmsen), dann zu Fu\u00df \u00fcber den Weg entlang der U1 oder \u00fcber die August-Krogmann-Stra\u00dfe oder auch mit den Bussen 27 und 168 (1 Station). Die Parkpl\u00e4tze sind beschr\u00e4nkt, aber einige auf dem Gel\u00e4nde des BFW sind vorhanden. <\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>AUS DER KONZERTREIHE: &lsquo;MUSIKALISCHE STOLPERSTEINE&rsquo; <\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><a href=\"https:\/\/dpg.hamburg\/wp-content\/uploads\/2018\/12\/hfmt-viewbig2018.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3253 alignleft\" src=\"https:\/\/dpg.hamburg\/wp-content\/uploads\/2018\/12\/hfmt-viewbig2018.jpg\" alt=\"\" width=\"352\" height=\"235\" srcset=\"https:\/\/dpg.hamburg\/wp-content\/uploads\/2018\/12\/hfmt-viewbig2018.jpg 1024w, https:\/\/dpg.hamburg\/wp-content\/uploads\/2018\/12\/hfmt-viewbig2018-300x200.jpg 300w, https:\/\/dpg.hamburg\/wp-content\/uploads\/2018\/12\/hfmt-viewbig2018-768x512.jpg 768w\" sizes=\"auto, (max-width: 352px) 100vw, 352px\" \/><\/a>Das Konzert &lsquo;Musik auf der Schwarzen Liste&rsquo; der studentischen Initiative Culture Connects mit der Unterst\u00fctzung der Deutsch-Polnischer Gesellschaft widmet sich 2020, 75 Jahre nach Ende des 2. Weltkriegs, einem vergessenen Kapitel der Musikgeschichte: einst ein Teil der pulsierenden Kulturwelt der Zwischenkriegszeit, heute nur ausgew\u00e4hlten Experten bekannt &#8211; Komponisten wie Szymon Laks oder Erwin Schulhoff geh\u00f6rten zu den f\u00fchrenden Ihrer Zeit und wurden nach 1933 entw\u00fcrdigt, verboten und verfolgt. Der eine \u00fcberlebte als Leiter des Lagerorchesters von Auschwitz, der andere starb als Gefangener im KZ W\u00fclzburg in Bayern &#8211; au\u00dfergew\u00f6hnliche Schicksale, dennoch kaum rezipiert und selten gespielt, wie so viele ihrer ber\u00fchmten Zeitgenossen, die unter Verfolgung litten. Die Musik jener Zeit lassen junge exzellente K\u00fcnstler aus Hamburg, Berlin, Bremen und Hannover wieder aufleben und erz\u00e4hlen ihre Geschichte in den historischen R\u00e4umen des Budge-Palais, einer j\u00fcdischen, in der NS-Zeit zwangsenteigneten, Kaufmannsvilla und Residenz des Reichsstatthalters der NSDAP bis 1945. Ihre letzten Bewohner der Familie Budge kamen durch die NS-Verfolgung zu Tode. Daran erinnern zwei Stolpersteine vor dem Haus.<\/p>\n<p>Die Konzertreihe &lsquo;Musikalische Stolpersteine&rsquo; widmet sich ausschlie\u00dflich verfemter oder &lsquo;entarteter&rsquo; Musik.<\/p>\n<p>Werke von: Szymon Laks, Erwin Schulhoff, Ernst Krenek, Witold Lutos\u0142awski, Olivier Messiaen uvm. Mitwirkende: Elizaveta Don (Hamburg) &#8211; Klavier, Alina Ohem (Hamburg) &#8211; Klassische Gitarre, Sebastian Berakdar (Berlin) &#8211; Klavier, Eduard Don (Hamburg) &#8211; Klarinette, Lev Kucher (Hannover) &#8211; Violoncello und Roman Ohem (Bremen) &#8211; Violine und Moderation<\/p>\n<p>&nbsp;<\/p>\n<p>Das Konzert findet am <strong>25.4.2020 um 19.30 Uhr<\/strong> im Mendelssohnsaal der HfMT Hamburg, Harvesterhuderweg 12 statt. Eintritt: 15\/10 Euro, Mitglieder der DPG HH zahlen 10,00\u20ac.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>LESUNG MIT ARNO \u00a0SURMINSKI<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><a href=\"https:\/\/dpg.hamburg\/wp-content\/uploads\/2019\/08\/ARNO-SURMINSKI2019.png\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-3656 alignleft\" src=\"https:\/\/dpg.hamburg\/wp-content\/uploads\/2019\/08\/ARNO-SURMINSKI2019.png\" alt=\"\" width=\"376\" height=\"252\" srcset=\"https:\/\/dpg.hamburg\/wp-content\/uploads\/2019\/08\/ARNO-SURMINSKI2019.png 376w, https:\/\/dpg.hamburg\/wp-content\/uploads\/2019\/08\/ARNO-SURMINSKI2019-300x201.png 300w\" sizes=\"auto, (max-width: 376px) 100vw, 376px\" \/><\/a>Am <strong>29. April um 19.00 Uhr<\/strong> findet im Altonaer Museum, Museumstr. 23 eine Lesung mit dem Schriftsteller und unserem Mitglied Arno Surminski statt. Er wird aus seinen ausgew\u00e4hlten Werken vorlesen, die sich mit Polen, Ostpreu\u00dfen, Vergangenheit und Zukunft befassen.<\/p>\n<p>Arno Surminski hatte schon mit seinem ersten Roman \u201eJokehnen: oder Wie lange f\u00e4hrt man von Ostpreu\u00dfen nach Deutschland?\u201c, der 1974 erschien, einen gro\u00dfen Erfolg. Der Roman, in dem der Schriftsteller seine eigene Vergangenheit verarbeitet, wurde sp\u00e4ter erfolgreich verfilmt. Zahlreiche Romane und Erz\u00e4hlungen, aber auch Sachb\u00fccher des Autors folgten. Der Wahl-Hamburger setzte sich immer wieder f\u00fcr die Verst\u00e4ndigung und die Vers\u00f6hnung zwischen Deutschen und Polen ein.<\/p>\n<p>Als einer der letzten noch lebenden Zeitzeugen schildert Arno Surminski in seinen B\u00fcchern und Erz\u00e4hlungen oft das Leben in Ostpreu\u00dfen \u2013 einst friedlich und fast idyllisch, dann zerst\u00f6rt durch Krieg und Vertreibung, und letztlich von Gefl\u00fcchteten fortgef\u00fchrt an anderen Orten fernab der Heimat. Der Schriftsteller\u00a0 leistet mit seinen zahlreichen Romanen und Erz\u00e4hlungen einen wichtigen literarischen Beitrag zum Umgang mit dem Thema Flucht und Vertreibung in Deutschland. Viele seiner B\u00fccher wurden in andere Sprachen \u00fcbersetzt und mehrfach ausgezeichnet.<\/p>\n<p>Sehr bewegend erz\u00e4hlt Arno Surminski die Geschichten seiner Protagonisten. Diese tragen bisweilen auch autobiografische Z\u00fcge und stehen stellvertretend f\u00fcr das Schicksal einer ganzen Generation von Heimatvertriebenen aus Ostpreu\u00dfen.<\/p>\n<p>Das Politische Bildungsforum Hamburg der Konrad-Adenauer-Stiftung e.V. und ihr Kooperationspartner, die Deutsch-Polnische Gesellschaft Hamburg e.V., sind erfreut, dass Arno Surminski die Einladung annahm. Da seine Themen auch heute noch aktuell sind, wird der Schriftsteller mit den Teilnehmerinnen und Teilnehmern ins Gespr\u00e4ch kommen..<\/p>\n<p>Der Eintritt ist frei, <strong>wir bitten um verbindliche Anmeldung per E-Mail kas-hamburg@kas.de bis 22. April.<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>PROJEKTE ANDERER VERANSTALTER<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>AUSSTELLUNG IM ATELIER VON JAN DE WERYHA<\/strong><\/p>\n<figure id=\"attachment_1257\" style=\"width: 288px\"  class=\"wp-caption alignleft\"><a href=\"https:\/\/dpg.hamburg\/wp-content\/uploads\/2015\/12\/weryha-kellermann.png\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-1257\" src=\"https:\/\/dpg.hamburg\/wp-content\/uploads\/2015\/12\/weryha-kellermann.png\" alt=\"\" width=\"288\" height=\"114\" srcset=\"https:\/\/dpg.hamburg\/wp-content\/uploads\/2015\/12\/weryha-kellermann.png 770w, https:\/\/dpg.hamburg\/wp-content\/uploads\/2015\/12\/weryha-kellermann-300x119.png 300w\" sizes=\"auto, (max-width: 288px) 100vw, 288px\" \/><\/a><figcaption class=\"wp-caption-text\">Jan de Weryha<\/figcaption><\/figure>\n<p>Am Sonntag<strong>, dem 22. M\u00e4rz um 15.00 Uhr<\/strong> findet im Atelierhaus Reinbecker Redder 81 die Vernissage der Ausstellung der neuesten Arbeiten des polnischen K\u00fcnstlers Jan de Weryha statt. Die G\u00e4ste werden vom ersten Vorsitzenden des Freundeskreises Sammlung Jan de Weryha, Werner Omniczynski, begr\u00fc\u00dft. Die Einf\u00fchrung kommt von Dr. Volker Probst, (1994-2005 Leiter des Barlach-Museums in G\u00fcstrow), unter dem Titel \u201eGEWACHSEN- GESPALTEN- GESTALTET Bemerkung zum Holzwerk von Jan de Weryha\u201c.<\/p>\n<p><!--more--><\/p>\n<p><a href=\"https:\/\/dpg.hamburg\/wp-content\/uploads\/2020\/02\/Sammlung-de-Weryha-Hamburg-1-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-4049 alignright\" src=\"https:\/\/dpg.hamburg\/wp-content\/uploads\/2020\/02\/Sammlung-de-Weryha-Hamburg-1-scaled.jpg\" alt=\"\" width=\"196\" height=\"131\" srcset=\"https:\/\/dpg.hamburg\/wp-content\/uploads\/2020\/02\/Sammlung-de-Weryha-Hamburg-1-scaled.jpg 2560w, https:\/\/dpg.hamburg\/wp-content\/uploads\/2020\/02\/Sammlung-de-Weryha-Hamburg-1-300x200.jpg 300w, https:\/\/dpg.hamburg\/wp-content\/uploads\/2020\/02\/Sammlung-de-Weryha-Hamburg-1-1024x683.jpg 1024w, https:\/\/dpg.hamburg\/wp-content\/uploads\/2020\/02\/Sammlung-de-Weryha-Hamburg-1-768x512.jpg 768w, https:\/\/dpg.hamburg\/wp-content\/uploads\/2020\/02\/Sammlung-de-Weryha-Hamburg-1-1536x1024.jpg 1536w, https:\/\/dpg.hamburg\/wp-content\/uploads\/2020\/02\/Sammlung-de-Weryha-Hamburg-1-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 196px) 100vw, 196px\" \/><\/a>Jan de Weryha (* 1950 in Gda\u0144sk) ist ein polnischer Bildhauer und Vertreter der Konkreten Kunst. Im Jahre 1976 erlangte er sein Diplom in Bildhauerei an der Kunstakademie Danzig. Seit 1981 lebt er in Hamburg. Er war 1998 Preistr\u00e4ger des Prix du Jury beim Salon de Printemps &rsquo;98 Luxemburg. Den Auftrag f\u00fcr das Denkmal zur Erinnerung an die Deportierten des Warschauer Aufstandes 1944 \u00a0in der KZ-Gedenkst\u00e4tte Neuengamme erhielt er 1999 und 2012 den Auftrag f\u00fcr das Mahnmal zum Gedenken der NS-Zwangsarbeiter in Hamburg-Bergedorf. W\u00e4hrend der Einweihung kam es zu einer Gasattacke eines Deutschen auf polnische Ehreng\u00e4ste. Seine ausgefallenen Arbeiten wurden in zahlreichen Ausstellungen in der ganzen Welt gezeigt.<\/p>\n<p><a href=\"https:\/\/dpg.hamburg\/wp-content\/uploads\/2020\/02\/Sammlung-de-Weryha-Hamburg-2-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-4050 alignleft\" src=\"https:\/\/dpg.hamburg\/wp-content\/uploads\/2020\/02\/Sammlung-de-Weryha-Hamburg-2-scaled.jpg\" alt=\"\" width=\"201\" height=\"134\" srcset=\"https:\/\/dpg.hamburg\/wp-content\/uploads\/2020\/02\/Sammlung-de-Weryha-Hamburg-2-scaled.jpg 2560w, https:\/\/dpg.hamburg\/wp-content\/uploads\/2020\/02\/Sammlung-de-Weryha-Hamburg-2-300x200.jpg 300w, https:\/\/dpg.hamburg\/wp-content\/uploads\/2020\/02\/Sammlung-de-Weryha-Hamburg-2-1024x683.jpg 1024w, https:\/\/dpg.hamburg\/wp-content\/uploads\/2020\/02\/Sammlung-de-Weryha-Hamburg-2-768x512.jpg 768w, https:\/\/dpg.hamburg\/wp-content\/uploads\/2020\/02\/Sammlung-de-Weryha-Hamburg-2-1536x1024.jpg 1536w, https:\/\/dpg.hamburg\/wp-content\/uploads\/2020\/02\/Sammlung-de-Weryha-Hamburg-2-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 201px) 100vw, 201px\" \/><\/a>In seiner k\u00fcnstlerischen Arbeit besch\u00e4ftigt er sich mit der Materialit\u00e4t des Holzes. Schnitt, Bruch, Spalt sind Begriffe, die seinen Schaffensweg bestimmen. Seine Arbeiten werden in diesem Jahr ab Juni bis Oktober auf der NordArt 2020 in B\u00fcdelsdorf gezeigt. <em>Die 22. Auflage der NordArt zeigt Bilder, Fotografien, Skulpturen und Installationen von mehr als 200 ausgew\u00e4hlten K\u00fcnstlern aus aller Welt \u2013 international renommierte ebenso wie Newcomer. Zur NordArt 2020 haben sich rund 3.000 K\u00fcnstler\/innen aus \u00fcber 100 L\u00e4ndern beworben und die Auswahl der Werke von Jan de Weryha f\u00fcr die Ausstellung bedeutet eine gro\u00dfe Wertsch\u00e4tzung des Hamburger K\u00fcnstlers. <\/em><\/p>\n<p><em>\u00a0<\/em><\/p>\n<p><em>\u00a0<\/em><\/p>\n<p><em>\u00a0\u00a0<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>U N S E R E\u00a0 V E R A N S T A L T U N G E N \u00a0 MITGLIEDERVERSAMMLUNG \u00a0 Am Montag, 6. April 2020\u00a0 um [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[238,15,3],"tags":[],"class_list":["post-4028","post","type-post","status-publish","format-standard","category-deutsch-polnische-gesellschaft-hamburg-e-v","category-dpg-hamburg","category-mitteilungen","czr-hentry"],"_links":{"self":[{"href":"https:\/\/dpg.hamburg\/fr\/wp-json\/wp\/v2\/posts\/4028","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dpg.hamburg\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dpg.hamburg\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dpg.hamburg\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dpg.hamburg\/fr\/wp-json\/wp\/v2\/comments?post=4028"}],"version-history":[{"count":0,"href":"https:\/\/dpg.hamburg\/fr\/wp-json\/wp\/v2\/posts\/4028\/revisions"}],"wp:attachment":[{"href":"https:\/\/dpg.hamburg\/fr\/wp-json\/wp\/v2\/media?parent=4028"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dpg.hamburg\/fr\/wp-json\/wp\/v2\/categories?post=4028"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dpg.hamburg\/fr\/wp-json\/wp\/v2\/tags?post=4028"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}