{"id":1281,"date":"2016-02-07T00:26:26","date_gmt":"2016-02-06T23:26:26","guid":{"rendered":"http:\/\/aktuell.dpg.hamburg\/?p=1281"},"modified":"2016-02-22T22:48:12","modified_gmt":"2016-02-22T21:48:12","slug":"chopins-letztes-konzert-1848-eine-veranstaltung-im-schloss-reinbek-7-februar-2016-1830-uhr","status":"publish","type":"post","link":"https:\/\/dpg.hamburg\/it\/Beitr\u00e4ge\/fremdveranstaltung\/chopins-letztes-konzert-1848-eine-veranstaltung-im-schloss-reinbek-7-februar-2016-1830-uhr\/","title":{"rendered":"Chopins letztes Konzert 1848 \u2013 eine Veranstaltung im Schloss Reinbek &#8211; 7. Februar 2016 18:30 Uhr"},"content":{"rendered":"<p>Liebe Freunde der Chopin-Gesellschaft Hamburg-Sachsenwald e.V.,<\/p>\n<p>nun starten wir in unser 4. Jahr mit au\u00dfergew\u00f6hnlichen Konzerten, zu denen wir Sie sehr herzlich einladen und auf die wir uns gemeinsam freuen.<\/p>\n<p>Eine besondere Beachtung verdient unser Konzert am 7. Februar 2016 18:30 Uhr im Reinbeker Schloss. Es handelt sich hierbei um eine Wiederauff\u00fchrung des letzten Pariser Konzerts von Chopin vom 16.<br \/>\nFebruar 1848, welches man sehr selten zu h\u00f6ren bekommt. Der Pianist des Abends ist Volodymyr Lavrynenko aus der Ukraine, die Moderation hat Prof. Adam Wibrowski aus Paris \u00fcbernommen, au\u00dferdem spielt ein Klavier-Trio der HfMT Hamburg. Karten erhalten Sie \u00fcber das Internet, bei unseren bekannten Verkaufsstellen in Aum\u00fchle und Reinbek sowie im Reinbeker Schloss. Wir freuen uns auf Ihren Besuch.<\/p>\n<p>Herzliche Gr\u00fc\u00dfe<br \/>\nRolf Nerlich<\/p>\n<p>&#8212;<br \/>\nChopin-Gesellschaft Hamburg-Sachsenwald e.V.<br \/>\nDr. Daniela und Rolf Nerlich, Mitglieder des Vorstandes<br \/>\nOtternweg 4<br \/>\n21521 Aum\u00fchle<br \/>\nFax: 04104 694835<br \/>\nE-Mail: dr.nerlich@chopin-hamburg.de oder nerlich@chopin-hamburg.de<br \/>\nWeb: <a href=\"http:\/\/www.chopin-hamburg.de\" target=\"_blank\">www.chopin-hamburg.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Liebe Freunde der Chopin-Gesellschaft Hamburg-Sachsenwald e.V., nun starten wir in unser 4. Jahr mit au\u00dfergew\u00f6hnlichen Konzerten, zu denen wir Sie sehr herzlich einladen und auf die wir uns gemeinsam freuen. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[152,103],"tags":[],"class_list":["post-1281","post","type-post","status-publish","format-standard","category-chopin-gesellschaft-hamburg-sachsenwald","category-fremdveranstaltung","czr-hentry"],"_links":{"self":[{"href":"https:\/\/dpg.hamburg\/it\/wp-json\/wp\/v2\/posts\/1281","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dpg.hamburg\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dpg.hamburg\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dpg.hamburg\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dpg.hamburg\/it\/wp-json\/wp\/v2\/comments?post=1281"}],"version-history":[{"count":0,"href":"https:\/\/dpg.hamburg\/it\/wp-json\/wp\/v2\/posts\/1281\/revisions"}],"wp:attachment":[{"href":"https:\/\/dpg.hamburg\/it\/wp-json\/wp\/v2\/media?parent=1281"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dpg.hamburg\/it\/wp-json\/wp\/v2\/categories?post=1281"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dpg.hamburg\/it\/wp-json\/wp\/v2\/tags?post=1281"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}