{"id":223,"date":"2014-11-07T08:00:46","date_gmt":"2014-11-07T06:00:46","guid":{"rendered":"http:\/\/aktuell.dpg.hamburg\/?p=223"},"modified":"2014-11-18T01:34:06","modified_gmt":"2014-11-17T23:34:06","slug":"kongress-der-deutsch-polnischen-gesellschaft-bundesverband-in-dresden-2014","status":"publish","type":"post","link":"https:\/\/dpg.hamburg\/it\/Beitr\u00e4ge\/dpg-bundesverband\/kongress-der-deutsch-polnischen-gesellschaft-bundesverband-in-dresden-2014\/","title":{"rendered":"KONGRESS  DER DEUTSCH-POLNISCHEN GESELLSCHAFT  BUNDESVERBAND  IN  DRESDEN 2014"},"content":{"rendered":"<p><a href=\"https:\/\/dpg.hamburg\/wp-content\/uploads\/2014\/11\/pic_bundeskongress_197_10892.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-350\" src=\"https:\/\/dpg.hamburg\/wp-content\/uploads\/2014\/11\/pic_bundeskongress_197_10892.jpg\" alt=\"pic_bundeskongress_197_10892\" width=\"476\" height=\"317\" data-wp-pid=\"350\" \/><\/a><\/p>\n<p>KONGRESS\u00a0 DER DEUTSCH-POLNISCHEN GESELLSCHAFT\u00a0 BUNDESVERBAND\u00a0 IN\u00a0 DRESDEN\u00a0 Der Jahreskongress des Bundesverbandes findet vom 7. bis 9. November 2014 in Dresden statt. Im Rahmen des Kongresses wird auch der DIALOG-Preis 2014 verliehen, den in diesem Jahr der polnische Staatspr\u00e4sident a. D. und Friedensnobelpreistr\u00e4ger Lech Walesa erhalten wird. Der Vorstand der DPG Hamburg l\u00e4dt alle Interessenten herzlich ein, an diesem Kongress in der Metropole an der Oberelbe und Partnerstadt Hamburgs teilzunehmen. Die Arbeit wird in diesem Jahr u.a. in f\u00fcnf Arbeitsgruppen verlaufen, und zwar zu den Themen Schulpartnerschaften, Zusammenarbeit in der Grenzregion, Sorben als Mittler zwischen Polen und Deutschland und Erinnerungskultur. Je nach Interessenlage kann jeder an einer der jeweiligen Arbeitsgruppen teilnehmen. In den Podiumsdiskussionen wird auch die friedliche Revolution vor 25 Jahren thematisiert. Abends findet eine Tanzveranstaltung statt. Mehr Informationen \u00fcber den Kongress erhalten sie auf der Webseite des Bundesverbandes: www.dpg-bundesverband.de\u00a0 Das Angebot aus den letzten Mitteilungen, an dem Dresden-Besichtigungsprogramm am 6.11. teilzunehmen, ist immer noch aktuell. Falls Sie Interesse an dieser gemeinsamen Reise mit dem Vorstand unserer Gesellschaft haben, melden Sie sich bitte bis zum 30. Oktober 2014 an. N\u00e4here Informationen erhalten Sie bei unserer Vorsitzenden unter Telefon 830 12 21 oder bei unserem Ehrenvorsitzenden Gerd Hoffmann unter 04154 795884, der auch f\u00fcr die Durchf\u00fchrung des Besichtigungsprogramms verantwortlich ist. Sie k\u00f6nnen sich auch per E-Mail: hoffmann.gerd@hamburg.de oder krizak_viola@hotmail.com anmelden.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>KONGRESS\u00a0 DER DEUTSCH-POLNISCHEN GESELLSCHAFT\u00a0 BUNDESVERBAND\u00a0 IN\u00a0 DRESDEN\u00a0 Der Jahreskongress des Bundesverbandes findet vom 7. bis 9. November 2014 in Dresden statt. Im Rahmen des Kongresses wird auch der DIALOG-Preis 2014 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[123],"tags":[122],"class_list":["post-223","post","type-post","status-publish","format-standard","category-dpg-bundesverband","tag-dpg-kongress","czr-hentry"],"_links":{"self":[{"href":"https:\/\/dpg.hamburg\/it\/wp-json\/wp\/v2\/posts\/223","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dpg.hamburg\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dpg.hamburg\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dpg.hamburg\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dpg.hamburg\/it\/wp-json\/wp\/v2\/comments?post=223"}],"version-history":[{"count":0,"href":"https:\/\/dpg.hamburg\/it\/wp-json\/wp\/v2\/posts\/223\/revisions"}],"wp:attachment":[{"href":"https:\/\/dpg.hamburg\/it\/wp-json\/wp\/v2\/media?parent=223"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dpg.hamburg\/it\/wp-json\/wp\/v2\/categories?post=223"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dpg.hamburg\/it\/wp-json\/wp\/v2\/tags?post=223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}