{"id":3551,"date":"2019-06-22T00:14:43","date_gmt":"2019-06-21T23:14:43","guid":{"rendered":"https:\/\/dpg.hamburg\/?p=3551"},"modified":"2019-04-29T14:21:20","modified_gmt":"2019-04-29T13:21:20","slug":"fahrt-nach-lueneburg-am-22-juni-um-1200-uhr-ostpreussische-landesmuseum","status":"publish","type":"post","link":"https:\/\/dpg.hamburg\/it\/Beitr\u00e4ge\/dpg-hamburg\/fahrt-nach-lueneburg-am-22-juni-um-1200-uhr-ostpreussische-landesmuseum\/","title":{"rendered":"FAHRT NACH L\u00dcNEBURG am 22. Juni um 12:00 Uhr Ostpreu\u00dfische Landesmuseum"},"content":{"rendered":"<p>Im August 2018\u00a0 wurde das Ostpreu\u00dfische Landesmuseum nach umfangreichen Umbauma\u00dfnahmen wieder er\u00f6ffnet und pr\u00e4sentiert mit der Deutsch-Baltischer Abteilung neben seinen wechselnden Sonderausstellungen eine vollkommen neugestaltete Dauerausstellung. Es hei\u00dft auf der Webseite des Museums: \u201eErforschen Sie Bernstein im hauseigenen Labor, sp\u00e4hen Sie vom Hochsitz in die weiten W\u00e4lder des ehemaligen Ostpreu\u00dfens, verfolgen Sie den Weg vom Aufstieg Preu\u00dfens bis zur Reichsgr\u00fcndung, erfahren Sie mehr \u00fcber das Schicksal der Vertriebenen nach dem Zweiten Weltkrieg, entdecken Sie die Hansezeit, betrachten Sie bedeutende Kunst von Lovis Corinth und K\u00e4the Kollwitz und lernen Sie die ber\u00fchmten Trakehner Pferde kennen. Ein H\u00f6hepunkt ist zudem die Deutsch-Baltische Abteilung, die erstmals die Geschichte der Deutschen im Baltikum museal aufbereitet.\u201c<\/p>\n<p>Da wir mit dem Ostpreu\u00dfischen Landesmuseum seit einigen Jahren zusammenarbeiten, m\u00f6chten wir es unter der F\u00fchrung des Museumsdirektor Dr. Joachim M\u00e4hnert besichtigen.<\/p>\n<p>Die Besichtigung findet <strong>am 22. Juni um 12:00 Uhr<\/strong> statt. Nach einer Mittagspause werden wir anschlie\u00dfend eine Stadtf\u00fchrung anbieten. Sie k\u00f6nnen individuell nach L\u00fcneburg reisen oder falls gew\u00fcnscht, werden wir einige Gruppenfahrkarten besorgen.<\/p>\n<p>F\u00fcr die Planung m\u00fcssen wir aber wissen, wie viele Personen mitfahren m\u00f6chten, deshalb bitten wir um Anmeldung bis zum 10.06. unter: <a href=\"mailto:krizak_viola@hotmail.com\">krizak_viola@hotmail.com<\/a>, Tel.: (830 12 21) oder auf dem am Textende angef\u00fcgten Anmeldeformular.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Im August 2018\u00a0 wurde das Ostpreu\u00dfische Landesmuseum nach umfangreichen Umbauma\u00dfnahmen wieder er\u00f6ffnet und pr\u00e4sentiert mit der Deutsch-Baltischer Abteilung neben seinen wechselnden Sonderausstellungen eine vollkommen neugestaltete Dauerausstellung. Es hei\u00dft auf der [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[238,15,50,401],"tags":[],"class_list":["post-3551","post","type-post","status-publish","format-standard","category-deutsch-polnische-gesellschaft-hamburg-e-v","category-dpg-hamburg","category-museum","category-ostpreussische-landesmuseum","czr-hentry"],"_links":{"self":[{"href":"https:\/\/dpg.hamburg\/it\/wp-json\/wp\/v2\/posts\/3551","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dpg.hamburg\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dpg.hamburg\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dpg.hamburg\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dpg.hamburg\/it\/wp-json\/wp\/v2\/comments?post=3551"}],"version-history":[{"count":0,"href":"https:\/\/dpg.hamburg\/it\/wp-json\/wp\/v2\/posts\/3551\/revisions"}],"wp:attachment":[{"href":"https:\/\/dpg.hamburg\/it\/wp-json\/wp\/v2\/media?parent=3551"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dpg.hamburg\/it\/wp-json\/wp\/v2\/categories?post=3551"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dpg.hamburg\/it\/wp-json\/wp\/v2\/tags?post=3551"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}