{"id":2359,"date":"2017-05-01T00:03:17","date_gmt":"2017-04-30T23:03:17","guid":{"rendered":"http:\/\/aktuell.dpg.hamburg\/?p=2359"},"modified":"2018-03-05T22:04:17","modified_gmt":"2018-03-05T21:04:17","slug":"mitteilungen-032017-mai-juli-2","status":"publish","type":"post","link":"https:\/\/dpg.hamburg\/ja\/Beitr\u00e4ge\/mitteilungen\/mitteilungen-032017-mai-juli-2\/","title":{"rendered":"MITTEILUNGEN 03\/2017 (MAI \u2013 JULI)"},"content":{"rendered":"<p><strong>UNSERE VERANSTALTUNGEN<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong><a href=\"https:\/\/dpg.hamburg\/wp-content\/uploads\/2017\/04\/morgenrot.png\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-2346 alignleft\" src=\"https:\/\/dpg.hamburg\/wp-content\/uploads\/2017\/04\/morgenrot-300x208.png\" alt=\"\" width=\"300\" height=\"208\" srcset=\"https:\/\/dpg.hamburg\/wp-content\/uploads\/2017\/04\/morgenrot-300x208.png 300w, https:\/\/dpg.hamburg\/wp-content\/uploads\/2017\/04\/morgenrot.png 373w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>FILMVORF\u00dcHRUNG zur polnisch-ostpreu\u00dfischen Geschichte<\/strong><\/p>\n<p>Am <strong>12. Mai\u00a0 um 19.00 Uhr<\/strong> zeigen wir in der Zusammenarbeit mit dem F\u00f6rderverein \u201eMahnmal St. Nikolai\u201c den Film <strong>\u201eMorgenrot\u201c,<\/strong> nach dem Drehbuch und unter der Regie von Michal Korchowiec.<\/p>\n<p>Sieben Jahrhunderte geh\u00f6rten die Masuren zu Ostpreu\u00dfen, bis sie nach dem Zweiten Weltkrieg in die Volksrepublik Polen eingegliedert wurden. Wer nicht floh oder ums Leben kam, musste sich anpassen. Doch wie wird man zum Beispiel in wenigen Wochen zu einer \u201eechten\u201c Polin angesichts von Enteignung, Gewalt und Zwang? In seiner Familie muss es ein Geheimnis geben, das sp\u00fcrte der 29j\u00e4hriger Maler und B\u00fchnenbildner Micha\u0142 Korchowiec seit langem. Um diesem Geheimnis n\u00e4her zu kommen, produzierte er einen sehr pers\u00f6nlichen Dokumentarfilm: &#8220;Morgenrot&#8221;. Darin geht es um seine deutsche Oma aus Ostpreu\u00dfen, die nach dem Krieg in den jetzt polnischen Masuren geblieben ist, seinen polnischen Opa, der gegen die Deutschen gek\u00e4mpft hatte, und um ein uneheliches Kind, das ermordet wurde. Regisseur Micha\u0142 Korchowiec ist fest entschlossen, endlich seine zum Teil verschwiegenen Familienwurzeln zu ergr\u00fcnden. Wie k\u00f6nnte das besser gehen, als seine Mutter auf eine Reise in die Orte ihrer Kindheit mitzunehmen und dort ein Treffen mit Verwandten einzurichten. Doch leicht wird das nicht. Es geht los durch enge Waldstra\u00dfen, verschlafene masurische D\u00f6rfer im Nordosten Polens, aber auch in Richtung verdr\u00e4ngter Geschichte. Der Regisseur durchbricht das lange Schweigen und gibt seiner Mutter und seiner Gro\u00dfmutter Raum, die Familiengeheimnisse und Verletzungen zu offenbaren, und zugleich zu verstehen, worauf diese historisch gr\u00fcnden.<\/p>\n<p>Im Anschluss an die Filmvorf\u00fchrung erl\u00e4utert der Regisseur Micha\u0142 Korchowiec sein Filmprojekt.<\/p>\n<p>Die Filmvorf\u00fchrung findet im Mahnmal St.Nikolai, Willy-Brandt-Stra\u00dfe 60 statt.<\/p>\n<p>Eintritt \u20ac 6,-, erm. \u20ac 4,-<\/p>\n<p><strong>UMWELTKONGRESS IN RZESZOW<\/strong><\/p>\n<p>Wir sind stolz, Ihnen mitteilen zu k\u00f6nnen, dass wir vom <strong>18. bis 21.Mai 2017<\/strong> einen deutsch-polnisch-ukrainischen Umwelt- und Energiekongress in Rzeszow (S\u00fcdostpolen) mitgestalten k\u00f6nnen, der in der Zusammenarbeit mit der Polnisch-Deutschen Gesellschaft Rzeszow entstanden ist. Er ist mit finanzieller Unterst\u00fctzung des Bundesumweltministeriums und der Stiftung f\u00fcr Deutsch-Polnische Zusammenarbeit zustande gekommen. Ziel des Kongresses ist der Austausch und der Wissenstransfer zu Energiefragen zwischen den Institutionen und zivilgesellschaftlichen Initiativen in Polen, der Ukraine und Deutschland. Wichtig sind auch in diesem Zusammenhang die Auswirkungen auf Klima, Umwelt und Gesundheit. Auf dem Kongress sollen die beteiligten Zielgruppen \u2013 Kommunen, Kirchen sowie Schulen und Universit\u00e4ten \u2013 konkrete Projekte und Erfahrungen darstellen. Es sollen auch M\u00f6glichkeiten aufgezeigt werden, wie Handlungsspielr\u00e4ume auf dem Weg einer \u00f6kologischen Erneuerung besser wahrgenommen und genutzt werden k\u00f6nnen. Der Kongress kann Impulse zur Vernetzung der Akteure geben und soll zu weitergehenden Diskussionen und Projekten f\u00fchren.<\/p>\n<p>Falls Sie Interesse haben, melden sie sich bitte bei unserem Vorstandsmitglied, Hartwig Zillmer an, der federf\u00fchrend das Projekt begleitet: ha.zillmer@web.de<\/p>\n<p><strong><a href=\"https:\/\/dpg.hamburg\/wp-content\/uploads\/2017\/04\/ballinstadt.png\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-2352 alignleft\" src=\"https:\/\/dpg.hamburg\/wp-content\/uploads\/2017\/04\/ballinstadt-300x201.png\" alt=\"\" width=\"300\" height=\"201\" srcset=\"https:\/\/dpg.hamburg\/wp-content\/uploads\/2017\/04\/ballinstadt-300x201.png 300w, https:\/\/dpg.hamburg\/wp-content\/uploads\/2017\/04\/ballinstadt.png 394w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><a href=\"http:\/\/www.ballinstadt.de\/kontakt\/\" target=\"_blank\" rel=\"noopener noreferrer\">BALLINSTADT<\/a><\/strong><\/p>\n<p>Die Themen Auswanderung, Flucht, Emigration f\u00fcllen die Schlagzeilen unserer Medien und zwingen uns, sich damit zu besch\u00e4ftigen. Das ist aber kein exklusives Problem unserer Zeit.<\/p>\n<p>Es gab in der deutsch-polnischen und europ\u00e4ischen Geschichte weit virulentere Phasen von Zu- und Auswanderung. Um Geschichte besser verstehen zu lernen, l\u00e4dt der Vorstand Sie und die Freund*innen unserer Gesellschaft auf vielf\u00e4ltige Nachfrage am Sonnabend<strong>, 17. Juni<\/strong> in das Auswanderermuseum im BallinStadt auf der Veddel (S-Bahn S3) ein. Wir wollen Sie mitnehmen \u201eauf eine spannende Reise in die Ein- und Auswanderungsgeschichte \u00fcber vier Epochen hinweg. In insgesamt drei H\u00e4usern auf 2.500 qm begleiten Sie Menschen mit all ihren W\u00fcnschen und Tr\u00e4umen, die Sie auf ihrem Weg in eine neue Heimat mitnahmen\u201c. Wir fangen <strong>um 11.00 Uhr<\/strong> mit einem kurzen allgemeinen Einf\u00fchrungsvortrag an, dann bieten wir Ihnen im kleinen Seminarraum 1 einen Vortrag\u00a0 zum Thema &#8220;Polen in der Migrationsgeschichte Hamburgs und deren Auswirkungen&#8221; an, das Frau Markert von der Geschichtswerkstatt in Wilhelmsburg halten wird. Danach besichtigen wir die Ausstellung.\u00a0 Um etwa 13.30 Uhr\u00a0 werden wir uns zum abschlie\u00dfenden Imbiss im Museum &#8211; Caf\u00e9 zusammensetzen. Referentenkosten tr\u00e4gt die Gesellschaft. Eintritt: 10 \u20ac.<\/p>\n<p><strong>BESUCH IM ATELIER VON JAN DE WERYHA<\/strong><img loading=\"lazy\" decoding=\"async\" id=\"fancybox-img\" class=\"alignright\" src=\"http:\/\/freunde-de-weryha.de\/wp-content\/uploads\/2016\/11\/Logo-klein.jpg\" alt=\"logo-klein\" width=\"149\" height=\"149\" \/><\/p>\n<p>Die DPG Hamburg e.V. und der Freundeskreis Sammlung de Weryha e.V.,\u00a0 laden Sie am <strong>24. Juni\u00a0 ab 14.00 Uhr<\/strong> ins Atelier des Bergedorfer Bildhauers Jan de Weryha ein, wo uns der K\u00fcnstler durch die Sammlung f\u00fchrt und\u00a0 f\u00fcr\u00a0 Gespr\u00e4che zur Verf\u00fcgung steht. Die fr\u00fcheren Begegnungen\u00a0 haben vielen Freund*innen gut gefallen. Diese Einladung findet im Rahmen des diesj\u00e4hrigen Sommerfestes anl\u00e4sslich des 1-j\u00e4hrigen Bestehens des Vereins \u201eFreundeskreis der Sammlung de Weryha\u201c auf dem Gel\u00e4nde des Ateliers mit einem \u201ekulturellem Picknick\u201c statt, d.h., wir werden dieses Sommerfest mit Musik, Grill und Picknick \u00a0versch\u00f6nern. Adresse:\u00a0 <strong>Reinbeker Redder 81, 21031 Hamburg-Lohbr\u00fcgge <\/strong><\/p>\n<p>Eine Anmeldung ist erw\u00fcnscht: ha.zillmer@web.de und\/ oder: krizak_viola@hotmail.com<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>LESUNG MIT RADEK KNAPP<\/strong><\/p>\n<p>Am Donnerstag, <strong>29. Juni um 20:00 Uhr<\/strong> liest im Rahmen der Literatur altonale der polnisch-\u00f6sterreichische Schriftsteller Radek Knapp aus seinem Buch \u201eDer Mann, der Luft zum Fr\u00fchst\u00fcck a\u00df\u201c. In seinem einzigartigen Stil erz\u00e4hlt Radek Knapp von der unfreiwilligen Emigration des zw\u00f6lfj\u00e4hrigen Walerian von Polen nach Wien. Seine Schulkarriere ist kurz und endet mit seinem Hinauswurf. Als ihn seine Mutter ebenfalls auf die Stra\u00dfe setzt, kostet er in seiner neuen Bleibe das Gef\u00fchl der Freiheit aus \u2013 und die Bekanntschaft mit Schimmelpilz. Er schl\u00e4gt sich mit Gelegenheitsjobs durch und dringt immer tiefer in das Wiener Leben ein. Dort st\u00f6\u00dft er auf wenig Sympathie f\u00fcr Menschen von jenseits der Grenze und lernt einiges \u00fcber die Grenzen des guten Geschmacks und der Legalit\u00e4t. Irgendwann versteht er, dass \u201ezuhause\u201c \u00fcberall sein kann \u2013 wenn es ihm gelingt, seinen eigenen Weg zu finden.<\/p>\n<p>Radek Knapp, geb. 1964 in Warschau, lebt als freier Autor in Wien und in der N\u00e4he Warschaus. Sein Roman \u201eHerrn Kukas Empfehlungen\u201c ist ein Longseller. Au\u00dferdem erschienen von ihm u.a. die Erz\u00e4hlungssammlung \u201ePapiertiger\u201c, der mit dem Aspekte-Preis ausgezeichnete Roman \u201eFranio\u201c und der Roman \u201eDer Gipfeldieb\u201c (2015).<\/p>\n<p>Moderation: Jana Halamickova<\/p>\n<p>Die Lesung findet in Kooperation mit dem Literaturzentrum im Literaturhaus Hamburg in der Buchhandlung Christiansen, Bahrenfelder Str. 79, Ottensen statt ( Kartentelefon: 040. 227 92 03 oder Mailto: <a href=\"mailto:lit@lit-hamburg.de\">lit@lit-hamburg.de<\/a>). Eintritt: 6,00 Euro<\/p>\n<p><strong>NEUES MITGLIED<\/strong><\/p>\n<p>Kamil K. ist unser neues Mitglied geworden, wor\u00fcber wir uns sehr freuen. Wir hei\u00dfen ihn herzlich willkommen und hoffen auf eine gute Zusammenarbeit<\/p>\n<p><strong>VERANSTALTUNGER ANDERER TR\u00c4GER<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>AUSSTELLUNG \u201eWEM GEH\u00d6RT POLEN\u201c<\/strong><\/p>\n<p>Anhand von 60 Propagandapostkarten aus dem Ersten Weltkrieg pr\u00e4sentiert die sehenswerte Ausstellung bis zum 30. Mai 2017 im Gew\u00f6lbekeller des Mahnmals St. Nikolai (Willy-Brandt-Stra\u00dfe 60) die Situation und Stimmung der Polen in der Zeit vor 100 Jahren und veranschaulicht ihre komplizierte Stellung in der internationalen Politik. In einer Zeit vor Kinos, Telefon, TV oder Internet stellten Ansichtspostkarten ein wichtiges Mittel des Massenkonsums, der Massenkommunikation und der politischen Einflussnahme dar. Die Ausstellung, konzipiert von Prof. Dr. Rudolf Jaworski (Konstanz), zeigt diese Funktionen eines in ganz Europa weit verbreiteten Mediums anhand der im Ersten Weltkrieg propagierten Polenbilder: patriotische Selbstdarstellung der Polen, die sekundierende franz\u00f6sische Perspektive, der Blickwinkel der drei Teilungsm\u00e4chte Russland, Preu\u00dfen-Deutschland und \u00d6sterreich-Ungarn. Diese konkurrierenden Sichtweisen erlauben einen Gesamteindruck, welche Optionen f\u00fcr eine europ\u00e4ische Nachkriegszeit propagiert und wie sie visuell umgesetzt wurden. Eine Ausstellung des Wissenschaftlichen Zentrums der Polnischen Akademie der Wissenschaften in Wien, pr\u00e4sentiert von der Landeszentrale f\u00fcr politische Bildung.<\/p>\n<p><strong>Begleitveranstaltungen (Beginn jeweils um 18:00 Uhr):<\/strong><\/p>\n<p><strong>Donnerstag, 4. Mai: <\/strong>Prof. Dr. Stephan Lehnstaedt (Berlin): \u201eVom Ersten zum Zweiten Weltkrieg. Kontinuit\u00e4ten und Br\u00fcche in der deutschen Wahrnehmung Polens\u201c<\/p>\n<p><strong>Mittwoch, 10. Mai:<\/strong> Dr. Piotr Szlanta (Warschau), \u201eNeue Herren oder Befreier? Die polnischen<\/p>\n<p>Okkupationserfahrungen des Ersten Weltkriegs im Lichte von Karikaturen\u201c<\/p>\n<p><strong>Donnerstag, 11.Mai:<\/strong> \u00a0\u201ePD Dr. Joachim Tauber (L\u00fcneburg): \u201eDeutschland, Polen und Litauen 1916\u20131939\u201c<\/p>\n<p><strong>Donnerstag, 18.Mai<\/strong>: Dr. Libby O\u2019Connell (Chicago) u.a.: \u201eErinnern an den Gro\u00dfen Krieg: Der Kriegseintritt der USA 1917. Vortr\u00e4ge und Podiumsdiskussion<\/p>\n<p>In Kooperation mit und gef\u00f6rdert durch das Generalkonsulat der Vereinigten Staaten in Amerika (HH)<\/p>\n<p><strong>LESUNG MIT\u00a0 HANS BOLLINGER <\/strong><\/p>\n<p>\u201eWo\u00a0 liegt\u00a0 Polen?\u201c\u00a0 k\u00f6nnte\u00a0 man\u00a0 fragen.\u00a0 \u201ePolen\u00a0 liegt\u00a0 nicht, Polen arbeitet!\u201c. Kaum treffender kann man das beschreiben, was Hans Bollinger\u00a0 bei zahllosen Reisen in den deutschen Nachbarstaat erleben durfte. Diesseits der Grenze wei\u00df man nur wenig von den massiven Ver\u00e4nderungen in den vergangenen\u00a0 vier\u00a0 Jahrzehnten,\u00a0 die\u00a0 Polen\u00a0 zu\u00a0 einem\u00a0 modernen\u00a0 europ\u00e4ischen\u00a0 Land\u00a0 werden\u00a0 lie\u00dfen.\u00a0 Doch\u00a0 gerade\u00a0 die\u00a0 Begegnungen\u00a0 mit\u00a0 einfachen\u00a0 Menschen\u00a0 haben\u00a0 es\u00a0 Bollinger\u00a0 angetan:\u00a0 Bergleute,\u00a0 K\u00f6hler,\u00a0 F\u00f6rster \u00a0und\u00a0 Bauern,\u00a0 die\u00a0 in\u00a0 schwierigen Verh\u00e4ltnissen ihr pers\u00f6nlichen Gl\u00fcck zu finden. Der\u00a0 P\u00e4dagoge\u00a0 und\u00a0 Musiker\u00a0 Hans\u00a0 Bollinger\u00a0 engagiert\u00a0 sich\u00a0 intensiv f\u00fcr einen partnerschaftlichen Austausch mit Polen. \u201eUnterwegs\u00a0 in\u00a0 Polen\u201c\u00a0 ist\u00a0 eine\u00a0 ganz\u00a0 pers\u00f6nliche\u00a0 Liebeserkl\u00e4rung an ein untersch\u00e4tztes Land, das es zu entdecken gilt.<\/p>\n<p>Hans Bollinger, der 2. Vorsitzender der DPG Saarland ist, liest aus seinem Buch am Montag, <strong>29. Mai um 19.00 Uhr<\/strong> in der Residenz des polnischen Generalkonsuls, Marie-Louisen-Stra\u00dfe 137.<\/p>\n<p><strong>Anmeldung erforderlich unter: <\/strong><a href=\"mailto:adam.borkowski@msz.gov.pl\"><strong>adam.borkowski@msz.gov.pl<\/strong><\/a><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>FILMLAND POLEN<\/strong><\/p>\n<p>Am <strong>Sonntag, 14. Mai um 17.00 Uhr<\/strong> wird im Kino Metropolis (Kleine Theaterstra\u00dfe 10) der Film <strong>\u201eDas Gl\u00fcck der Welt (Szczescie swiata)\u201c<\/strong> in der Regie von Michal Rosa gezeigt. Ein Wohnhaus in Schlesien, Sommer 1939. Noch existiert die Welt, in der Schlesier, Polen, Juden und Deutsche nebeneinander als Nachbarn leben. Die junge Rosa ist eine wundersch\u00f6ne und geheimnisvolle Erscheinung, die den M\u00e4nnern den Kopf verdreht und in den Frauen hei\u00dfe Eifersucht erwecken kann. Die magische, mythologisierte Realit\u00e4t des Hauses ist voll von ungew\u00f6hnlichen Menschen und Ideen, die auf eine spannende Zukunft warten. Die Kamera kehrt dann erst in den 50er Jahren in das Haus zur\u00fcck. Was wurde aus Rosa und ihren Nachbarn?<\/p>\n<p><strong>Am Sonntag, 11. Juni um 17.00 Uhr <\/strong>wird der Film <strong>\u201eCamper (Kamper)\u201c<\/strong> in der Regie von Lukasz Grzegorzek gezeigt.<\/p>\n<p><strong>ALTONALE MIT POLNISCHEM JAZZ<\/strong><\/p>\n<p>Das Kulturfestival in Altona, die altonale, \u00a0ist so vielf\u00e4ltig und bunt wie die Bewohner dieses Stadtteils. Mehr als 200 Veranstaltungen in den Bereichen Literatur, Film, Kunst, Theater, Musik und Tanz bietet die diesj\u00e4hrige altonale 19. Die Partnerstadt des Hamburger Festivals ist 2017 Groningen. K\u00fcnstler und Aktionen aus der quirligen niederl\u00e4ndischen Hauptstadt der gleichnamigen Provinz erg\u00e4nzen und bereichern das Kulturprogramm.<\/p>\n<p>\u00a9 Justyna Jaworska<\/p>\n<p>Auch polnische K\u00fcnstler sind in diesem Jahr vertreten. <strong>Am 1. Juli um 15.00 Uhr<\/strong> spielt auf der Jazz-B\u00fchne auf dem Spritzenplatz der polnische Musiker <strong>Wac\u0142aw Zimpel<\/strong>. Er\u00a0 ist ein Komponist, klassisch ausgebildeter Klarinettist und Multiinstrumentalist. Sein Solowerk taucht in ein neues Terrain ein und entwirft hinrei\u00dfende Looping-Klanglandschaften. Seine Live-Auftritte sind ein Erlebnis. Das Ein-Mann-Orchester spielt mehrere Klarinetten, Synths und eine Khaen &#8211; Thai-Mund-Orgel aus Bambus. Er wurde mit dem \u201ePaszport Polityki\u201c &#8211; Preis in der Kategorie \u201ePopul\u00e4re Musik\u201c f\u00fcr das Jahr 2016 ausgezeichnet.<\/p>\n<p><strong>Am 1. Juli um 19.00 Uhr<\/strong> findet auf der Jazz-B\u00fchne auf dem Spritzrnplatz das Konzert \u201eLife is a long song, remembering Al Jarreau\u201d, eine Welt Premiere statt.\u00a0 Der polnische Pianist Vladyslav Sendecki , J\u00fcrgen Attig, \u00a0ein weltweit gefragter Bassist und Ken Norris, S\u00e4nger, Arrangeur, Komponist f\u00fchren Sie durch Al Jarreau\u00b4s Welt als S\u00e4nger, Autor und Mensch. Es ist nicht nur eine pers\u00f6nliche Verbeugung vor dem Werk dieses gro\u00dfen K\u00fcnstlers und Menschen, sondern eine inspirierende neue und frische Aufmachung dieser sonnigen und positiven Musik.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>DANZIG-REISE<\/strong><\/p>\n<p>Der F\u00f6rderkreis \u201eSammlung de Weryha\u201c organisiert vom <strong>30.09. &#8211; 3.10. 2017<\/strong> eine K\u00fcnstlerreise nach Gdansk\/Danzig. Wir werden gemeinsam mit dem Bergedorfer Bildhauer Jan de Weryha seine Geburtsstadt besichtigen, dabei u.a. Arbeiten von ihm in der Altstadt sehen und einen Besuch in der Kunstakademie, in der er studierte, sowie der St\u00e4dtischen Galerie machen. Geplant sind auch der Besuch der Kathedrale in Oliwa, der Parkanlage und ein Orgelkonzert, Besichtigung des Solidarnosc-Zentrums und ein Konzert in der Danziger Philharmonie.<\/p>\n<p>Die Anreise ist\u00a0 mit Flug, Bahn oder Auto m\u00f6glich. Es gibt Fl\u00fcge samstags ab Hamburg, die max. 4 Stunden dauern und bis ca. 13 Uhr in Danzig ankommen. Direktfl\u00fcge nach Danzig sind nicht m\u00f6glich, sondern nur \u00fcber Kopenhagen oder Frankfurt\/M.<\/p>\n<p><strong>Kosten<\/strong>: bei Unterbringung in einem Einzelzimmer in einem 4*-Hotel mit Fr\u00fchst\u00fcck, incl. Flug ca. 500\u20ac, bei Unterbringung im Doppelzimmer ca. 410\u20ac. Es kommen dazu weitere Kosten f\u00fcr Verpflegung, Stadtf\u00fchrung, Konzertbesuch, evtl. Fahrtkosten und pers\u00f6nliche Ausgaben.<\/p>\n<p>Verbindliche Anmeldung und Fragen ab sofort bis Mitte Mai an die mail-Adresse von Horst Sellhusen: jose17@gmx.de und eine Anzahlung von 50\u20ac auf das Konto des Freundeskreises (Freundeskreis Sammlung de Weryha, Volksbank Bergedorf, DE76 2019 0109 0019 5046 00) unter dem Stichwort: Danzig.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>SONSTIGES<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>NACHRUF F\u00dcR WOLFGANG NECKEL<\/strong><\/p>\n<p>Am 14. M\u00e4rz verstarb Wolfgang Neckel der langj\u00e4hrige Hamburger Landesschulrat (1968-1988) und gro\u00dfe Polenfreund. Er war unglaublich aktiv und hat unendlich viel f\u00fcr die deutsch-polnische Verst\u00e4ndigung in den 70er und 80er-Jahren getan. Es gab nie so viele Schulpartnerschaften wie zu seiner Amtszeit! F\u00fcr ihn war seine Stellung ein &#8220;Werkzeug&#8221; im Dienste seiner Ziele, Projekte und Vorstellungen: Deutsch-polnische Partnerschaften, Sch\u00fcleraustausche,\u00a0 Lehrer*innen-Begegnungen. Unter seiner Obhut und in enger Zusammenarbeit dem Institut f\u00fcr Lehrerfortbildung (IfL) \u00a0entstanden in drei gemeinsamen Lehrer*innen-Seminaren in Hamburg und in Warschau drei Schulprojekte, die in\u00a0 Brosch\u00fcren in beiden Sprachen &#8211; polnisch und deutsch &#8211; unterrichtet und dokumentiert wurden, drei Themen, die seinerzeit so fortschrittlich und aktuell waren und es heute noch sind: Frieden &#8211; Europa &#8211; und Umwelt. Er war einer der ersten Repr\u00e4sentanten bundesdeutscher Schulverwaltung bereits in den 70er-Jahren, die die deutsch-polnischen Vertr\u00e4ge von 1972 in Umsetzungsschwung brachten, die ersten deutsch (also Hamburger)-polnische Sch\u00fclerbegegnung\u00a0 besonders finanziell unterst\u00fctze. Zu dieser damaligen Aufbruchsstimmung geh\u00f6rten u.a. auch die deutsch-polnischen Schulbuchempfehlungen, die er in alle Schulen verteilen lie\u00df und dazu im damaligen IfL (heute LI) Seminare anbot. Heute noch wird es deutlich: Das, was\u00a0 Wolfgang Neckel auf diesem Gebiet getan und erreicht hat und wie er sich pers\u00f6nlich und &#8220;von Amts wegen&#8221; f\u00fcr die Verbesserung der Beziehungen zwischen beiden L\u00e4ndern und den Menschen beider L\u00e4nder eingesetzt hat, ist und bleibt unerreicht und vorbildlich!<\/p>\n<p>Wolfgang Neckel war Mitglied in der Deutsch-Polnischen Gesellschaft Hamburg, einige Jahre arbeitete er auch im Vorstand aktiv mit.<\/p>\n<p>Wir w\u00fcnschen Ihnen einen sch\u00f6nen, sonnigen Sommer<\/p>\n<p>und gr\u00fc\u00dfen herzlich<\/p>\n<p>F\u00fcr den Vorstand<\/p>\n<p>Viola Krizak<\/p>\n","protected":false},"excerpt":{"rendered":"<p>UNSERE VERANSTALTUNGEN \u00a0 FILMV [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2352,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[238,15,3],"tags":[],"class_list":["post-2359","post","type-post","status-publish","format-standard","has-post-thumbnail","category-deutsch-polnische-gesellschaft-hamburg-e-v","category-dpg-hamburg","category-mitteilungen","czr-hentry"],"_links":{"self":[{"href":"https:\/\/dpg.hamburg\/ja\/wp-json\/wp\/v2\/posts\/2359","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dpg.hamburg\/ja\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dpg.hamburg\/ja\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dpg.hamburg\/ja\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dpg.hamburg\/ja\/wp-json\/wp\/v2\/comments?post=2359"}],"version-history":[{"count":0,"href":"https:\/\/dpg.hamburg\/ja\/wp-json\/wp\/v2\/posts\/2359\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dpg.hamburg\/ja\/wp-json\/wp\/v2\/media\/2352"}],"wp:attachment":[{"href":"https:\/\/dpg.hamburg\/ja\/wp-json\/wp\/v2\/media?parent=2359"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dpg.hamburg\/ja\/wp-json\/wp\/v2\/categories?post=2359"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dpg.hamburg\/ja\/wp-json\/wp\/v2\/tags?post=2359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}