{"id":2960,"date":"2018-06-23T00:01:08","date_gmt":"2018-06-22T23:01:08","guid":{"rendered":"http:\/\/aktuell.dpg.hamburg\/?p=2960"},"modified":"2019-07-08T23:30:16","modified_gmt":"2019-07-08T22:30:16","slug":"sommerfest-2018-des-freundeskreises-sammlung-de-weryha-e-v-am-samstag-den-23-6-und-sonntag-den-24-6-2018","status":"publish","type":"post","link":"https:\/\/dpg.hamburg\/ja\/Beitr\u00e4ge\/fremdveranstaltung\/sommerfest-2018-des-freundeskreises-sammlung-de-weryha-e-v-am-samstag-den-23-6-und-sonntag-den-24-6-2018\/","title":{"rendered":"SOMMERFEST 2018 des Freundeskreises Sammlung de Weryha e.V. am Samstag, den 23.6. und Sonntag, den 24.6.2018"},"content":{"rendered":"<p>Der Freundeskreis Sammlung de Weryha e.V.<br \/>\nl\u00e4dt ein zum<br \/>\nSOMMERFEST 2018<br \/>\nam Samstag, den 23.6. und Sonntag, den 24.6.2018<br \/>\nReinbeker Redder 81, 21031 Hamburg \u2013 Galerieatelier de Weryha<\/p>\n<p><a href=\"http:\/\/freunde-de-weryha.de\/wp-content\/uploads\/2018\/05\/sommerfest2018-1.png\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-513 alignleft\" src=\"http:\/\/freunde-de-weryha.de\/wp-content\/uploads\/2018\/05\/sommerfest2018-1-300x169.png\" alt=\"\" width=\"300\" height=\"169\" \/><\/a>Samstag ab 12:00 Uhr<\/p>\n<p>14:30 Uhr: offizielle Begr\u00fc\u00dfung durch die 2. Vorsitzende des Freundeskreises Sammlung de Weryha Dr. Christel Oldenburg.<br \/>\n15:00 Uhr: Jan de Weryha f\u00fchrt durch Atelier und Ausstellung.<br \/>\n15:30 Uhr: Gastk\u00fcnstlerin \u2013 Magdalena Hohlweg pr\u00e4sentiert ihre Werke.<\/p>\n<p>An beiden Tagen<br \/>\nsorgen f\u00fcr das leibliche Wohl Kaffee und Kuchen, Bratwurst und kalte Getr\u00e4nke.<br \/>\nZwischendurch musikalische Untermalung von Ona Kupciuniene, Akkordeonspielerin aus Litauen.<br \/>\nDer Freundeskreis pr\u00e4sentiert sich mit einem Info-Tisch.<\/p>\n<p>Sonntag ab 14:00 Uhr<br \/>\n15:00 Uhr: Kunstf\u00fchrungen: Magdalena Hohlweg und Jan de Weryha.<br \/>\n16:00 Uhr: Horst Sellhusen, 1. Vorsitzender des Freundeskreises, in einem K\u00fcnstlergespr\u00e4ch mit den beiden K\u00fcnstlern. Anschlie\u00dfend Versteigerung zu Gunsten des Freundeskreises Sammlung de Weryha von je einem Werk beider K\u00fcnstler<\/p>\n<p>Offizielles Ende des Sommerfestes: 18:00 Uhr<\/p>\n<p>Wir bedanken uns bei der Bezirksversammlung Bergedorf sowie<br \/>\nbei der Deutsch-Polnischen Gesellschaft Hamburg e.V.<br \/>\nf\u00fcr die finanzielle Unterst\u00fctzung.<\/p>\n<p><a href=\"http:\/\/freunde-de-weryha.de\/wp-content\/uploads\/2018\/05\/sommerfest2018-2.png\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-514 alignright\" src=\"http:\/\/freunde-de-weryha.de\/wp-content\/uploads\/2018\/05\/sommerfest2018-2-300x190.png\" alt=\"\" width=\"300\" height=\"190\" \/><\/a>Magdalena Hohlweg: Sie schafft aus Natur- und anderen Kleinstfundst\u00fccken ganz eigene Bildwelten. \u201eEin befremdlicher welker Bl\u00fctenrest harmoniert auf wunderliche Weise mit einem alten Knopf. Ein winziger Tannensamen \u00fcberzeugt als munter durch das Bild tippelnde Vogelgestalt\u201c so stellt sie ihre Arbeit dar. Und: \u201eMich interessiert das \u00dcbersehene, vermeintlich Unbedeutende oder Aussortierte. Ich wechsle die Perspektive, \u00e4ndere Denkrichtungen und bilde neue Zusammenh\u00e4nge. So \u00e4ndert sich die Welt.\u201c Magdalena Hohlweg wurde 1962 geboren. Die Autodidaktin lebt und arbeitet seit 2008 hauptberuflich als freie K\u00fcnstlerin in Hamburg.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/freunde-de-weryha.de\/wp-content\/uploads\/2018\/05\/sommerfest2018-3.png\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-515 alignleft\" src=\"http:\/\/freunde-de-weryha.de\/wp-content\/uploads\/2018\/05\/sommerfest2018-3-300x154.png\" alt=\"\" width=\"300\" height=\"154\" \/><\/a>[\u2026] Kein anderer bedeutender K\u00fcnstler der abstrakten Moderne hat so konsequent in Holz gearbeitet wie der [\u2026] Bildhauer Jan de Weryha. Seine in den letzten zwanzig Jahren entstandenen Bodenarbeiten, freistehenden Objekte und Wandreliefs, aber auch die beiden von ihm entworfenen Denkm\u00e4ler wirken wie ein Res\u00fcmee auf zahlreiche Bewegungen der abstrakten Kunst seit dem Beginn des 20. Jahrhunderts. Diese Kunststile vom Konstruktivismus \u00fcber die Konkrete Kunst, ZERO, Minimal und Post Minimal Art bis zur zeitgen\u00f6ssischen Installations-kunst dienten ihm jedoch nur als Fundus, um jene Tendenzen zu extrahieren, die ihm eine objektive und in den k\u00fcnstlerischen Traditionen stehende Darstellung des von ihm gew\u00e4hlten Materials Holz, seiner strukturellen Vielfalt und seiner \u00c4sthetik, erm\u00f6glichten. Gleichzeitig hat er damit allen diesen Stilrichtungen neue L\u00f6sungen in Holz hinzugef\u00fcgt. [\u2026]<br \/>\nDr. Axel Feu\u00df<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der Freundeskreis Sammlung de  [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[142,103,149,405,124],"tags":[],"class_list":["post-2960","post","type-post","status-publish","format-standard","category-fremdbeitrag","category-fremdveranstaltung","category-jan-de-weryha","category-sammlung-de-weryha","category-freundeskreis-sammlung-de-weryha","czr-hentry"],"_links":{"self":[{"href":"https:\/\/dpg.hamburg\/ja\/wp-json\/wp\/v2\/posts\/2960","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dpg.hamburg\/ja\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dpg.hamburg\/ja\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dpg.hamburg\/ja\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dpg.hamburg\/ja\/wp-json\/wp\/v2\/comments?post=2960"}],"version-history":[{"count":0,"href":"https:\/\/dpg.hamburg\/ja\/wp-json\/wp\/v2\/posts\/2960\/revisions"}],"wp:attachment":[{"href":"https:\/\/dpg.hamburg\/ja\/wp-json\/wp\/v2\/media?parent=2960"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dpg.hamburg\/ja\/wp-json\/wp\/v2\/categories?post=2960"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dpg.hamburg\/ja\/wp-json\/wp\/v2\/tags?post=2960"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}