{"id":4502,"date":"2022-05-08T00:10:18","date_gmt":"2022-05-07T23:10:18","guid":{"rendered":"https:\/\/dpg.hamburg\/?p=4502"},"modified":"2022-06-13T17:58:34","modified_gmt":"2022-06-13T16:58:34","slug":"gedenk-glaswuerfel-im-garten-der-frauen-08-05-2022-friedhof-ohlsdorf","status":"publish","type":"post","link":"https:\/\/dpg.hamburg\/ja\/Beitr\u00e4ge\/fremdveranstaltung\/gedenk-glaswuerfel-im-garten-der-frauen-08-05-2022-friedhof-ohlsdorf\/","title":{"rendered":"Gedenk-Glasw\u00fcrfel im Garten der Frauen 08.05.2022 Friedhof Ohlsdorf"},"content":{"rendered":"<p><strong>Einweihung<\/strong><\/p>\n<p>des Gedenkglasw\u00fcrfels f\u00fcr die verstorbenen S\u00e4uglinge und Kleinkinder von Zwangsarbeiterinnen<\/p>\n<p>Sonntag, 8. Mai 14 Uhr,<br \/>\n<a href=\"http:\/\/www.garten-der-frauen.de\/Aktuell_Mai_22.html\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline; color: #000080;\">Garten der Frauen auf dem Ohlsdorfer Friedhof<\/span><\/a><\/p>\n<p>Der <span style=\"text-decoration: underline;\"><span style=\"color: #000080; text-decoration: underline;\"><a style=\"color: #000080; text-decoration: underline;\" href=\"http:\/\/www.garten-der-frauen.de\/\" target=\"_blank\" rel=\"noopener\">Verein Garten der Frauen e. V.<\/a><\/span><\/span> l\u00e4dt ein zur Einweihung des Gedenkglasw\u00fcrfels f\u00fcr die verstobenen S\u00e4uglinge und Kleinkider von Zwangsarbeiterinnen.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" src=\"http:\/\/www.garten-der-frauen.de\/img\/Glaswuerfel_Beispiel.jpg\" alt=\"\" width=\"219\" height=\"222\" border=\"0\" \/>250 S\u00e4uglinge und Kleinkinder von Zwangsarbeiterinnen und 3 \u00e4ltere M\u00e4dchen, die selbst Zwangsarbeit leisten mussten, wurden in der NS-Zeit zwischen 1943 und 1945 auf dem Ohlsdorfer Friedhof bestattet, dazu zwei \u00e4ltere Jungen mit Grabst\u00e4tten auf dem J\u00fcdischen Friedhof Ilandkoppel. Die meisten Gr\u00e4ber gibt es nicht mehr.<\/p>\n<p>Der Verein Garten der Frauen erinnert an die Kinder mit diesem Glasw\u00fcrfel, der aus 9x9cm gro\u00dfen bunten Glassteinen zusammengesetzt ist. Auf 255 Steinen stehen jeweils der Name und das Alter eines Kindes. Auf den anderen Steinen sind kleine kindgerechte Zeichnungen eingraviert, und ein Stein steht f\u00fcr alle Kinder, die uns nicht bekannt sind.<!--more--><\/p>\n<p>Frauen aus 16 Nationen wurden in der NS-Zeit aus ihrer Heimat verschleppt und zur Zwangsarbeit f\u00fcr Hamburger Firmen eingesetzt. Diejenigen unter ihnen, die in dieser Zeit in Hamburg Kinder gebaren, mussten etwa eine Woche nach der Entbindung wieder 10-12 Stunden schwer arbeiten und litten unter Hunger. Es war ihnen nicht m\u00f6glich, ihre S\u00e4uglinge ausreichend zu versorgen. Die meisten Kinder starben an Vernachl\u00e4ssigung und Unterern\u00e4hrung.<\/p>\n<p>F\u00fcr R\u00fcckfragen: Dr. Rita Bake, Tel: 5604462<\/p>\n<p>&nbsp;<\/p>\n<p>(C) Foto: <a href=\"http:\/\/www.garten-der-frauen.de\/\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline; color: #000080;\">Garten der Frauen e. V.<\/span><\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Einweihung des Gedenkglasw\u00fcrfe [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4501,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[142,103],"tags":[],"class_list":["post-4502","post","type-post","status-publish","format-standard","has-post-thumbnail","category-fremdbeitrag","category-fremdveranstaltung","czr-hentry"],"_links":{"self":[{"href":"https:\/\/dpg.hamburg\/ja\/wp-json\/wp\/v2\/posts\/4502","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dpg.hamburg\/ja\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dpg.hamburg\/ja\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dpg.hamburg\/ja\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dpg.hamburg\/ja\/wp-json\/wp\/v2\/comments?post=4502"}],"version-history":[{"count":0,"href":"https:\/\/dpg.hamburg\/ja\/wp-json\/wp\/v2\/posts\/4502\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dpg.hamburg\/ja\/wp-json\/wp\/v2\/media\/4501"}],"wp:attachment":[{"href":"https:\/\/dpg.hamburg\/ja\/wp-json\/wp\/v2\/media?parent=4502"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dpg.hamburg\/ja\/wp-json\/wp\/v2\/categories?post=4502"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dpg.hamburg\/ja\/wp-json\/wp\/v2\/tags?post=4502"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}