{"id":307,"count":1,"description":"","link":"https:\/\/dpg.hamburg\/ja\/Beitr\u00e4ge\/tag\/verdienstkreuz-am-bande-des-verdienstordens-der-bundesrepublik-deutschland\/","name":"Verdienstkreuz am Bande des Verdienstordens der Bundesrepublik Deutschland","slug":"verdienstkreuz-am-bande-des-verdienstordens-der-bundesrepublik-deutschland","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/dpg.hamburg\/ja\/wp-json\/wp\/v2\/tags\/307","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dpg.hamburg\/ja\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/dpg.hamburg\/ja\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/dpg.hamburg\/ja\/wp-json\/wp\/v2\/posts?tags=307"},{"href":"https:\/\/dpg.hamburg\/ja\/wp-json\/wp\/v2\/tribe_events?tags=307"},{"href":"https:\/\/dpg.hamburg\/ja\/wp-json\/wp\/v2\/tec_calendar_embed?tags=307"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}