{"id":1198,"date":"2015-11-24T13:53:57","date_gmt":"2015-11-24T12:53:57","guid":{"rendered":"http:\/\/aktuell.dpg.hamburg\/?p=1198"},"modified":"2015-11-25T13:55:10","modified_gmt":"2015-11-25T12:55:10","slug":"deutschland-und-die-nato-in-zeiten-des-wandels-rede-von-staatssekretaer-stephan-steinlein-zur-eroeffnung-der-konferenz-die-nato-auf-dem-weg-nach-warschau","status":"publish","type":"post","link":"https:\/\/dpg.hamburg\/nl\/Beitr\u00e4ge\/auswaertiges-amt-der-bundersrepublik-deutschland\/deutschland-und-die-nato-in-zeiten-des-wandels-rede-von-staatssekretaer-stephan-steinlein-zur-eroeffnung-der-konferenz-die-nato-auf-dem-weg-nach-warschau\/","title":{"rendered":"&#8220;Deutschland und die NATO in Zeiten des Wandels&#8221; &#8211; Rede von Staatssekret\u00e4r Stephan Steinlein zur Er\u00f6ffnung der Konferenz &#8220;Die NATO auf dem Weg nach Warschau&#8221;"},"content":{"rendered":"<p>24.11.2015<\/p>\n<p><em>Staatssekret\u00e4r Steinlein er\u00f6ffnete am 23. November 2015 mit einer Rede\u00a0 &#8220;Deutschland und die NATO in Zeiten des Wandels&#8221; die Konferenz der Deutsch-Atlantischen Gesellschaft &#8220;Die NATO auf dem Weg nach Warschau&#8221;. Die Konferenz in der Reihe &#8220;NATO Talk around the Brandenburger Tor&#8221; wurde gemeinsam mit der Bundesakademie f\u00fcr Sicherheitspolitik und der Botschaft der Republik Polen im Berliner Hotel Adlon-Kempinski ausgerichtet.<\/em><\/p>\n<p>Sehr geehrter Herr Minister (BM Schmidt),<br \/>\nLieber Jerzy Marganski,<br \/>\nExzellenzen,<br \/>\nsehr geehrte Abgeordnete des<br \/>\nDeutschen Bundestages,<br \/>\nmeine sehr verehrten Damen und Herren,<\/p>\n<p>vor zwei Jahrzehnten war ich im Pressereferat u. a. auch f\u00fcr die NATO-Erweiterung zust\u00e4ndig. Danach versank gerade Jugoslawien in einer Abfolge von blutigen Erbfolgekriegen.<\/p>\n<p>In der Allianz drehte sich in dieser Zeit alles um die Frage, ob die NATO neue Wege beschreiten sollte \u2013 konkret: den Weg in eine Krisenmanagement \u2013 und Stabilisierungsrolle jenseits der eigenen B\u00fcndnisgrenzen. Senator Lugar hat diese Debatte mit dem ber\u00fchmt gewordenen Diktum auf den Punkt gebracht: \u201eNATO must go out of area or out of business\u201c.<\/p>\n<p>Wenn wir diesen Satz heute h\u00f6ren, k\u00f6nnen wir ermessen, wie sehr sich die Situation in Europa ver\u00e4ndert hat. Lugars Satz ist zun\u00e4chst einmal Zeugnis des damaligen Zustands in Europa \u2013 einem Europa, in dem B\u00fcndnisverteidigung keine priorit\u00e4re Rolle mehr spielte. Ein Europa, in dem die NATO ihre origin\u00e4re Aufgabe, ihren Daseinszweck, in Ermangelung eines potenziellen Gegners offenbar neu definieren musste.<\/p>\n<p>Ich m\u00f6chte an dieser Stelle ausdr\u00fccklich der Legende widersprechen, die sagt, die NATO habe seinerzeit die Schw\u00e4che Russlands ausgenutzt, um dieses Land strategisch in die Enge zu treiben. Im Gegenteil, die NATO hatte bereits 1991 mit der Schaffung des Nordatlantischen Kooperationsrats ein essentielles Forum geschaffen. Dort wollte sie mit allen ehemaligen Warschauer Pakt-Staaten, einschlie\u00dflich der damaligen Sowjetunion, \u00fcber die Abwicklung der Hinterlassenschaften des Kalten Krieges sowie Fragen der europ\u00e4ischen Sicherheit partnerschaftlich beraten.<\/p>\n<p>Zur Wahrheit geh\u00f6rt dabei auch, dass es die Staaten Ostmitteleuropas waren, die nach der Wiedererlangung ihrer Freiheit sehr schnell den Wunsch nach einem Beitritt zur Allianz \u00e4u\u00dferten. Ein Wunsch, dem sich das B\u00fcndnis mehrere Jahre lang verschloss, bevor es zu einer behutsamen schrittweisen \u00d6ffnung kam.<\/p>\n<p>Aber zur\u00fcck zu den sog. \u201eout of area-Eins\u00e4tzen\u201c: Was mit den Eins\u00e4tzen auf dem Balkan Anfang der 1990er Jahre begann, erreichte mit dem 13-j\u00e4hrigen ISAF-Einsatz in Afghanistan seinen vorl\u00e4ufigen H\u00f6hepunkt. Der Kampfeinsatz der NATO in Afghanistan wurde vor fast einem Jahr beendet. Ihr Engagement f\u00fcr eine nachhaltige Stabilisierung Afghanistans setzt die NATO heute auf andere Weise fort. Sie unterst\u00fctzt, ber\u00e4t und bildet die afghanischen Sicherheitskr\u00e4fte dort aus, wo weiter Defizite bestehen. Und die gibt es in der Tat!<\/p>\n<p>Die Ereignisse in Kunduz haben gezeigt, wie fragil Sicherheit und Entwicklung in Afghanistan noch immer sind. Daher hat das Bundeskabinett am vergangenen Mittwoch beschlossen, den Einsatz der Bundeswehr in Afghanistan zu verl\u00e4ngern und personell auf 980 Soldatinnen und Soldaten auszuweiten. \u00dcber dieses Mandat wird der Deutsche Bundestag in den kommenden Wochen beraten.<\/p>\n<p>Die NATO-Au\u00dfenminister werden bei ihrer Herbsttagung Anfang n\u00e4chster Woche aller Voraussicht nach beschlie\u00dfen, ihr Engagement 2016 nicht nur in Kabul, sondern auch in den verschiedenen Regionen in Afghanistan fortzusetzen. F\u00fcr diese Verl\u00e4ngerung hat sich die Bundesregierung in den vergangenen Monaten nachdr\u00fccklich eingesetzt \u2013 auch um die Nachhaltigkeit des in den letzten vierzehn Jahren Erreichten nicht zu gef\u00e4hrden.<\/p>\n<p>Gleichzeitig hat sich das strategische Umfeld der NATO in einer Weise ver\u00e4ndert, die deutlich macht, dass das eingangs zitierte Lugar-Wort nicht auf ein \u201eentweder\/oder\u201c zwischen B\u00fcndnisverteidigung und internationalem Krisenmanagement verk\u00fcrzt werden darf.<\/p>\n<p>Denn mit dem Konflikt in der Ukraine ist nach dem Ende der Balkankriege die Frage von Krieg und Frieden nach Europa zur\u00fcckgekehrt. Russland hat mit der v\u00f6lkerrechtswidrigen Annexion der Krim, der Destabilisierung der Ukraine \u2013 aber auch mit einer Rhetorik, die geradezu fahrl\u00e4ssig mit nuklearen Handlungsoptionen spielt \u2013 die europ\u00e4ische Friedensordnung in Frage gestellt. Eine Friedensordnung, wohlbemerkt, die Russland selbst mit aufgebaut hat, die es in Helsinki und Paris besiegelt hat und mit der das \u201eZeitalter der Konfrontation und der Teilung Europas\u201c ein Ende finden sollte.<\/p>\n<p>Diese Friedensordnung beruht auf Prinzipien wie der Anerkennung staatlicher Souver\u00e4nit\u00e4t, territorialer Integrit\u00e4t und der Unverletzlichkeit von Grenzen, dem Bekenntnis zur friedlichen Konfliktbeilegung und dem Verzicht auf die Androhung der Anwendung von Gewalt und eben auch, wie die Charta von Paris es 1990 festhielt, auf dem Recht der freien B\u00fcndniswahl.<\/p>\n<p>Die westliche Staatengemeinschaft hat auf die russische Infragestellung unserer europ\u00e4ischen Ordnung reagiert \u2013 durch eine entschlossene Sanktionspolitik der Europ\u00e4ischen Union und eine St\u00e4rkung der F\u00e4higkeit der NATO, die Beistandsf\u00e4higkeit f\u00fcreinander glaubw\u00fcrdig zu unterf\u00fcttern.<\/p>\n<p>Die NATO hat diese R\u00fcckbesinnung auf ihre Kernaufgabe der kollektiven Verteidigung nicht gesucht. Aber Russland muss verstehen, wie ernst die Sorgen um die europ\u00e4ische Sicherheit sind, die es durch sein Verhalten ausgel\u00f6st hat \u2013 insbesondere bei unseren \u00f6stlichen B\u00fcndnispartnern, aber nicht nur bei diesen.<\/p>\n<p>Gerade wir Deutsche verstehen aus unserer Geschichte w\u00e4hrend des Kalten Krieges nur zu gut das Sicherheitsempfinden geografisch exponierter Staaten. Heute stehen wir f\u00fcr Sicherheit und Freiheit unserer Verb\u00fcndeten ebenso ein, wie die Alliierten dies f\u00fcr den freien Teils unseres Landes w\u00e4hrend des Kalten Krieges getan haben. Wir sind heute nicht mehr vorrangig \u201eSicherheitsempf\u00e4nger\u201c \u2013 wir sind Sicherheitsgarant als Teil der transatlantischen B\u00fcndnisarchitektur. Und wir sind dies in vollem Bewusstsein unserer Verantwortung gegen\u00fcber unseren Nachbarn und Partnern, aber auch unserer Verantwortung f\u00fcr eine gesamteurop\u00e4ische Sicherheitsarchitektur.<\/p>\n<p>Aus unserer Verpflichtung zur B\u00fcndnisverteidigung folgt, dass wir ein genuines Interesse an einer glaubhaften Abschreckung haben. Abschreckung ist ein schwieriges Wort im Deutschen. Ein heute oft eher negativ besetztes Wort.<\/p>\n<p>Dabei dient wohl verstandene Abschreckung dem Ziel, Konflikte weniger wahrscheinlich zu machen und nach M\u00f6glichkeit zu vermeiden. Und damit Abschreckung konfliktpr\u00e4ventiv wirken kann, muss sie glaubhaft sein. Denn nur wenn ein potenzieller Aggressor an ein reelles Risiko glaubt, dass der Preis f\u00fcr einen eigenen Angriff zu hoch ist, wird er von folgenschweren Fehlkalkulationen abgehalten werden.<\/p>\n<p>In diesem Sinne hat sich die NATO bei ihrem Gipfel in Wales auf ein ganzes B\u00fcndel an Ma\u00dfnahmen verst\u00e4ndigt. Die deutliche Botschaft dahinter ist: die Sicherheit der B\u00fcndnisverteidigung ist unteilbar. Wir stehen, egal was passiert, f\u00fcreinander ein.<\/p>\n<p>Die Anpassungen der NATO haben weitreichende Folgen f\u00fcr unsere sicherheitspolitische Ausrichtung. Das in Arbeit befindliche neue Wei\u00dfbuch, das Mitte n\u00e4chsten Jahres vorliegen soll, wird hierzu klare Aussagen enthalten.<\/p>\n<p>Aber, meine Damen und Herren,<\/p>\n<p>Bei allem Bekenntnis zur Notwendigkeit einer glaubhaften Abschreckung: Wir sind und bleiben zutiefst \u00fcberzeugt davon, dass Abschreckung und Verteidigung allein nachhaltige Sicherheit in Europa nicht gew\u00e4hrleisten k\u00f6nnen. Kluge B\u00fcndnispolitik muss \u00fcber den Tag hinausdenken und dabei auch aus dem reichen Erfahrungsschatz der vergangenen Jahrzehnte europ\u00e4ischer und transatlantischer Sicherheitspolitik sch\u00f6pfen.<\/p>\n<p>Wir sind der festen \u00dcberzeugung, dass kollektive Verteidigung stets einer Erg\u00e4nzung um Elemente der kooperativen Sicherheit bedarf! Sicherheit ist die Summe aus Verteidigung und Entspannung, aus \u201edeterrence\u201c und \u201ed\u00e9tente\u201c. Diese Weisheit ist seit dem ber\u00fchmten Bericht von Pierre Harmel 1967 Teil des Selbstverst\u00e4ndnisses der NATO \u2013 die NATO-DNA sozusagen. Und sie hat bis heute nichts von ihrer Relevanz verloren.<\/p>\n<p>Ich bin mir bewusst, dass der Weg zum Erfolg in diesem Bereich oft steinig ist. Da hilft auch kein Wunschdenken. Ehrliche Bereitschaft zur Deeskalation, ein wechselseitiges Interesse und ein erhebliches Ma\u00df an strategischer Geduld und Beharrungsverm\u00f6gen sind Voraussetzung, damit dieser doppelte Ansatz \u00fcberhaupt eine Chance hat.<\/p>\n<p>Ihn deshalb aber nicht beharrlich zu verfolgen, w\u00e4re fahrl\u00e4ssig!<\/p>\n<p>Die NATO hat sich letztes Jahr in Wales zu diesem Doppelansatz bekannt. Wir haben uns nach sehr sorgf\u00e4ltiger Abw\u00e4gung eben nicht daf\u00fcr entschieden, die Br\u00fccken zu Russland einzurei\u00dfen. Die Staats- und Regierungschefs haben sich vielmehr zur Aufrechterhaltung der regelbasierten europ\u00e4ischen Sicherheitsarchitektur bekannt \u2013 und damit auch zur Wahrung der NATO-RUS-Grundakte und der in ihr enthaltenen Selbstbeschr\u00e4nkungen des B\u00fcndnisses.<\/p>\n<p>Wir haben auf schnelle Verlegbarkeit der NATO-Reaktionskr\u00e4fte, auf rotierende Pr\u00e4senzen im \u00f6stlichen B\u00fcndnisgebiet und eine intensivierte \u00dcbungspraxis gesetzt \u2013 und sind nicht den Weg der permanenten Stationierung substanzieller Kampftruppen gegangen, wie so mancher es gefordert hat \u2013 und bis heute fordert.<\/p>\n<p>Dies war und bleibt richtig. Und es ist aus unserer Sicht auch unverzichtbar, dass wir weiter mit RUS im Gespr\u00e4ch bleiben. Wie Au\u00dfenminister Steinmeier beim letzten OSZE-Ministerrat in der Schweiz gesagt hat: Die Gleichung \u201eMonolog + Monolog = Dialog\u201c geht einfach nicht auf! Wir sollten daher auch rasch zu einem politischen Dialog im NATO-Russland-Rat zur\u00fcckkehren \u2013 zumindest auf Ebene der Botschafter.<\/p>\n<p>Aus unserer Sicht gibt es keine gute Alternative zum Dialog \u2013 so lang der Weg hin zu einer Verst\u00e4ndigung \u00fcber eine neue, eine erneuerte europ\u00e4ische Sicherheitsstruktur auch sein mag. Wichtig ist, so weit wie m\u00f6glich zu erhalten, was es noch an geltenden Verabredungen und Transparenzregeln gibt. Wir halten uns an Buchstaben und Geist von Transparenzregimen, wie dem Wiener Dokument. Dies zeigt etwa die Einladung von russischen Beobachtern zur j\u00fcngsten NATO-Gro\u00df\u00fcbung auf der Iberischen Halbinsel. Sie ist ein wichtiges Zeichen in Zeiten allgemeiner Sprachlosigkeit und Misstrauen zwischen der NATO und Russland.<\/p>\n<p>Aus dieser \u00dcberzeugung heraus hat die Allianz \u2013 auf deutsche Initiative hin \u2013 einen Krisenkontaktmechanismus mit Russland eingerichtet, der es der milit\u00e4rischen Seite erlaubt, gef\u00e4hrliche Situationen oder auch Missverst\u00e4ndnisse durch rasche Kontaktaufnahme einzufangen.<\/p>\n<p>Damit dieser Mechanismus praktische Wirkung entfalten kann, m\u00fcssen beide Seiten allerdings auch bereit sein, ihn zu nutzen. Die NATO hat diese Bereitschaft wiederholt unter Beweis gestellt. Ich m\u00f6chte diese Gelegenheit nutzen, auch an Moskau gerichtet daf\u00fcr zu werben, diesen Mechanismus zu nutzen.<\/p>\n<p>Verl\u00e4ssliche Kommunikationskan\u00e4le f\u00fcr den Krisenfall sind unabdingbar \u2013 f\u00fcr sich genommen aber nicht ausreichend. Angesichts erh\u00f6hter Man\u00f6vert\u00e4tigkeit und milit\u00e4rischer Aktivit\u00e4ten beider Seiten insb. zur See und in der Luft \u2013 und dem damit verbundenen Risiko von Unf\u00e4llen, Fehlern und ungewollter Eskalation \u2013 ben\u00f6tigen wir flankierende Ma\u00dfnahmen, die diese Risiken so weit wie m\u00f6glich minimieren.<\/p>\n<p>Wir stehen daher in der Pflicht, die M\u00f6glichkeiten verl\u00e4sslicher wechselseitiger milit\u00e4rischer Verhaltenskodizes auszusch\u00f6pfen \u2013 oder neue Wege zur Risikominimierung zu suchen. Auch diese \u00dcberzeugung wird deutsche Politik auf dem Weg nach Warschau pr\u00e4gen.<\/p>\n<p>Das Bem\u00fchen um Dialog, Vertrauensaufbau und Kooperation wird im \u00dcbrigen im Zentrum unseres Vorsitzes in der OSZE stehen, den wir im kommenden Jahr \u00fcbernehmen. Wir sind uns der Herausforderungen, die der Vorsitz in diesen st\u00fcrmischen Zeiten mit sich bringt, wohl bewusst.<\/p>\n<p>Au\u00dfenminister Steinmeier hat es in seiner Rede zum OSZE Vorsitz im Deutschen Bundestag gesagt: \u201eVertrauensbildung f\u00e4llt nicht vom Himmel, sondern entsteht durch Zusammenarbeit an ganz konkreten Themen. Nur so kann man verloren gegangenes gemeinsames Bewusstsein wieder schaffen \u2013 Bewusstsein f\u00fcr gemeinsame Bedrohungen, aber auch f\u00fcr gemeinsame Interessen.\u201c<\/p>\n<p>Es liegt in unserem ureigenen Interesse, Russland politisch in die Verantwortung zu nehmen, um gemeinsame Herausforderungen auch gemeinsam angehen zu k\u00f6nnen. Das gilt f\u00fcr den Konflikt in Syrien ebenso wie f\u00fcr den Kampf gegen den internationalen Terrorismus oder die Sicherheitsarchitektur in Nah- und Mittelost. Hier k\u00f6nnen wir nur mit, nicht ohne und schon gar nicht gegen Russland zu Fortschritten kommen.<\/p>\n<p>Das Abkommen mit dem Iran hat gezeigt, dass ein jahrelanges z\u00e4hes Ringen am Ende zum Erfolg f\u00fchren kann \u2013 entgegen aller zynischen Unkenrufe und Entmutigungen. Gerade in unruhigen Zeiten wie diesen ist Diplomatie gefragt! Das Iran-Abkommen er\u00f6ffnet f\u00fcr die ganze Region neue Chancen.<\/p>\n<p>Das setzt aber voraus, dass alle betroffenen Akteure diese Chance auch nutzen. Die Entwicklungen der letzten Monate haben gezeigt, wie wenig selbstverst\u00e4ndlich dies ist. Die Diplomatie ist mit einem Verhandlungserfolg nicht aus der Verantwortung entlassen, sondern tr\u00e4gt neue Verantwortung zur Nutzung der sich daraus ergebenden M\u00f6glichkeiten. Wie wir es im Umgang mit dem Syrien-Konflikt gerade versuchen!<\/p>\n<p>Dem Durchbruch von Wien in der Iran-Frage folgt das z\u00e4he Ringen von Wien um eine L\u00f6sung des Syrien-Konflikts. Immerhin: es wird wieder ernsthaft gerungen um eine politische L\u00f6sung. Das allein ist schon ein Fortschritt!<\/p>\n<p>Auch f\u00fcr den Ukraine-Konflikt gilt: die Vereinbarungen von Minsk waren nur der Anfang eines schwierigen Prozesses auf der Suche nach einer Entsch\u00e4rfung und L\u00f6sung des Konflikts. Sicher, wir k\u00f6nnen mit dem bislang Erreichten nicht zufrieden sein. Schon deshalb nicht, weil die Umsetzung der Minsker Vereinbarungen hinter den Zeitplan zur\u00fcckgefallen sind. Aber immerhin: Seit gut zwei Monaten h\u00e4lt in der Ostukraine der Waffenstillstand mehr oder weniger &#8211; und die Zahl der Todesopfer ist drastisch zur\u00fcck gegangen. Ansporn genug, diesen Weg weiter zu gehen.<\/p>\n<p>Meine Damen und Herren,<\/p>\n<p>deutsche Politik hat in den vergangenen Monaten unter Beweis gestellt, dass sie f\u00fcr die Sicherheit und Stabilit\u00e4t Europas mehr Verantwortung zu tragen bereit ist. Das gilt f\u00fcr die Fl\u00fcchtlingskrise ebenso wie die Bem\u00fchungen zur Stabilisierung der Konflikte in Syrien und der Ukraine. Und das gilt f\u00fcr unsere eigene Sicherheit und Verteidigungsf\u00e4higkeit.<\/p>\n<p>Unsere amerikanischen Freunde fordern mit Recht transatlantische Lastenteilung. Sie ist wichtig f\u00fcr eine nachhaltige Sicherheitspolitik.<\/p>\n<p>Gleichzeitig wissen wir: Europ\u00e4ische Verteidigungshaushalte werden auch in Zukunft nicht in den Himmel wachsen. Wir haben in Deutschland eine \u00fcberf\u00e4llige Trendumkehr vollzogen: Der Haushalt des BMVg soll 2016 von 33 Mrd. auf 34,4 Mrd. wachsen. Aber unsere Spielr\u00e4ume werden angesichts der Fl\u00fcchtlingskrise und weiter bestehenden Notwendigkeit zur Haushaltskonsolidierung auch k\u00fcnftig begrenzt bleiben.<\/p>\n<p>Umso dringender brauchen wir echte Fortschritte beim \u201epooling and sharing\u201c von F\u00e4higkeiten und Fortschritte bei multinationalen Entwicklungs- und Beschaffungsprojekten. Bilaterale und multilaterale Leuchtturm-Projekte mit Frankreich, aber auch mit Italien, sind ein Motor f\u00fcr die engere Zusammenarbeit in diesem Bereich \u2013 sei es bei der weltraumgest\u00fctzten Satellitenaufkl\u00e4rung oder beim Entwicklungsprojekt f\u00fcr ein europ\u00e4isches Drohnen-Aufkl\u00e4rungssystem.<\/p>\n<p>Wir ben\u00f6tigen gr\u00f6\u00dfere europ\u00e4ische Transparenz in der F\u00e4higkeitenentwicklung und eine bessere Harmonisierung der Verteidigungsplanung von EU und NATO. Die Europ\u00e4ische Verteidigungsagentur muss eine st\u00e4rker gestaltende Rolle einnehmen als bisher \u2013 das setzt voraus, dass die Mitgliedstaaten in ihrem Beharren auf Souver\u00e4nit\u00e4t k\u00fcnftig zur\u00fcckstecken m\u00fcssen. Und wir brauchen Fortschritte bei der Schaffung eines gemeinsamen R\u00fcstungsmarkts in Europa: eine Harmonisierung von Normen und Standards, die gegenseitige Anerkennung von Zertifizierungen auch im milit\u00e4rischen Bereich, europaweite Ausschreibungen von Beschaffungsvorhaben und eine Harmonisierung von Beschaffungszyklen.<\/p>\n<p>Vor allem aber gilt es, das Potenzial der NATO als \u201eIntegrationskatalysator\u201c vollumf\u00e4nglich zu nutzen. Denn nirgendwo sonst auf der Welt sind Streitkr\u00e4fte multinational so eng miteinander verzahnt und integriert wie in der Allianz. Hieran m\u00fcssen wir ankn\u00fcpfen.<\/p>\n<p>Meine Damen und Herren,<\/p>\n<p>mit Senator Lugar und seiner Aussage zu \u201eout of area or out of business\u201c habe ich diese Rede begonnen. Wenn Lugar damit meinte, dass die NATO ihre Daseinsberechtigung nur \u00fcber Auslandseins\u00e4tze erhalten kann, dann m\u00fcssen wir ihm aus heutiger Sicht nachdr\u00fccklich widersprechen.<\/p>\n<p>Das B\u00fcndnis und die kollektive Selbstverteidigung haben an Relevanz nichts verloren. Im Gegenteil, sie sind wichtiger denn je.<\/p>\n<p>Der Gipfel in Warschau wird das unterstreichen. Und hoffentlich ein starkes Signal der Geschlossenheit der Allianz aussenden. Wir stehen in der Allianz f\u00fcreinander ein. Und denken gleichzeitig \u00fcber den Tag hinaus. Ganz im Sinne der Charta von Paris. Da hei\u00dft es: \u201eSicherheit ist unteilbar, und die Sicherheit jedes Teilnehmerstaates ist untrennbar mit der der anderen verbunden.\u201c Die Selbstevidenz dieses Satzes ist in den letzten Jahren leider etwas verloren gegangen. Lassen Sie uns daran arbeiten, sie wieder fest in den K\u00f6pfen aller Beteiligten zu verankern.<\/p>\n<p>\u00dcbrigens: Auch in der Charta von Paris wird der Kampf gegen den Terrorismus schon als gemeinsame Aufgabe benannt.<\/p>\n<p>Ich danke Ihnen f\u00fcr Ihre Aufmerksamkeit!<\/p>\n<p>&nbsp;<\/p>\n<p>Internetangebot des Ausw\u00e4rtigen Amts: <a href=\"http:\/\/www.auswaertiges-amt.de\/\">www.auswaertiges-amt.de<\/a><\/p>\n<p>Folgen Sie uns auf Twitter: <a href=\"http:\/\/twitter.com\/AuswaertigesAmt\">@AuswaertigesAmt<\/a> und auf Facebook: <a href=\"http:\/\/www.facebook.com\/AuswaertigesAmt\">http:\/\/www.facebook.com\/AuswaertigesAmt<\/a><\/p>\n<p>Hinweis: Bitte antworten Sie nicht direkt auf diesen Newsletter, weil dies eine reine Absendeadresse ist. Wenn Sie uns eine Nachricht senden wollen, nutzen Sie bitte das Kontaktformular auf der Webseite des Ausw\u00e4rtigen Amts. Vielen Dank!<\/p>\n<p>Wenn Sie diesen Newsletter in Zukunft nicht mehr erhalten m\u00f6chten, klicken Sie auf den nachstehenden Link:<br \/>\n<a href=\"https:\/\/www.auswaertiges-amt.de\/DE\/Service\/Newsletter\/newsletter_abbestellen_node.html\">Newsletter abbestellen<\/a><\/p>\n<p>\u00a9 1995-2015 Ausw\u00e4rtiges Amt<\/p>\n","protected":false},"excerpt":{"rendered":"<p>24.11.2015 Staatssekret\u00e4r Steinlein er\u00f6ffnete am 23. November 2015 mit einer Rede\u00a0 &#8220;Deutschland und die NATO in Zeiten des Wandels&#8221; die Konferenz der Deutsch-Atlantischen Gesellschaft &#8220;Die NATO auf dem Weg nach [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[79,142],"tags":[],"class_list":["post-1198","post","type-post","status-publish","format-standard","category-auswaertiges-amt-der-bundersrepublik-deutschland","category-fremdbeitrag","czr-hentry"],"_links":{"self":[{"href":"https:\/\/dpg.hamburg\/nl\/wp-json\/wp\/v2\/posts\/1198","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dpg.hamburg\/nl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dpg.hamburg\/nl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dpg.hamburg\/nl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dpg.hamburg\/nl\/wp-json\/wp\/v2\/comments?post=1198"}],"version-history":[{"count":0,"href":"https:\/\/dpg.hamburg\/nl\/wp-json\/wp\/v2\/posts\/1198\/revisions"}],"wp:attachment":[{"href":"https:\/\/dpg.hamburg\/nl\/wp-json\/wp\/v2\/media?parent=1198"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dpg.hamburg\/nl\/wp-json\/wp\/v2\/categories?post=1198"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dpg.hamburg\/nl\/wp-json\/wp\/v2\/tags?post=1198"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}