{"id":186,"date":"2014-10-15T23:19:05","date_gmt":"2014-10-15T21:19:05","guid":{"rendered":"http:\/\/aktuell.dpg.hamburg\/?p=186"},"modified":"2014-10-25T23:21:19","modified_gmt":"2014-10-25T21:21:19","slug":"vortrag-von-prof-borodziej","status":"publish","type":"post","link":"https:\/\/dpg.hamburg\/nl\/Beitr\u00e4ge\/vortrag\/vortrag-von-prof-borodziej\/","title":{"rendered":"VORTRAG VON PROF. BORODZIEJ"},"content":{"rendered":"<p><strong>VORTRAG VON PROF. BORODZIEJ<\/strong><\/p>\n<p>In dem interessanten Vortrag \u201eDer Warschauer Aufstand nach 70 Jahren\u201c hat der Gast aus Warschau die\u00a0 Ereignisse vor dem August 1944 vorgestellt, die dazu gef\u00fchrt haben, dass die Entscheidung getroffen wurde, mit dem\u00a0 Aufstand zu beginnen. Es ging um den Kampf gegen Fremdherrschaft, wobei die Hoffnung auf Hilfe von au\u00dfen eine gro\u00dfe Rolle spielte. Die eigene Unterlegenheit sollte durch die \u00dcberrumpelung des Gegners kompensiert werden. Der Aufstand wurde sehr lange geplant und vorbereitet und sollte, nach Absicht der Protagonisten, innerhalb k\u00fcrzester Zeit eine radikale Ver\u00e4nderung und Verbesserung grunds\u00e4tzlicher Gegebenheiten herbeif\u00fchren. Es lief aber alles anders als geplant und die Hoffnungen wurden nicht erf\u00fcllt.<\/p>\n<p>Der Schwerpunkt des Vortrags von Prof. Borodziej lag auf dem unterschiedlichen Umgang mit den historischen Ereignissen nach dem Krieg und wurde in den folgenden 70 Jahren zu einem konstruktiven Element des polnischen Nationalbewusstseins. In den Jahren 1945-48 unterschied die offizielle Propaganda zwischen den \u201eVerr\u00e4tern\u201c in der F\u00fchrung des Untergrundstaates und dem unschuldigen, heldenhaften \u201eWarschauer Volk\u201c bzw. den \u201eeinfachen Soldaten\u201c der AK (Heimatarmee, Armia Krajowa). In der gesamten Stalin-Zeit wurde \u00fcber den Aufstand geschwiegen und nach 1954 kehrte die Staatspropaganda zum Muster bis 1949 zur\u00fcck, verbunden mit dem \u00f6ffentlichen Verschweigen des Warschauer Aufstandes und seiner vielen Opfer. In den 60er Jahren wurden der 20. und 25. Jahrestag in Warschau gefeiert. In den 70er Jahren entwickelte sich die staatlich organisierte Erinnerung immer mehr in Richtung gesamtnationale Solidarit\u00e4t.<\/p>\n<p>Am 1.08. 2004 wurde das Museum des Warschauer Aufstandes er\u00f6ffnet, das die polnische Tradition verk\u00f6rpert, die gelebt wird. Das Museum hat sich als historisch-kulturelle B\u00fchne gut etabliert und durch seine Art der Pr\u00e4sentation der Ereignisse zu einem sensationellen Erfolg gef\u00fchrt, die als Vorbild f\u00fcr viele historische Museen in Europa steht. Die Premiere des Filmes \u201eMiasto \u201944\/Stadt \u201944\u201c\u00a0 von Jan Komasa im Fu\u00dfballstadion\u00a0 zu einem Massenereignis, an dem 11.000 Menschen teilnahmen.<\/p>\n<p>Heute geh\u00f6rt der Aufstand zum offiziellen Gedenken und zum kollektiven Bewusstsein in Polen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>VORTRAG VON PROF. BORODZIEJ In dem interessanten Vortrag \u201eDer Warschauer Aufstand nach 70 Jahren\u201c hat der Gast aus Warschau die\u00a0 Ereignisse vor dem August 1944 vorgestellt, die dazu gef\u00fchrt haben, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[12,116,13],"class_list":["post-186","post","type-post","status-publish","format-standard","category-vortrag","tag-gedenken","tag-vortrag","tag-warschau","czr-hentry"],"_links":{"self":[{"href":"https:\/\/dpg.hamburg\/nl\/wp-json\/wp\/v2\/posts\/186","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dpg.hamburg\/nl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dpg.hamburg\/nl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dpg.hamburg\/nl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dpg.hamburg\/nl\/wp-json\/wp\/v2\/comments?post=186"}],"version-history":[{"count":0,"href":"https:\/\/dpg.hamburg\/nl\/wp-json\/wp\/v2\/posts\/186\/revisions"}],"wp:attachment":[{"href":"https:\/\/dpg.hamburg\/nl\/wp-json\/wp\/v2\/media?parent=186"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dpg.hamburg\/nl\/wp-json\/wp\/v2\/categories?post=186"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dpg.hamburg\/nl\/wp-json\/wp\/v2\/tags?post=186"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}