{"id":225,"date":"2015-01-17T09:00:54","date_gmt":"2015-01-17T07:00:54","guid":{"rendered":"http:\/\/aktuell.dpg.hamburg\/?p=225"},"modified":"2014-10-26T03:23:17","modified_gmt":"2014-10-26T01:23:17","slug":"klausurtagung-2015","status":"publish","type":"post","link":"https:\/\/dpg.hamburg\/pl\/Beitr\u00e4ge\/dpg-hamburg\/klausurtagung-2015\/","title":{"rendered":"KLAUSURTAGUNG 2015"},"content":{"rendered":"<p><strong>KLAUSURTAGUNG 2015<\/strong><\/p>\n<p>Der Vorstand unserer Gesellschaft organisiert vom 17.-18. Januar 2015 eine Klausurtagung, w\u00e4hrend der wir \u00fcber die Aktivit\u00e4ten des Jahres 2015 beraten und einen Jahresplan 2015 erstellen werden. Falls Sie Anregungen, Ideen, Vorschl\u00e4ge haben, teilen Sie uns diese bitte telefonisch (Viola Krizak 040 830 12 21, Aleksandra Jeszke-Zillmer 59 49 07) oder per E-Mail (Info@dpg-hamburg.de) mit.<\/p>\n<p>Die Klausurtagung findet im \u201eHaus am Sch\u00fcberg\u201c in Ammersbek statt. Mitglieder sind herzlich zur Teilnahme eingeladen. Falls Sie Interesse haben, teilen Sie dies uns bitte bis zum 30. November 2014 telefonisch oder per E-Mail mit, damit wir ggf. Zimmer f\u00fcr Sie reservieren lassen k\u00f6nnen. Tagesg\u00e4ste sind ebenfalls willkommen. Der Eigenbeitrag f\u00fcr eine \u00dcbernachtung mit Vollverpflegung wird ca. 50 Euro betragen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>KLAUSURTAGUNG 2015 Der Vorstand unserer Gesellschaft organisiert vom 17.-18. Januar 2015 eine Klausurtagung, w\u00e4hrend der wir \u00fcber die Aktivit\u00e4ten des Jahres 2015 beraten und einen Jahresplan 2015 erstellen werden. Falls [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[120],"class_list":["post-225","post","type-post","status-publish","format-standard","category-dpg-hamburg","tag-dpg-hamburg","czr-hentry"],"_links":{"self":[{"href":"https:\/\/dpg.hamburg\/pl\/wp-json\/wp\/v2\/posts\/225","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dpg.hamburg\/pl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dpg.hamburg\/pl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dpg.hamburg\/pl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dpg.hamburg\/pl\/wp-json\/wp\/v2\/comments?post=225"}],"version-history":[{"count":0,"href":"https:\/\/dpg.hamburg\/pl\/wp-json\/wp\/v2\/posts\/225\/revisions"}],"wp:attachment":[{"href":"https:\/\/dpg.hamburg\/pl\/wp-json\/wp\/v2\/media?parent=225"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dpg.hamburg\/pl\/wp-json\/wp\/v2\/categories?post=225"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dpg.hamburg\/pl\/wp-json\/wp\/v2\/tags?post=225"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}