{"id":3084,"date":"2018-10-12T12:16:57","date_gmt":"2018-10-12T11:16:57","guid":{"rendered":"http:\/\/aktuell.dpg.hamburg\/?p=3084"},"modified":"2018-10-01T12:43:36","modified_gmt":"2018-10-01T11:43:36","slug":"starjazzfestival2018","status":"publish","type":"post","link":"https:\/\/dpg.hamburg\/ru\/Beitr\u00e4ge\/jazz\/starjazzfestival2018\/","title":{"rendered":"star Jazz Festival 2018"},"content":{"rendered":"<p>star Jazz Festival 2018 | Perspektiven: Mikrokosmos &#8212; Makrokosmos<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Freitag, 12.10. und Samstag 13.10.2018, 19:30 Uhr<\/strong><br \/>\nMiralles-Saal<br \/>\nMittelweg 42<br \/>\n20148 Hamburg<br \/>\nNach dem gro\u00dfen Erfolg im Jahre 2017 eine neue Auflage des\u00a0<strong>star Jazz Festival <\/strong>pr\u00e4sentiert von Jazz Federation Hamburg e.V.<br \/>\n<strong>Freitag, 12.10.2018, 19:30 Uhr<\/strong><\/p>\n<p><a href=\"https:\/\/dpg.hamburg\/wp-content\/uploads\/2018\/10\/star-jazz-festival-2018.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-3093 alignleft\" src=\"https:\/\/dpg.hamburg\/wp-content\/uploads\/2018\/10\/star-jazz-festival-2018-211x300.jpg\" alt=\"\" width=\"211\" height=\"300\" srcset=\"https:\/\/dpg.hamburg\/wp-content\/uploads\/2018\/10\/star-jazz-festival-2018-211x300.jpg 211w, https:\/\/dpg.hamburg\/wp-content\/uploads\/2018\/10\/star-jazz-festival-2018.jpg 400w\" sizes=\"auto, (max-width: 211px) 100vw, 211px\" \/><\/a>Den Auftakt machen Maciej Obara (alt-, tenorsax) und Dominik Wania (p). Zwei Musiker aus Polen, Gro\u00dfmeister ihres Fachs, deren so kraftvoll, wie reich facettiertes Zusammenspiel im Mikrokosmos des Duos zur vollen Bl\u00fcte treibt.<\/p>\n<p>Weiterer Programmpunkt am ersten Festivaltag ist das zu diesem Anlass von Vladyslav Sendecki ins Leben gerufene multimediale Projekt Motion Ensemble of Hamburg. Hier vereinen sich erstklassige lokale Bl\u00e4ser und Streicher, die gemeinsam mit Reiner Winterschladen (trp), J\u00fcrgen Spiegel (dr, perc) und Vladyslav Sendecki (p, rhodes, seaboard) auf die B\u00fchne gehen.<\/p>\n<p>Der Klangk\u00f6rper interagiert mit den Bildern des von Dokumentarfilmer Timo Grosspietsch kreierten Films Land\u2013 es unterstreicht mit grenz\u00fcberschreitenden Kl\u00e4ngen aus Jazz, Klassik, Neuer Musik und Elektronics die bildpoetische Erz\u00e4hlung in Detail- und Weitwinkelperspektive dieser Dokumentation.<\/p>\n<p>Das Publikum wird unmittelbar in den kreativen Prozess hineingesogen \u2013 Klang- und Bildsprache verschmelzen in seiner Wahrnehmung zur metaphysischen Einheit.<\/p>\n<p><strong>Maciej Obara (sax) &#8212; Dominik Wania (p)<\/strong><\/p>\n<p><strong>\u201eTheater of Imagination\u201d: Motion Ensemble of Hamburg<\/strong><\/p>\n<p>Den NDR-Film \u201eDas Land\u201c (Regie:\u00a0<strong>Timo Gro\u00dfpietsch<\/strong>)\u00a0<strong>zur Musik von Vladyslav Sendecki:<\/strong><\/p>\n<p><strong>Vladyslav Sendecki<\/strong>\u00a0(p\/ seaboard),\u00a0<strong>J\u00fcrgen Spiegel<\/strong>\u00a0(ds\/perc),\u00a0<strong>Reiner Winterschladen<\/strong>(tp)<\/p>\n<p>und Dozenten der Jugendmusikschule:<\/p>\n<p><strong>Ewelina Nowicka<\/strong>\u00a0(Violine),\u00a0<strong>Annika Stolze<\/strong>\u00a0(Cello),\u00a0<strong>Mariola Rutschka<\/strong>\u00a0(Fl\u00f6te),\u00a0<strong>Thilo Jacques<\/strong>\u00a0(Horn) und Studentin\u00a0<strong>Katharina Jensen\u00a0<\/strong>(Klarinette).<br \/>\n<strong>Samstag, 13.10.2018, 19:30 Uhr<\/strong><\/p>\n<p>Am zweiten Festivaltag \u00f6ffnet sich u.a. das Objektiv zum Weitwinkel und fokussiert auf The Club of Continents. Mit den geladenen Musikern Saliou Cissokho (kora, kalabass) aus Afrika, Guo Yazhi (woodwinds) aus China\/U.S.A., Nils Petter Molvaer (trp, electronix) aus Norwegen, Mino Cinelu(perc) aus Frankreich\/U.S.A.\/Martinique und Gastgeber und Leiter des Ensembles Vladyslav Sendecki (p, seabord, electronix) aus Polen\/Deutschland betritt eine ungew\u00f6hnliche, in dieser Zusammenstellung einmalige K\u00fcnstlerriege gemeinsam die B\u00fchne.<\/p>\n<p>In dieser Konstellation, geeint durch Kreativit\u00e4t, gegenseitigen Respekt und die Lust am gemeinsamen Schaffensprozess, lassen sie Grenzen vergessen und laden ein zu einem faszinierenden musikalischen Abenteuer. Ein Parforceritt komplexer Rhythmen, magischer Soundcollagen, virtuoser Improvisationen auf der Basis tiefen musikalischen Verstehens wartet auf das Publikum \u2013 und die Akteure!<\/p>\n<p><strong>Club der Kontinente<\/strong><\/p>\n<p><strong>China: Yazhi Guo<\/strong>\u00a0(Chinesische Blasinstrumente)<\/p>\n<p><strong>\u202a<\/strong><strong>Ghana\/Afrika: Saliou Cissokho<\/strong>\u00a0(Kora \/ Kalabass )<\/p>\n<p><strong>Europa: Nils Petter Molvaer<\/strong>\u00a0(tp)<\/p>\n<p><strong>Mittelamerika\/Frankreich: Mino Cinelu<\/strong>\u00a0(ds, perc)<\/p>\n<p><strong>Europa: Vladyslav Sendecki<\/strong>\u00a0(p)<\/p>\n<p>Solo, Duo, Trio, Tutti<\/p>\n<p>Die<strong>\u00a0star Tankstellen\u00a0<\/strong>offerieren im zweiten Jahr des star Jazz Festivals ein musikalisch konzeptionelles Highlight der Extraklasse, das \u00fcber ein rein konzertantes Jazzerleben weit hinaus geht.<\/p>\n<p>Mit dem star Jazz Festival am 12. und 13. Oktober 2018 etabliert sich ein weiteres Kleinod in der an Festivals so reichen Stadt Hamburg \u2013 und birgt mit beispielhaftem Konzept und formidabler Besetzungsliste eine Strahlkraft weit \u00fcber die Stadtgrenze hinaus.<\/p>\n<p><a href=\"https:\/\/dpg.hamburg\/wp-content\/uploads\/2015\/09\/star-.png\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-1029 alignleft\" src=\"https:\/\/dpg.hamburg\/wp-content\/uploads\/2015\/09\/star--300x69.png\" alt=\"\" width=\"300\" height=\"69\" srcset=\"https:\/\/dpg.hamburg\/wp-content\/uploads\/2015\/09\/star--300x69.png 300w, https:\/\/dpg.hamburg\/wp-content\/uploads\/2015\/09\/star-.png 491w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Von der Orlen Deutschland GmbH, deren star Tankstellen seit 15 Jahren auch in Deutschland ein Begriff sind, wurde das Festival im Rahmen ihrer Kulturf\u00f6rderung ins Leben gerufen. Erwachsen aus den Ideen des k\u00fcnstlerischen Leiters Vladyslav Sendecki sowie in Kooperation mit der Jazz Federation Hamburg fiel im vergangenen Jahr der Startschuss f\u00fcr das star Jazz Festival. An zwei Tagen Ende Oktober 2017 wurde der Miralles-Saal im Hamburger Stadtteil Harvestehude mit seinen rund 400 Pl\u00e4tzen zum Mekka f\u00fcr hochkar\u00e4tigen Jazz mit Fokus auf Deutschland und Polen.<\/p>\n<p><em>\u201eDer verbindenden Kraft des Jazz, sein Ausdruck positiver Lebensenergie, die Grenzen \u00fcberwindet, geb\u00fchrt besonderes Augenmerk. Best\u00e4rkt durch den gro\u00dfen Publikumserfolg zum Festivalstart in 2017, freuen wir uns mit dem star Jazz Festival 2018 diese \u00fcber die Grenzen verbindende\u00a0<\/em><strong><em>polnische-deutsche Kooperation<\/em><\/strong><em>\u00a0weiterzuf\u00fchren \u2013 und weiter auszubauen. Es ist uns ein gro\u00dfes Anliegen, uns langfristig f\u00fcr die Musikkultur und hervorragende musikalische Leistungen einzusetzen. Musik \u2013 und gerade der Jazz \u2013 ist eine Sprache, die \u00fcber alle Landesgrenzen hinaus Menschen miteinander verbindet. Das unterst\u00fctzen wir!&#187;<\/em>, betont<strong>\u00a0Wieslaw Milkiewicz, Gesch\u00e4ftsf\u00fchrer (CTO) der Orlen Deutschland<\/strong>\u00a0<strong>GmbH und Pressesprecher der star Tankstellen<\/strong>. Das Unternehmen ist f\u00fcr sein starkes soziales Engagement und die aktive F\u00f6rderung in Sport und Kultur bekannt.<\/p>\n<p>Am 12. und 13. Oktober 2018 wird der Miralles-Saal des star Jazz Festivals erneut zum Schauplatz eines musikalisch konzeptionellen Highlights, das in diesem Jahr \u00fcber ein rein konzertantes Jazzerleben weit hinaus geht und sich den M\u00f6glichkeiten der multimedialen Performance \u00f6ffnet.<\/p>\n<p><strong>Leitthema des diesj\u00e4hrigen star Jazz Festivals ist PERSPEKTIVEN: Mikrokosmos &#8212; Makrokosmos<\/strong><\/p>\n<p>Als Ausgangspunkt dient ein einfacher Begriff, dessen Definition jedoch so variabel wie emotional bedeutsam ist, sich von kleinster Einheit bis hin zum globalen Umfang anwenden l\u00e4sst: Das Land. Einzig die Sicht darauf \u2013 die Perspektive &#8212; ist das Ma\u00df der Dinge.<br \/>\nHierzulande, auf dem Land, au\u00dfer Landes, aus aller Herren L\u00e4nder, Land unter, Festland, Kontinent, Staatsgebiet, Landstrich, Ackerland, Scholle&#8230; Ein weites Feld, ein spannungsreiches Thema. Das uns alle betrifft. Und uns \u00fcber alle Grenzen hinweg miteinander verbindet &#8212; weltweit. Wie sonst nur die Musik es vermag&#8230;<\/p>\n<p>Mit dieser Vision l\u00e4dt der aus Polen stammende\u00a0<strong>Vladyslav Sendecki, Komponist und Arrangeur, Pianist und k\u00fcnstlerischer Leiter des star Jazz Festivals,<\/strong>\u00a0K\u00fcnstler aus seinem direkten Umfeld der Hamburger Jazz- und Klassik-Szene, sowie europa- und weltweit renommierte Musiker in seine Wahlheimat Hamburg ein.<br \/>\nSeine f\u00fcr das Festival entstandenen Kompositionen ziehen sich, gleich eines roten Fadens, durch das zweit\u00e4gige Konzertgeschehen \u2013 bieten zugleich Klammer und Freiraum f\u00fcr entstehende Interaktionen und Improvisation von und mit seinen G\u00e4sten.<\/p>\n<p>Beide Konzerttage werden vom Medienpartner der Veranstaltung NDR Jazz, mitgeschnitten und zu einem sp\u00e4teren Zeitpunkt auf NDR Info ausgestrahlt.<\/p>\n<p>Beginn 19:30 Uhr (Einlass 18:30 Uhr)<br \/>\nTickets * 25 \u20ac \/ 12,50 \u20ac Tagesticket, 40 \u20ac \/ 20 \u20ac Zweitagesticket<br \/>\nVorverkauf * Konzertkasse Gerdes * Rothenbaumchaussee 77, 20148 Hamburg<\/p>\n<p><strong>Karten bestellen<a href=\"https:\/\/www.konzertkassegerdes.de\/index.php?option=com_rseventspro&amp;layout=subscribe&amp;id=2154:star-jazz-festival-edition-2018&amp;Itemid=161\">\u00a0hier<\/a><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Quelle: www.kulturograf.de<\/p>\n","protected":false},"excerpt":{"rendered":"<p>star Jazz Festival 2018 | Perspektiven: Mikrokosmos &#8212; Makrokosmos &nbsp; Freitag, 12.10. und Samstag 13.10.2018, 19:30 Uhr Miralles-Saal Mittelweg 42 20148 Hamburg Nach dem gro\u00dfen Erfolg im Jahre 2017 eine [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3093,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[142,103,70,174,198],"tags":[10],"class_list":["post-3084","post","type-post","status-publish","format-standard","has-post-thumbnail","category-fremdbeitrag","category-fremdveranstaltung","category-jazz","category-jazzkonzert","category-konzert","tag-musik","czr-hentry"],"_links":{"self":[{"href":"https:\/\/dpg.hamburg\/ru\/wp-json\/wp\/v2\/posts\/3084","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dpg.hamburg\/ru\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dpg.hamburg\/ru\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dpg.hamburg\/ru\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dpg.hamburg\/ru\/wp-json\/wp\/v2\/comments?post=3084"}],"version-history":[{"count":0,"href":"https:\/\/dpg.hamburg\/ru\/wp-json\/wp\/v2\/posts\/3084\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dpg.hamburg\/ru\/wp-json\/wp\/v2\/media\/3093"}],"wp:attachment":[{"href":"https:\/\/dpg.hamburg\/ru\/wp-json\/wp\/v2\/media?parent=3084"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dpg.hamburg\/ru\/wp-json\/wp\/v2\/categories?post=3084"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dpg.hamburg\/ru\/wp-json\/wp\/v2\/tags?post=3084"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}