{"id":4336,"date":"2021-03-24T00:18:02","date_gmt":"2021-03-23T23:18:02","guid":{"rendered":"https:\/\/dpg.hamburg\/?p=4336"},"modified":"2021-03-21T19:29:20","modified_gmt":"2021-03-21T18:29:20","slug":"online-debatte-polen-in-den-schlagzeilen-wie-ticken-die-medien-24-maerz2021-1900-uhr","status":"publish","type":"post","link":"https:\/\/dpg.hamburg\/ru\/Beitr\u00e4ge\/deutsches-polen-institut\/online-debatte-polen-in-den-schlagzeilen-wie-ticken-die-medien-24-maerz2021-1900-uhr\/","title":{"rendered":"Online-Debatte: Polen in den Schlagzeilen: Wie ticken die Medien?  24.M\u00e4rz2021, 19:00 Uhr"},"content":{"rendered":"<p>Sp\u00e4testens seit der spektakul\u00e4ren \u00dcbernahme Verlagsgruppe Polska Press durch den regierungsnahen Mineral\u00f6lkonzern und Tankstellenbetreiber Orlen, waren die polnischen Medien auch in Deutschland, wenngleich nicht in aller, so doch in vieler Munde. Zum Auftakt der neuen Debattenreihe \u201ePolen-Quartett\u201c wollen wir die gestiegene Aufmerksamkeit nutzen, um uns dem Thema etwas ausf\u00fchrlicher zu widmen. Unser erster Gast ist Gerhard Gnauck, langj\u00e4hriger Auslandskorrespondent zahlreicher deutschsprachiger Tageszeitungen mit Sitz in Warschau.<\/p>\n<ul>\n<li><strong>Dr. Gerhard Gnauck<\/strong>, Polen-Korrespondent der Frankfurter Allgemeinen Zeitung (FAZ)<\/li>\n<li><strong>Prof. Dr. Peter Oliver Loew<\/strong>, Direktor des Deutschen Polen-Instituts<\/li>\n<li><strong>Dr. Agnieszka \u0141ada<\/strong>, stv. Direktorin des Deutschen Polen-Instituts<\/li>\n<li><strong>Bastian Sendhardt<\/strong>, wissenschaftlicher Mitarbeiter des Deutschen Polen-Instituts<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Teilnahme auf <strong>:<\/strong> <a href=\"https:\/\/zoom.us\/webinar\/register\/WN_fDRiPe8NT8CgwaaiPGgysw\">https:\/\/zoom.us\/webinar\/register\/WN_fDRiPe8NT8CgwaaiPGgysw<\/a> (Registrierung notwendig)<\/p>\n<p>: <a href=\"http:\/\/www.facebook.com\/deutschespoleninstitut\">www.facebook.com\/deutschespoleninstitut<\/a><\/p>\n<p>Mehr Informationen: <a href=\"mailto:sendhardt@dpi-da.de\">sendhardt@dpi-da.de<\/a><\/p>\n<p><strong>Polen-Quartett<\/strong><\/p>\n<p>Vier Personen, ein Thema.<\/p>\n<p>\u00dcber Polen.<\/p>\n<p>Das Deutsche Polen-Institut hat ein neues Debatten-Format ins Leben gerufen. Im Rahmen des Polen-Quartett diskutieren Mitarbeiter des Deutschen-Polen-Instituts mit externen G\u00e4sten \u00fcber verschiedene Themen mit Polen-Bezug. Das Polen-Quartett m\u00f6chte einerseits \u00fcber den jeweiligen Stand der Debatte in Polen informieren und andererseits an Debatten in Deutschland ankn\u00fcpfen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sp\u00e4testens seit der spektakul\u00e4ren \u00dcbernahme Verlagsgruppe Polska Press durch den regierungsnahen Mineral\u00f6lkonzern und Tankstellenbetreiber Orlen, waren die polnischen Medien auch in Deutschland, wenngleich nicht in aller, so doch in vieler [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4335,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[303,448,439],"tags":[],"class_list":["post-4336","post","type-post","status-publish","format-standard","has-post-thumbnail","category-deutsches-polen-institut","category-online-debatte","category-onlineveranstaltung","czr-hentry"],"_links":{"self":[{"href":"https:\/\/dpg.hamburg\/ru\/wp-json\/wp\/v2\/posts\/4336","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dpg.hamburg\/ru\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dpg.hamburg\/ru\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dpg.hamburg\/ru\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dpg.hamburg\/ru\/wp-json\/wp\/v2\/comments?post=4336"}],"version-history":[{"count":0,"href":"https:\/\/dpg.hamburg\/ru\/wp-json\/wp\/v2\/posts\/4336\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dpg.hamburg\/ru\/wp-json\/wp\/v2\/media\/4335"}],"wp:attachment":[{"href":"https:\/\/dpg.hamburg\/ru\/wp-json\/wp\/v2\/media?parent=4336"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dpg.hamburg\/ru\/wp-json\/wp\/v2\/categories?post=4336"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dpg.hamburg\/ru\/wp-json\/wp\/v2\/tags?post=4336"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}