{"id":4341,"date":"2021-03-22T00:39:51","date_gmt":"2021-03-21T23:39:51","guid":{"rendered":"https:\/\/dpg.hamburg\/?p=4341"},"modified":"2021-03-21T19:52:19","modified_gmt":"2021-03-21T18:52:19","slug":"online-theaterstueck-bombe-mit-anschliessendem-gespraech-22-maerz-2021-1830-uhr","status":"publish","type":"post","link":"https:\/\/dpg.hamburg\/tr\/Beitr\u00e4ge\/fremdveranstaltung\/online-theaterstueck-bombe-mit-anschliessendem-gespraech-22-maerz-2021-1830-uhr\/","title":{"rendered":"ONLINE: Theaterst\u00fcck &#8220;Bombe!&#8221; mit anschlie\u00dfendem Gespr\u00e4ch\u00a022. M\u00e4rz 2021 &#8211; 18:30\u00a0Uhr"},"content":{"rendered":"<p>B\u00fcndnis NIEDERSACHSEN PACKT AN l\u00e4dt ein<\/p>\n<p><strong>Theaterst\u00fcck &#8220;Bombe!&#8221; mit anschlie\u00dfendem Gespr\u00e4ch<\/strong><\/p>\n<p><a href=\"https:\/\/dpg.hamburg\/wp-content\/uploads\/2021\/03\/bombe2021.png\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-4343 alignleft\" src=\"https:\/\/dpg.hamburg\/wp-content\/uploads\/2021\/03\/bombe2021.png\" alt=\"\" width=\"269\" height=\"269\" srcset=\"https:\/\/dpg.hamburg\/wp-content\/uploads\/2021\/03\/bombe2021.png 269w, https:\/\/dpg.hamburg\/wp-content\/uploads\/2021\/03\/bombe2021-150x150.png 150w\" sizes=\"auto, (max-width: 269px) 100vw, 269px\" \/><\/a>Sehr geehrte Damen und Herren,<\/p>\n<p>liebe Unterst\u00fctzerinnen und Unterst\u00fctzer,<\/p>\n<p>im Rahmen der Internationalen Wochen gegen Rassismus laden wir Sie herzlich ein, am <strong>22. M\u00e4rz 2021 in der Zeit von 18:30\u00a0Uhr bis ca. 20:00\u00a0Uhr<\/strong> bei der <strong>Vorf\u00fchrung von Ausschnitten des <\/strong>bisher nur einmal vom Deutschen Theater G\u00f6ttingen aufgef\u00fchrten <strong>Theaterst\u00fcckes \u201eBombe!\u201c mit anschlie\u00dfendem gemeinsamen Austausch<\/strong> dabei zu sein.<\/p>\n<p>Das Autorenduo Abdul Abbasi und Philipp L\u00f6hle schickt in seinem gemeinsam geschriebenen St\u00fcck vier Schauspieler:innen des Ensembles auf eine komische und erhellende Tour de Farce \u00fcber die Lage der Willkommens-Nation in Sachen Integration inklusive syrischer und deutscher Vorurteile. Einen kleinen Eindruck des Theaterst\u00fcckes sehen Sie <a href=\"https:\/\/youtu.be\/5gK-XDsjJ8I\">hier<\/a>.<\/p>\n<p>Im Anschluss reflektieren und diskutieren wir mit Phlipp L\u00f6hle und Abdul Abbasi, den Schauspieler:innen sowie dem Publikum \u00fcber den Stand der Integration in Deutschland, \u00fcber Vorurteile und Stereotypen auf deutscher wie syrischer Seite sowie \u00fcber die Beweggr\u00fcnde der Autoren f\u00fcr dieses St\u00fcck. Moderiert wird die Veranstaltung von der NDR-Journalistin Nadia Kailouli.<\/p>\n<p>&nbsp;<\/p>\n<p>Die Veranstaltung findet via <strong>Edudip <\/strong>statt. Die Plattform Edudip ist browserbasiert. F\u00fcr eine optimale Funktionalit\u00e4t empfehlen wir die Nutzung des Browsers Google Chrome.<\/p>\n<p>Die Teilnahme ist <strong>kostenlos<\/strong>, eine vorherige Anmeldung unter <a href=\"https:\/\/www.edudip.com\/de\/webinar\/film-ab-bombe\/1063292\">https:\/\/www.edudip.com\/de\/webinar\/film-ab-bombe\/1063292<\/a> jedoch notwendig.<\/p>\n<p>&nbsp;<\/p>\n<p>Wir freuen uns, Sie am 22. M\u00e4rz 2021 begr\u00fc\u00dfen zu d\u00fcrfen.<\/p>\n<p>Die Einladung k\u00f6nnen Sie gerne an Interessierte weiterleiten.<\/p>\n<p>&nbsp;<\/p>\n<p>Ihre Gesch\u00e4ftsstelle<\/p>\n<p>NIEDERSACHSEN PACKT AN<\/p>\n<p>&nbsp;<\/p>\n<p>Nieders\u00e4chsische Staatskanzlei<\/p>\n<p>Planckstra\u00dfe 2 | 30169 Hannover<\/p>\n<p>Tel.:\u00a0 (0511) 120-6909 | Email:\u00a0<a href=\"mailto:buendnis@niedersachsen.de\">buendnis@niedersachsen.de<\/a><\/p>\n<p><a href=\"http:\/\/www.niedersachsen-packt-an.de\/\">www.niedersachsen-packt-an.de<\/a><\/p>\n<p>\/Erfolgsgeschichten aus Niedersachsen \u00a0\u00a0 <strong>Jetzt NEU: unser Podcast \u201eGr\u00fcnkohl mit Pita\u201c<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>#InternationaleWochengegenRassismus (15.-28. M\u00e4rz 2021)<\/strong><\/p>\n<p><strong>#Solidarit\u00e4t.Grenzenlos.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>B\u00fcndnis NIEDERSACHSEN PACKT AN l\u00e4dt ein Theaterst\u00fcck &#8220;Bombe!&#8221; mit anschlie\u00dfendem Gespr\u00e4ch Sehr geehrte Damen und Herren, liebe Unterst\u00fctzerinnen und Unterst\u00fctzer, im Rahmen der Internationalen Wochen gegen Rassismus laden wir Sie [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4344,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[103,439],"tags":[],"class_list":["post-4341","post","type-post","status-publish","format-standard","has-post-thumbnail","category-fremdveranstaltung","category-onlineveranstaltung","czr-hentry"],"_links":{"self":[{"href":"https:\/\/dpg.hamburg\/tr\/wp-json\/wp\/v2\/posts\/4341","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dpg.hamburg\/tr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dpg.hamburg\/tr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dpg.hamburg\/tr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dpg.hamburg\/tr\/wp-json\/wp\/v2\/comments?post=4341"}],"version-history":[{"count":0,"href":"https:\/\/dpg.hamburg\/tr\/wp-json\/wp\/v2\/posts\/4341\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dpg.hamburg\/tr\/wp-json\/wp\/v2\/media\/4344"}],"wp:attachment":[{"href":"https:\/\/dpg.hamburg\/tr\/wp-json\/wp\/v2\/media?parent=4341"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dpg.hamburg\/tr\/wp-json\/wp\/v2\/categories?post=4341"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dpg.hamburg\/tr\/wp-json\/wp\/v2\/tags?post=4341"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}