{"id":5899,"date":"2023-08-30T17:16:26","date_gmt":"2023-08-30T16:16:26","guid":{"rendered":"https:\/\/dpg.hamburg\/?p=5899"},"modified":"2023-09-03T10:19:40","modified_gmt":"2023-09-03T09:19:40","slug":"lesung-mit-adam-soboczynski-sonntag-dem-17-september-um-17-00-uhr-literaturhotel-wedina","status":"publish","type":"post","link":"https:\/\/dpg.hamburg\/tr\/Beitr\u00e4ge\/dpg-hamburg\/lesung-mit-adam-soboczynski-sonntag-dem-17-september-um-17-00-uhr-literaturhotel-wedina\/","title":{"rendered":"TERMIN ABGESAGT: LESUNG MIT ADAM SOBOCZYNSKI &#8211; Sonntag, dem 17. September um 17.00 Uhr &#8211; Literaturhotel WEDINA"},"content":{"rendered":"<p><strong><span style=\"color: #0000ff;\">TERMIN ABGESAGT:<\/span> LESUNG MIT ADAM SOBOCZYNSKI<\/strong><\/p>\n<p><a href=\"https:\/\/dpg.hamburg\/wp-content\/uploads\/2023\/08\/adamsoboczynskitraumland.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-5863 alignleft\" src=\"https:\/\/dpg.hamburg\/wp-content\/uploads\/2023\/08\/adamsoboczynskitraumland.jpg\" alt=\"\" width=\"305\" height=\"500\" srcset=\"https:\/\/dpg.hamburg\/wp-content\/uploads\/2023\/08\/adamsoboczynskitraumland.jpg 305w, https:\/\/dpg.hamburg\/wp-content\/uploads\/2023\/08\/adamsoboczynskitraumland-183x300.jpg 183w\" sizes=\"auto, (max-width: 305px) 100vw, 305px\" \/><\/a>Falls Sie DIE ZEIT-Leser sind, ist Ihnen bestimmt der Name Adam Soboczynski bekannt. Er schreibt seit einigen Jahren Kritiken zu den neu erschienen B\u00fcchern oder Feuilletons zu aktuellen Themen, wie vor einigen Wochen \u00fcber den am 24. Juli verstorbenen Martin Walser. Die Lesung aus seinem \u00a0neuen Buch, das erst im September erscheint, \u201eTraumland: Der Westen, der Osten und ich\u201c findet<del><span style=\"color: #0000ff;\"> <strong>am Sonntag, dem 17. September um 17.00 Uhr<\/strong> <\/span><\/del>im Literaturhotel WEDINA , Gurlittstra\u00dfe 23 in St. Georg statt.<\/p>\n<p>Das neu erschienene Buch wirft einen pers\u00f6nlichen Blick auf eine Epoche der Freiheit im Osten wie im Westen Europas. Gl\u00e4nzend erz\u00e4hlt. Mit spielerischem Scharfsinn hilft\u00a0 Adam Soboczynski, uns selbst ebenso zu verstehen wie diesen seltsamen Osten Europas. Er erz\u00e4hlt von seiner Jugend in der Bonner und dem Erwachsensein in der Berliner Republik, von der gro\u00dfen Freiheit zwischen den Jahren 1989 und 2022, und wie sie verloren zu gehen droht \u2013 in beiden Teilen Europas. Im Osten wird sie von au\u00dfen bedroht, im Westen reibt sie sich an inneren K\u00e4mpfen auf.<\/p>\n<p>Sein Blick wandert immer wieder in den Osten Europas, der nach dem Fall des Eisernen Vorhangs zur Bl\u00fcte gelangt und bald schon wieder bedroht wird, was wir lange nicht sehen wollten. Und wer h\u00e4tte gedacht, dass sich auch die Freiheit im Westen in Gefahr befindet? Erst durch Trump und die AfD, und schlie\u00dflich durch die allgegenw\u00e4rtige Empfindlichkeit der Aufkl\u00e4rungs- und Liberalismuskritiker. Ein heiteres, ein melancholisches, ein kluges und gegenw\u00e4rtiges Buch.<\/p>\n<p>Adam Soboczynski wurde 1975 in Polen geboren. Als er sechs Jahre war, wanderte seine Familie in die Bundesrepublik aus. Er studierte Literaturwissenschaften in Bonn, Berkeley und St Andrews und promovierte \u00fcber Heinrich von Kleist. Er arbeitet als Feuilletonredakteur bei DIE ZEIT. 2005 erhielt er den Axel-Springer-Preis f\u00fcr junge Journalisten. Die Lesung wird in der Zusammenarbeit mit dem Klett-Cotta-Verlag und dem Literaturhaus durchgef\u00fchrt.<\/p>\n<p><del><span style=\"color: #0000ff;\">Datum: Sonntag, 17. September 2023<\/span><\/del><\/p>\n<p>Zeit: Teatime 17 Uhr Eintritt: \u20ac 15,- (inkl. Tee und Geb\u00e4ck)<\/p>\n<p>Ort: Wedina Hotel, Gurlittstr. 23<\/p>\n<p><strong>Anmeldung erforderlich unter 040-207 69 037 oder Mailto: lit@lit-hamburg.de<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>TERMIN ABGESAGT: LESUNG MIT ADAM SOBOCZYNSKI Falls Sie DIE ZEIT-Leser sind, ist Ihnen bestimmt der Name Adam Soboczynski bekannt. Er schreibt seit einigen Jahren Kritiken zu den neu erschienen B\u00fcchern [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5863,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[220,238,15],"tags":[],"class_list":["post-5899","post","type-post","status-publish","format-standard","has-post-thumbnail","category-buchlesung","category-deutsch-polnische-gesellschaft-hamburg-e-v","category-dpg-hamburg","czr-hentry"],"_links":{"self":[{"href":"https:\/\/dpg.hamburg\/tr\/wp-json\/wp\/v2\/posts\/5899","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dpg.hamburg\/tr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dpg.hamburg\/tr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dpg.hamburg\/tr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dpg.hamburg\/tr\/wp-json\/wp\/v2\/comments?post=5899"}],"version-history":[{"count":3,"href":"https:\/\/dpg.hamburg\/tr\/wp-json\/wp\/v2\/posts\/5899\/revisions"}],"predecessor-version":[{"id":5956,"href":"https:\/\/dpg.hamburg\/tr\/wp-json\/wp\/v2\/posts\/5899\/revisions\/5956"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dpg.hamburg\/tr\/wp-json\/wp\/v2\/media\/5863"}],"wp:attachment":[{"href":"https:\/\/dpg.hamburg\/tr\/wp-json\/wp\/v2\/media?parent=5899"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dpg.hamburg\/tr\/wp-json\/wp\/v2\/categories?post=5899"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dpg.hamburg\/tr\/wp-json\/wp\/v2\/tags?post=5899"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}