{"id":2805,"date":"2016-01-15T00:54:13","date_gmt":"2016-01-14T23:54:13","guid":{"rendered":"http:\/\/aktuell.dpg.hamburg\/?p=2805"},"modified":"2019-02-25T20:03:15","modified_gmt":"2019-02-25T19:03:15","slug":"01-2016","status":"publish","type":"post","link":"https:\/\/dpg.hamburg\/zh\/Beitr\u00e4ge\/mitteilungen\/01-2016\/","title":{"rendered":"MITTEILUNGEN 01\/2016 (Januar-Februar-M\u00e4rz)"},"content":{"rendered":"<p><strong>MITTEILUNGEN 01\/2016 (Januar-Februar-M\u00e4rz)<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>U N S E R E\u00a0 V E R A N S T A L T U N G E N<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong><a href=\"https:\/\/dpg.hamburg\/wp-content\/uploads\/2016\/02\/ProfDrStefanGarsztecki.png\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-1350 alignleft\" src=\"https:\/\/dpg.hamburg\/wp-content\/uploads\/2016\/02\/ProfDrStefanGarsztecki-300x248.png\" alt=\"\" width=\"300\" height=\"248\" srcset=\"https:\/\/dpg.hamburg\/wp-content\/uploads\/2016\/02\/ProfDrStefanGarsztecki-300x248.png 300w, https:\/\/dpg.hamburg\/wp-content\/uploads\/2016\/02\/ProfDrStefanGarsztecki.png 338w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>VORTRAG \u00a0ZUR \u00a0AKTUELLEN \u00a0SITUATION \u00a0IN \u00a0POLEN<\/strong><\/p>\n<p>Nach dem Wechsel der polnischen Regierung Ende Oktober erreichen uns aus Polen immer wieder beunruhigende Information, die dem Bild einer demokratischen Gesellschaft nicht immer gerecht werden k\u00f6nnen. Es ist auch nicht beruhigend, wenn Frau Beata Szydlo, die neue Ministerpr\u00e4sidentin Polens, in Br\u00fcssel die Einengung der Arbeit des Gerichtshofes als \u201ceinen internen politischen Streit\u201d bezeichnet. Die f\u00fcr uns nicht einfach einzusch\u00e4tzende neue Situation verunsichert gegenw\u00e4rtig nicht nur die Verantwortlichen in unserem Vorstand, sondern auch weite Teile unserer Mitglieder und viele Freunde\u00a0 unserer langj\u00e4hrigen Arbeit, was aus vielen Gespr\u00e4chen und auch Zuschriften deutlich erkennbar ist. Wir m\u00f6chten dieser allgemeinen und mehr und mehr um sich greifenden Verunsicherung begegnen, ohne dass wir f\u00fcr die eine oder die andere Seite der sich in Polen zunehmend polarisierenden politischen Kr\u00e4fte Partei ergreifen. Nach vielen Zeitungsberichten, in denen mehr oder weniger fair \u00fcber Polen berichtet wurde, ist uns eine sachliche Analyse wichtig. Deshalb haben wir <strong>Prof. Dr. Stefan Garsztecki<\/strong>, Mitarbeiter der Technischen Universit\u00e4t Chemnitz im Institut f\u00fcr Europ\u00e4ische Studien, Kultur- und L\u00e4nderstudien Ostmitteleuropas, eingeladen.<!--more--> Er besch\u00e4ftigt sich als Politikwissenschaftler und Historiker mit politischen Kulturen und Geschichtsdiskursen vergleichend mit Ostmitteleuropa. Er wird zum Thema <strong>\u201e100 Tage neue polnische Regierung im Amt\u201c<\/strong> sprechen und \u00a0die historischen Gr\u00fcnde und Probleme der Vorg\u00e4ngerregierung in Polen erl\u00e4utern, die ma\u00dfgebend zur heutigen Situation gef\u00fchrt haben. Dar\u00fcber hinaus wird er den in Polen\u00a0 besonders gepflegten Patriotismus erkl\u00e4ren, der von Bedeutung f\u00fcr die Beziehungen mit Deutschland und Europa ist.<\/p>\n<p>&nbsp;<\/p>\n<p>Die Moderation \u00fcbernimmt unser Mitglied <strong>Dr. Sabine Bamberger-Stemmann<\/strong>, Historikerin und Leiterin der Landeszentrale f\u00fcr politische Bildung. Das Treffen findet am <strong>29. Februar um 18.30 Uhr<\/strong> in der Krypta des Mahnmals St. Nikolai Willy-Brandt-Stra\u00dfe 60 statt. G\u00e4ste sind herzlich willkommen.<\/p>\n<p>Eintritt ist frei.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>MITGLIEDERVERSAMMLUNG<\/strong><\/p>\n<p><strong>Am Montag, 4. April 2016\u00a0 um 18.00 Uhr<\/strong>, findet im Berufsf\u00f6rderungswerk Hamburg, August-Krogmann-Str. 52, (Geb\u00e4ude U, Kaminzimmer\u00a0 im Erdgeschoss) die Mitgliederversammlung 2016 statt, die f\u00fcr uns das wichtigste Forum ist, in dem wir mit Ihnen ins Gespr\u00e4ch kommen k\u00f6nnen. Deshalb w\u00fcrden wir uns sehr \u00fcber Ihre zahlreiche Teilnahme freuen. Mit diesen Mitteilungen erhalten Sie die Tagesordnung.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>POLENREISE<\/strong><\/p>\n<p><a href=\"https:\/\/dpg.hamburg\/wp-content\/uploads\/2016\/02\/polenreise2016.png\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-1381 alignleft\" src=\"https:\/\/dpg.hamburg\/wp-content\/uploads\/2016\/02\/polenreise2016-300x193.png\" alt=\"\" width=\"300\" height=\"193\" srcset=\"https:\/\/dpg.hamburg\/wp-content\/uploads\/2016\/02\/polenreise2016-300x193.png 300w, https:\/\/dpg.hamburg\/wp-content\/uploads\/2016\/02\/polenreise2016.png 511w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Seit dem Jahr 2000 bieten wir regelm\u00e4\u00dfig jedes Jahr eine Reise nach Polen an, um Ihnen die Gelegenheit zu bieten, lebensnah unser Nachbarland kennenzulernen, bzw. ihre Kenntnisse zu vertiefen. In diesem Jahr ist unsere Vorsitzende Viola Krizak dem Wunsch der Teilnehmer der Reise 2015 nachgekommen und f\u00e4hrt vom 23. August bis 2. September nach Krakau, Lublin, Zamosc, Kazimierz Dolny, Sandomierz, also in das s.g. \u201eKleinpolen\u201c. Sie sind herzlich eingeladen mitzukommen.<\/p>\n<p><strong>Krakau,<\/strong> Polens alte K\u00f6nigstadt, geh\u00f6rt zweifellos zu den gr\u00f6\u00dften Sehensw\u00fcrdigkeiten in Europa. Im 2007 feierte die Stadt den 750. Jahrestag ihrer Gr\u00fcndung. Sie z\u00e4hlt nahezu 1 Million Einwohner und ist die meistbesuchte Stadt Polens. Krakau \u00fcbt ebenfalls einen starken Einfluss auf die polnische Kultur aus.\u00a0 <strong>Zamosc<\/strong> wurde nach der italienischer Vorstellung \u00a0von einer idealen Stadt ab 1578 vom venezianischen Baumeister Bernardo Morando im Stil der italienischen Renaissance erbaut, was ihr den Namen Padua des Nordens einbrachte. Die Stadt geh\u00f6rt zu den am besten erhaltenen Renaissance-St\u00e4dten Europas. Die Altstadt geh\u00f6rt seit 1992 zum Weltkulturerbe der UNESCO.<\/p>\n<p><strong>Lublin <\/strong>besitzt eine h\u00fcbsche Altstadt am Berghang, die aus einem Labyrinth romantischer Gassen besteht. In der ehemaligen Burg ist die gotische Dreifaltigkeit-Kapelle aus dem 14. Jh. mit wunderbaren Fresken erhalten. Die profane Architektur\u00a0 mit interessanten B\u00fcrgerh\u00e4usern und die sakrale Architektur bilden die H\u00f6hepunkte der bei uns wenig bekannten Stadt.<\/p>\n<p>Die Altstadt von <strong>Sandomierz<\/strong> z\u00e4hlt zu den sch\u00f6nsten, \u00e4ltesten und besterhaltenen Kleinst\u00e4dten in Polen. Ihre st\u00e4dtebauliche Struktur mit dem gro\u00dfen Altmarkt stammt aus dem 14.Jh..<\/p>\n<p>Au\u00dferdem werden noch einige Adelsresidenzen in <strong>Kozlowka<\/strong> und <strong>Baranow Sandomierski<\/strong> sowie architektonisch bedeutsame Kirchen in Opatow und Klimontow besichtigt.<\/p>\n<p>Wir haben damit begonnen, die Preise f\u00fcr den Flug Hamburg-Warschau-Hamburg, Hotels mit Fr\u00fchst\u00fcck, Stadtf\u00fchrer, Museumseintritte, Bustransfer von Krakau-Lublin-Krakau einzuholen. Wir sch\u00e4tzen, dass sich Kosten auf der H\u00f6he der Reise 2015 (DZ:\u00a0 ca.750 EUR p. P. und EZ: ca. 950 EUR p. P.) bewegen werden.<\/p>\n<p>Falls Sie Interesse haben, melden Sie sich bitte bis Ende Februar auf dem beigef\u00fcgten Formular oder per E-Mail: krizak_viola@hotmail.com an.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>NEUE MITGLIEDER<\/strong><\/p>\n<p>Dr. <strong>Ursula Piskorzynski<\/strong>, <strong>Marianne und Dr. Andreas Lenz<\/strong>, \u00a0<strong>Annalisa und Klaus Alber<\/strong>, <strong>Raimo K\u00f6rtner<\/strong> und <strong>Rafael Rucha<\/strong> \u00a0sind unsere neuen Mitglieder geworden, wor\u00fcber wir uns sehr freuen. Wir hei\u00dfen Sie herzlich willkommen und hoffen\u00a0 auf eine gute Zusammenarbeit.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>V E R A N S T A L T U N G E N\u00a0 A N D E R E R\u00a0 T R \u00c4 G E R<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong><a href=\"https:\/\/dpg.hamburg\/wp-content\/uploads\/2015\/04\/asur.png\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-742 alignleft\" src=\"https:\/\/dpg.hamburg\/wp-content\/uploads\/2015\/04\/asur.png\" alt=\"\" width=\"199\" height=\"224\" \/><\/a>LESUNG UNSERES \u00a0MITGLEDS UND SCHRFTSTELLERS\u00a0 ARNO SURMINSKI<\/strong><\/p>\n<p><strong>Am 06. Februar 2016 um 17.00 Uhr<\/strong> liest der Schriftsteller <strong>Arno Surminski<\/strong> zugunsten einer neuen Orgel in der Trittauer Martin-Luther-Kirche aus seinen Werken, u. a. aus seinem autobiografischen Roman \u201eKudenow oder an fremden Wassern weinen\u201c,\u00a0 in dem er seine Flucht aus Ostpreu\u00dfen und seine Jugend in der Trittauer neuen Heimat beschreibt. Die Lesung wird musikalisch von Truhenorgel und Cello begleitet. Der Eintritt ist frei; Spenden f\u00fcr die neue Orgel erbeten. Von den Kosten in H\u00f6he von ca. 300.000 \u20ac sind im Rahmen der seit vier Jahren laufenden Aktion unter dem Motto \u201eWir ziehen alle Register\u201c bisher \u00a0ca. 260.000 \u20ac \u00a0zusammen ge-kommen. Unser Ehrenvorsitzender Gerd Hoffmann ist als Trittauer einer der Organisatoren dieser Spenden-aktion.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>KONZERT DES UNIVERSIT\u00c4TSCHORS RZESZ\u00d2W UND DES JUGEND-SINFONIE-ORCHESTERS AHRENSBURG <\/strong><\/p>\n<p>Im Rahmen einer vor vier Monaten in Rzesz\u00f3w verabredeten Zusammenarbeit studieren das Jugend-Sinfonie-orchester Ahrensburg (JSOA) und der Chor der Musik-Fakult\u00e4t der Universit\u00e4t Rzesz\u00f3w vom 10. bis 16. Februar 2016 die Messe in G-Dur von Franz Schubert in Ahrensburg gemeinsam ein.<\/p>\n<p><strong>Am 13. Februar 2016 um 18.00 Uhr<\/strong> pr\u00e4sentieren die beiden Ensembles das Ergebnis ihrer beispielhaften musikalischen Zusammenarbeit in einem Konzert, das unter Leitung von Michael <strong>Klaue im Eduard-S\u00f6ring-Saal der Stormarnschule<\/strong> (Gymnasium, Waldstra\u00dfe, Unterf\u00fchrung S-Bahn Ahrensburg) stattfindet.<\/p>\n<p>Der Chor erwidert einen Besuch des JSOA im Herbst 2015.Durch Unterst\u00fctzung der Polnisch-Deutschen Gesellschaft Rzesz\u00f3w und der DPG Hamburg unternahm das JSOA eine Tournee in den S\u00fcdosten Polens und trat mit Werken von Bach , Verdi, Dvorak und Kallinikow in Rzesz\u00f3w, Krosno, Sanok und Krakau. auf. \u00a0Die musikalische Jugendbegegnung wurde aus Mittel des Deutsch-Polnischen Jugendwerks und der Goethe-Stiftung gef\u00f6rdert.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>KONZERT ZUR EHREN WANDA WILKOMIRSKA<\/strong><\/p>\n<p><strong>Am 20.Februar 2016 um 18:00 Uhr<\/strong> findet in Mahnmal St. Nikolai ein besonderes Konzert zu Ehren der weltber\u00fchmten Geigerin Wanda Wi\u0142komirska statt. Freuen Sie sich auf viel Musik, spannende Episoden aus ihrer Biografie, auf Fotos und auf Filmausschnitte aus dem faszinierenden Konzertleben der ber\u00fchmten Geigerin. Im Anschluss an das Konzert folgt eine Diskussionsrunde. Die Einf\u00fchrung \u00fcbernimmt Mariola Rutschka, die musikalischen\u00a0 Beitr\u00e4ge kommen von Ewelina Nowicka, Violine und\u00a0 Milena Antoniewicz, Klavier, die von den West Streichern, Sch\u00fcler der Staatlichen Jugendmusikschule Hamburg, begleitet werden. Wanda Wi\u0142komirska wird als Ehrengast anwesend sein.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>AUSSTELLUNG IM MUSEUM DER ARBEIT <\/strong><\/p>\n<p>Im Museum f\u00fcr Arbeit ist die Ausstellung \u201eZwangsarbeit. Die Deutschen, die Zwangsarbeiter und der Krieg\u201c\u00a0 noch bis 3. April zu sehen. \u00dcber 20 Millionen M\u00e4nner, Frauen und Kinder aus fast allen L\u00e4ndern Europas wurden als \u201cFremdarbeiter\u201d, Kriegsgefangene oder KZ-H\u00e4ftlinge in das nationalsozialistische Deutschland verschleppt oder mussten in den von der Wehrmacht besetzten Gebieten Zwangsarbeit leisten. Sp\u00e4testens seit 1942 geh\u00f6rten Zwangsarbeiter zum Alltag im nationalsozialistischen Deutschland. Die aus allen Teilen Europas, vor allem aus den \u00f6stlichen L\u00e4ndern, deportierten Arbeitskr\u00e4fte wurden \u00fcberall eingesetzt: in R\u00fcstungsbetrieben ebenso wie auf Baustellen, in der Landwirtschaft, im Handwerk, in \u00f6ffentlichen Einrichtungen und in Privathaushalten. Ob als Besatzungssoldat in Polen oder als B\u00e4uerin in Th\u00fcringen \u2013 alle Deutschen begegneten Zwangsarbeitern, viele profitierten davon. Zwangsarbeit war kein Geheimnis, sie war ein weitgehend \u00f6ffentlich stattfindendes Verbrechen. Die Ausstellung erz\u00e4hlt erstmals die gesamte Geschichte dieses Verbrechens und seiner Folgen nach 1945.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>DEUTSCH-POLNISCH-UKRAINISCHE WOCHE <\/strong><\/p>\n<p>Der Verein aubiko e.V. bietet vom 03. bis 09. April 2016 eine deutsch-polnisch-ukrainische Kulturwoche an. In der aktuellen Situation ist au\u00dferordentlich wichtig, Polen und die Ukraine n\u00e4her ins Bewusstsein der Hamburger Sch\u00fcler und B\u00fcrger zu r\u00fccken. Um eine breite Zielgruppe zu erreichen,\u00a0 besteht das Programm aus zwei Teilen. Im Rahmen eines Schulprojekts werden Polen und die Ukraine den Hamburger Sch\u00fcler\/-innen mit Workshops zu Sprache, Literatur, Theater und der polnischen K\u00fcche pr\u00e4sentiert und in einem \u00f6ffentlichen Abendprogramm werden alle Hamburger\/innen angesprochen. Im Rahmen des Schulprojekts werden sich die Teilnehmer mit der Frage auseinandersetzen, wo die polnischen Spuren in Hamburg zu sehen sind. Viele Stra\u00dfen sind z.B. heute nach polnischen St\u00e4dten benannt und die wenigsten Sch\u00fcler wissen etwas dar\u00fcber. Als Auftakt dieser Woche wird der Kabarettist und Autor Steffen M\u00f6ller eine Veranstaltung\u00a0 zum Thema polnische Kultur gestalten, die am 15.02.2016 am Lerchenfeldgymnasium in Hamburg stattfindet.<\/p>\n<p>Der Stadtpr\u00e4sident von Gda\u0144sk, Pawel Adamowicz hat die Schirmherrschaft f\u00fcr das Projekt \u00fcbernommen und das Generalkonsulat der Republik Polen in Hamburg unterst\u00fctzt das Vorhaben.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>DIE VOLKSHOCHSCHULE HAMBURG-OST in Farmsen<\/strong><\/p>\n<p>bietet (in Kooperation mit der DPG Hamburg) eine Busfahrt zu St\u00e4tten der polnischen Kultur und Geschichte in Teilen Hamburg an. Im Themenschwerpunkt \u201eAlles Hamburg\u201c bietet die VHS Einblicke in verschiedene Lebensbereiche und zeigt das soziale Miteinander in der Hansestadt. Die Kursleiter\/innen sind so vielf\u00e4ltig wie das Leben. Spannende Menschen zeigen ihren pers\u00f6nlichen Blick auf ihre Arbeit: Unsere 2. Vorsitzende, Aleksandra Jeszke-Zillmer, ist Kursleiterin f\u00fcr Polnisch in der VHS-Ost und sie organisiert diese Busfahrt. Sie f\u00fchrt uns\u00a0 u.a. zur St. Joseph-Kirche in der Gro\u00dfen Freiheit in St. Pauli, zur Gedenktafel anl. der Ermordung des Zwangsarbeiters Andrzej Szablewski am Alsterwanderweg und zum Atelier des bekannten polnischen K\u00fcnstlers Jan de Weryha. Die etwa 4-st\u00fcndige Fahrt endet mit einem typisch polnischen Imbiss im Bistro Koralle in Volksdorf, wo ein Gespr\u00e4ch mit Vertreter\/innen der \u201ePolonia\u201c m\u00f6glich wird<strong>. <\/strong><\/p>\n<p><strong>Termin: Samstag, 23.4.2016,\u00a0 Zeit: 13.00 \u2013 ca. 17.00 Uhr<\/strong><\/p>\n<p>Treffpunkt: Ab <strong>12.30 Uhr<\/strong> vor dem Gewerkschaftshaus (hinter dem ZOB), Besenbinderhof 60<\/p>\n<p>Kosten: 45 \u20ac (all. incl.). F\u00fcr Mitglieder der DPG: 35 \u20ac,<\/p>\n<p>Anmeldungen per E-Mail: <a href=\"mailto:ha.zillmer@gmx.de\">ha.zillmer@gmx.de<\/a>; telefonisch: 594907<\/p>\n<p>&nbsp;<\/p>\n<p><strong>P R O J E K T E\u00a0 D E R\u00a0 L E T Z T E N\u00a0\u00a0 M O N A T E<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>JUBIL\u00c4UM VON RESOVIA SALTANS<\/strong><\/p>\n<p>Es ist kaum zu glauben, RESOVIA SALTANS, das Tanz- und Gesangsensemble der Universit\u00e4t Rzeszow, mit dem wir seit 35 Jahren zusammenarbeiten, feierte am 14. November sein 40. Jubil\u00e4um! Aus diesem Anlass konnte unser Ehrenvorsitzender Gerd Hoffmann 31 Personen aus Norddeutschland gewinnen, an den Jubil\u00e4umsfeierlichkeiten teilzunehmen. Unter den 26 Mitgliedern und Freunden unserer Gesellschaft waren einige, die bei den zahlreichen Besuchen in Hamburg und Norddeutschland als Gastgeber die Studentinnen und Studenten aufnahmen und begeistert die Konzerte des Ensembles besucht haben. Au\u00dferdem nahmen an der Reise der Vorsitzende der DPG Tostedt, Hans-Dieter Feindt mit seiner Frau\u00a0 und sein Stellvertreter Burkhard Wessling sowie mit Carina Kaiser und Detlef\u00a0 zwei Vertreter des Hamburger Folkloreensemble FINKWAR-DER SPEELDEEL teil. Die beiden Gruppen haben sich im Jahr 2003 kennengelernt, angefreundet und seit dieser Zeit einige gemeinsame Konzerte veranstaltet.<\/p>\n<p>Das gro\u00dfe Gala-Konzert fand in der Philharmonie Rzeszow statt, die einen sehr feierlichen und gro\u00dfartigen Rahmen bot. Im Konzert traten zuerst die Senioren auf, die schon einige Wochen vorher flei\u00dfig ge\u00fcbt haben, um den Anforderungen des\u00a0 anstrengenden Auftritts gerecht zu werden. Es hat bestens funktioniert, was mit einem langen Applaus gew\u00fcrdigt wurde. Als zweite Gruppe traten die jungen, noch nicht so erfahrenen T\u00e4nzer auf und als dritte die repr\u00e4sentative Gruppe, in der die besten T\u00e4nzer\/innen auftreten. Es war beeindruckend, die wunderdbaren T\u00e4nze, die professionell gesungenen Volkslieder und die farbenfrohen Kost\u00fcme zu erleben. Danach gab es viele Reden, viele Lobesworte viele Blumen und Geschenke.<\/p>\n<p>Begleitend zu diesem Ereignis fand ein Symposium zum Thema \u201eFolklore \u00fcberwindet die Grenzen\u201c statt, an dem unsere Vorsitzende Viola Krizak, der Ehrenvorsitzende Gerd Hoffmann und Carina Kaiser (FINKWAR-DER SPEELDEEL ) mit Referaten teilgenommen haben.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>25 JAHRE DER PDG RZESZOW<\/strong><\/p>\n<p>Nach der Wende 1989 f\u00fchrten die Kontakte, die durch RESOVIA\u00a0 SALTANS entstanden sind, 1990 zur Entstehung der\u00a0 Polnisch-Deutschen Gesellschaft Rzeszow, die\u00a0 nach dem Vorbild der Hamburger Gesellschaft gebildet wurde. Am Anfang bestand die Hilfe aus praktischen Hinweisen zur Satzung\u00a0 und Arbeitsweise der Gesellschaft, die sp\u00e4ter zum regelm\u00e4\u00dfigen Austausch von Sch\u00fclern und Studenten gef\u00fchrt hat. Mit der Zeit ist die PDG Rzeszow unsere engagierte und vertraute Partnerin geworden, was zu einer engen und freundschaftli-chen deutsch-polnischen Zusammenarbeit gef\u00fchrt hat. Die PDG Rzesz\u00f3w ist unserer Erkenntnis nach die aktivste Gesellschaft in unserem Nachbarland.<\/p>\n<p>Der feierliche Empfang fand in einem Rzeszower Hotel statt und war mit vielen Erinnerungen an die beispiel-hafte Zusammenarbeit der beiden Gesellschaften in den vergangenen 25 Jahren gef\u00fcllt.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>ADVENTSFEIER 2015<\/strong><\/p>\n<p>Unsere allj\u00e4hrige Adventsfeier am 28.11. war \u00a0sehr erfolgreich. Der Chor METRUM aus Gnesen\/Gniezno sang einf\u00fchlsam Weihnachtslieder, die in interessanten, v\u00f6llig neuen Arrangements des Chorleiters Jarek Krenz mal kr\u00e4ftig, mal zart und einf\u00fchlsam klangen und sorgten damit bei den Zuh\u00f6rern f\u00fcr R\u00fchrung und Begeisterung. An der anschlie\u00dfenden Adventsfeier beteiligten sich ca. 120 Personen, so dass die r\u00e4umlichen Kapazit\u00e4ten voll ausgesch\u00f6pft waren. Es wurden gemeinsam Weihnachtslieder gesungen und Hartwig Zillmer hat ausgew\u00e4hlte Weihnachtsgeschichten vorgelesen. Die wunderbare Stimmung und das Beisammensein haben offensichtlich alle genossen.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>KLAUSURTAGUNG 2016<\/strong><\/p>\n<p>Der Vorstand unserer Gesellschaft nahm vom 16.- 17. Januar 2016 an der Klausurtagung teil, w\u00e4hrend der wir \u00fcber die Aktivit\u00e4ten f\u00fcr das laufende Jahr beraten und den Jahresplan\u00a0 erstellt haben. Eine \u00dcbersicht der von uns geplanten Projekte f\u00fcgen wir als Anlage bei. Wir hoffen, dass es gelingen wird, sie alle umzusetzen.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>MITTEILUNGEN 01\/2016 (Januar-F [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1350,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[238,15,3],"tags":[],"class_list":["post-2805","post","type-post","status-publish","format-standard","has-post-thumbnail","category-deutsch-polnische-gesellschaft-hamburg-e-v","category-dpg-hamburg","category-mitteilungen","czr-hentry"],"_links":{"self":[{"href":"https:\/\/dpg.hamburg\/zh\/wp-json\/wp\/v2\/posts\/2805","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dpg.hamburg\/zh\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dpg.hamburg\/zh\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dpg.hamburg\/zh\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dpg.hamburg\/zh\/wp-json\/wp\/v2\/comments?post=2805"}],"version-history":[{"count":0,"href":"https:\/\/dpg.hamburg\/zh\/wp-json\/wp\/v2\/posts\/2805\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dpg.hamburg\/zh\/wp-json\/wp\/v2\/media\/1350"}],"wp:attachment":[{"href":"https:\/\/dpg.hamburg\/zh\/wp-json\/wp\/v2\/media?parent=2805"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dpg.hamburg\/zh\/wp-json\/wp\/v2\/categories?post=2805"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dpg.hamburg\/zh\/wp-json\/wp\/v2\/tags?post=2805"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}